{"id":2498,"date":"2023-09-19T16:55:45","date_gmt":"2023-09-19T22:55:45","guid":{"rendered":"https:\/\/emmapay.com\/uat-costa-rica\/?page_id=2498"},"modified":"2023-09-24T16:29:28","modified_gmt":"2023-09-24T22:29:28","slug":"preguntas-frecuentes-personas","status":"publish","type":"page","link":"https:\/\/emmapay.com\/costa-rica\/ayuda\/preguntas-frecuentes\/preguntas-frecuentes-personas\/","title":{"rendered":"Preguntas Frecuentes Personas"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"2498\" class=\"elementor elementor-2498\" data-elementor-post-type=\"page\">\n\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-485485cc elementor-hidden-widescreen elementor-hidden-desktop elementor-hidden-mobile e-flex e-con-boxed e-con e-parent\" data-id=\"485485cc\" data-element_type=\"container\" data-settings=\"{&quot;container_type&quot;:&quot;flex&quot;,&quot;content_width&quot;:&quot;boxed&quot;}\" data-core-v316-plus=\"true\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-28c6742d e-flex e-con-boxed e-con e-parent\" data-id=\"28c6742d\" data-element_type=\"container\" data-settings=\"{&quot;container_type&quot;:&quot;flex&quot;,&quot;content_width&quot;:&quot;boxed&quot;}\" data-core-v316-plus=\"true\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-5e568b01 elementor-widget elementor-widget-heading\" data-id=\"5e568b01\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<style>\/*! elementor - v3.17.0 - 25-10-2023 *\/\n.elementor-heading-title{padding:0;margin:0;line-height:1}.elementor-widget-heading .elementor-heading-title[class*=elementor-size-]>a{color:inherit;font-size:inherit;line-height:inherit}.elementor-widget-heading .elementor-heading-title.elementor-size-small{font-size:15px}.elementor-widget-heading .elementor-heading-title.elementor-size-medium{font-size:19px}.elementor-widget-heading .elementor-heading-title.elementor-size-large{font-size:29px}.elementor-widget-heading .elementor-heading-title.elementor-size-xl{font-size:39px}.elementor-widget-heading .elementor-heading-title.elementor-size-xxl{font-size:59px}<\/style><h2 class=\"elementor-heading-title elementor-size-default\"><span class=\"inicio-bl\"> <a class=\"breadcrumb-link-bl\" href=\"https:\/\/emmapay.com\/costa-rica\/ayuda\/preguntas-frecuentes\">Ayuda<\/a> <\/span><span class=\"blu\">\/<\/span> <span class=\"inicio-bl\"><a class=\"breadcrumb-link-bl\" href=\"https:\/\/emmapay.com\/costa-rica\/ayuda\/preguntas-frecuentes\">Preguntas frecuentes<\/a><\/span><span class=\"blu\">\/<\/span>  Emma para personas <\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-5e9ee355 e-flex e-con-boxed e-con e-parent\" data-id=\"5e9ee355\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;container_type&quot;:&quot;flex&quot;,&quot;content_width&quot;:&quot;boxed&quot;}\" data-core-v316-plus=\"true\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-1d2a690a e-flex e-con-boxed e-con e-parent\" data-id=\"1d2a690a\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;container_type&quot;:&quot;flex&quot;,&quot;content_width&quot;:&quot;boxed&quot;}\" data-e-bg-lazyload=\"\" data-core-v316-plus=\"true\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-4b8786d0 elementor-hidden-tablet elementor-hidden-mobile_extra e-flex e-con-boxed e-con e-parent\" data-id=\"4b8786d0\" data-element_type=\"container\" data-settings=\"{&quot;container_type&quot;:&quot;flex&quot;,&quot;content_width&quot;:&quot;boxed&quot;}\" data-core-v316-plus=\"true\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-7ff4fd08 elementor-widget elementor-widget-heading\" data-id=\"7ff4fd08\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h6 class=\"elementor-heading-title elementor-size-default\"><span class=\"inicio-ay\"> <a class=\"breadcrumb-link-ay\" href=\"https:\/\/emmapay.com\/costa-rica\/ayuda\/preguntas-frecuentes\">Ayuda<\/a> <\/span><\/span><span class=\"whi\">\/ <span class=\"inicio-ay\"> <a class=\"breadcrumb-link-ay\" href=\"https:\/\/emmapay.com\/costa-rica\/ayuda\/preguntas-frecuentes\">Preguntas frecuentes<\/a><\/span>  \/<\/span>  Emma para personas<\/h6>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-511b9985 e-flex e-con-boxed e-con e-parent\" data-id=\"511b9985\" data-element_type=\"container\" data-settings=\"{&quot;container_type&quot;:&quot;flex&quot;,&quot;content_width&quot;:&quot;boxed&quot;}\" data-core-v316-plus=\"true\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-9dabee0 e-flex e-con-boxed e-con e-parent\" data-id=\"9dabee0\" data-element_type=\"container\" data-settings=\"{&quot;container_type&quot;:&quot;flex&quot;,&quot;content_width&quot;:&quot;boxed&quot;}\" data-core-v316-plus=\"true\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-2d9b9541 elementor-widget elementor-widget-heading\" data-id=\"2d9b9541\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">Preguntas<\/h1>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-45ac97fd elementor-widget elementor-widget-heading\" data-id=\"45ac97fd\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">frecuen<span class=\"title-gr\">tes<\/span><\/h1>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-760aa316 elementor-hidden-tablet elementor-hidden-mobile_extra elementor-hidden-mobile e-flex e-con-boxed e-con e-parent\" data-id=\"760aa316\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;container_type&quot;:&quot;flex&quot;,&quot;content_width&quot;:&quot;boxed&quot;}\" data-e-bg-lazyload=\"\" data-core-v316-plus=\"true\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-4c3be8b5 e-con-full e-flex e-con e-parent\" data-id=\"4c3be8b5\" data-element_type=\"container\" data-settings=\"{&quot;content_width&quot;:&quot;full&quot;,&quot;container_type&quot;:&quot;flex&quot;}\" data-core-v316-plus=\"true\">\n\t\t\t\t<div class=\"elementor-element elementor-element-2cdd4ce9 elementor-widget elementor-widget-elementskit-tab\" data-id=\"2cdd4ce9\" data-element_type=\"widget\" data-widget_type=\"elementskit-tab.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<div class=\"ekit-wid-con\" >        <div class=\"elementkit-tab-wraper vertical  elementskit-fitcontent-tab \">\n            <ul class=\"nav nav-tabs elementkit-tab-nav \">\n                                    <li class=\"elementkit-nav-item elementor-repeater-item-374d0f0\">\n                        <a class=\"elementkit-nav-link  active left-pos\" id=\"content-374d0f06a980b399e48a-tab\" data-ekit-handler-id=\"cr-dito-emma\" data-ekit-toggle=\"tab\" data-target=\"#content-374d0f06a980b399e48a\" href=\"#content-374d0f06a980b399e48a\"\n                            data-ekit-toggle-trigger=\"click\"\n                            aria-describedby=\"content-374d0f06a980b399e48a\">\n                            <span class=\"elementskit-tab-icon\"><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"40\" height=\"40\" viewBox=\"0 0 40 40\" fill=\"none\"><path d=\"M37.1666 18.1997V26.7831C37.1666 31.9164 34.2333 34.1163 29.8333 34.1163H15.1833C13.9499 34.1163 12.8333 33.9498 11.8666 33.5831C9.88327 32.8498 8.53326 31.3331 8.04993 28.8998C8.71659 29.0498 9.43326 29.1163 10.1833 29.1163H24.8333C29.2333 29.1163 32.1666 26.9164 32.1666 21.7831V13.1997C32.1666 12.4164 32.0999 11.7164 31.9666 11.0664C35.1333 11.7331 37.1666 13.9664 37.1666 18.1997Z\" stroke=\"#26D07C\" stroke-width=\"2\" stroke-miterlimit=\"10\" stroke-linecap=\"round\" stroke-linejoin=\"round\"><\/path><path d=\"M7.96667 13.833V21.1664\" stroke=\"#26D07C\" stroke-width=\"2\" stroke-miterlimit=\"10\" stroke-linecap=\"round\" stroke-linejoin=\"round\"><\/path><path d=\"M27.0333 13.833V21.1664\" stroke=\"#26D07C\" stroke-width=\"2\" stroke-miterlimit=\"10\" stroke-linecap=\"round\" stroke-linejoin=\"round\"><\/path><path d=\"M32.1666 13.2005V21.7838C32.1666 26.9172 29.2333 29.1171 24.8333 29.1171H10.1833C9.4333 29.1171 8.71663 29.0505 8.04997 28.9005C7.6333 28.8339 7.23331 28.7172 6.86665 28.5839C4.36665 27.6505 2.84998 25.4838 2.84998 21.7838V13.2005C2.84998 8.06713 5.7833 5.86719 10.1833 5.86719H24.8333C28.5666 5.86719 31.25 7.45051 31.9666 11.0672C32.0833 11.7338 32.1666 12.4171 32.1666 13.2005Z\" stroke=\"#171C8F\" stroke-width=\"2\" stroke-miterlimit=\"10\" stroke-linecap=\"round\" stroke-linejoin=\"round\"><\/path><path d=\"M17.5 21.8997C19.9301 21.8997 21.9 19.9297 21.9 17.4996C21.9 15.0696 19.9301 13.0996 17.5 13.0996C15.0699 13.0996 13.1 15.0696 13.1 17.4996C13.1 19.9297 15.0699 21.8997 17.5 21.8997Z\" stroke=\"#171C8F\" stroke-width=\"2\" stroke-miterlimit=\"10\" stroke-linecap=\"round\" stroke-linejoin=\"round\"><\/path><\/svg><\/span>                            <div class=\"ekit-tab-title-group\">\n                                                                <span class=\"elementskit-tab-title\">Cr\u00e9dito Emma<\/span>\n                            <\/div>\n                        <\/a>\n                    <\/li>\n                                        <li class=\"elementkit-nav-item elementor-repeater-item-f03385b\">\n                        <a class=\"elementkit-nav-link  left-pos\" id=\"content-f03385b6a980b399e48a-tab\" data-ekit-handler-id=\"nueva-app\" data-ekit-toggle=\"tab\" data-target=\"#content-f03385b6a980b399e48a\" href=\"#content-f03385b6a980b399e48a\"\n                            data-ekit-toggle-trigger=\"click\"\n                            aria-describedby=\"content-f03385b6a980b399e48a\">\n                            <span class=\"elementskit-tab-icon\"><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"28\" height=\"34\" viewBox=\"0 0 28 34\" fill=\"none\"><path d=\"M26.6 9V25C26.6 31.4 25 33 18.6 33H9C2.6 33 1 31.4 1 25V9C1 2.6 2.6 1 9 1H18.6C25 1 26.6 2.6 26.6 9Z\" stroke=\"#171C8F\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\"><\/path><path d=\"M17 6.59961H10.6\" stroke=\"#26D07C\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\"><\/path><path d=\"M13.7999 28.3604C15.1696 28.3604 16.2799 27.2501 16.2799 25.8804C16.2799 24.5107 15.1696 23.4004 13.7999 23.4004C12.4303 23.4004 11.3199 24.5107 11.3199 25.8804C11.3199 27.2501 12.4303 28.3604 13.7999 28.3604Z\" stroke=\"#26D07C\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\"><\/path><\/svg><\/span>                            <div class=\"ekit-tab-title-group\">\n                                                                <span class=\"elementskit-tab-title\">Nueva APP<\/span>\n                            <\/div>\n                        <\/a>\n                    <\/li>\n                                        <li class=\"elementkit-nav-item elementor-repeater-item-8f344c9\">\n                        <a class=\"elementkit-nav-link  left-pos\" id=\"content-8f344c96a980b399e48a-tab\" data-ekit-handler-id=\"descarga-y-registro\" data-ekit-toggle=\"tab\" data-target=\"#content-8f344c96a980b399e48a\" href=\"#content-8f344c96a980b399e48a\"\n                            data-ekit-toggle-trigger=\"click\"\n                            aria-describedby=\"content-8f344c96a980b399e48a\">\n                            <span class=\"elementskit-tab-icon\"><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"40\" height=\"40\" viewBox=\"0 0 40 40\" fill=\"none\"><path d=\"M18.3334 3.33301H15C6.66671 3.33301 3.33337 6.66634 3.33337 14.9997V24.9997C3.33337 33.333 6.66671 36.6663 15 36.6663H25C33.3334 36.6663 36.6667 33.333 36.6667 24.9997V21.6663\" stroke=\"#26D07C\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\"><\/path><path d=\"M24.85 6.91699C25.9666 10.9003 29.0833 14.017 33.0833 15.1503\" stroke=\"#26D07C\" stroke-width=\"2\" stroke-miterlimit=\"10\" stroke-linecap=\"round\" stroke-linejoin=\"round\"><\/path><path d=\"M26.7334 5.03375L13.6 18.1671C13.1 18.6671 12.6 19.6504 12.5 20.3671L11.7834 25.3838C11.5167 27.2004 12.8 28.4671 14.6167 28.2171L19.6334 27.5004C20.3334 27.4004 21.3167 26.9004 21.8334 26.4004L34.9667 13.2671C37.2334 11.0004 38.3 8.36709 34.9667 5.03375C31.6334 1.70042 29 2.76709 26.7334 5.03375Z\" stroke=\"#171C8F\" stroke-width=\"2\" stroke-miterlimit=\"10\" stroke-linecap=\"round\" stroke-linejoin=\"round\"><\/path><\/svg><\/span>                            <div class=\"ekit-tab-title-group\">\n                                                                <span class=\"elementskit-tab-title\">Descarga y registro<\/span>\n                            <\/div>\n                        <\/a>\n                    <\/li>\n                                        <li class=\"elementkit-nav-item elementor-repeater-item-9e97dfa\">\n                        <a class=\"elementkit-nav-link  left-pos\" id=\"content-9e97dfa6a980b399e48a-tab\" data-ekit-handler-id=\"mi-aplicaci-n-de-cr-dito\" data-ekit-toggle=\"tab\" data-target=\"#content-9e97dfa6a980b399e48a\" href=\"#content-9e97dfa6a980b399e48a\"\n                            data-ekit-toggle-trigger=\"click\"\n                            aria-describedby=\"content-9e97dfa6a980b399e48a\">\n                            <span class=\"elementskit-tab-icon\"><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"40\" height=\"40\" viewBox=\"0 0 40 40\" fill=\"none\"><path d=\"M20 24.1663C22.3012 24.1663 24.1667 22.3009 24.1667 19.9997C24.1667 17.6985 22.3012 15.833 20 15.833C17.6989 15.833 15.8334 17.6985 15.8334 19.9997C15.8334 22.3009 17.6989 24.1663 20 24.1663Z\" stroke=\"#26D07C\" stroke-width=\"2\" stroke-miterlimit=\"10\" stroke-linecap=\"round\" stroke-linejoin=\"round\"><\/path><path d=\"M30.8334 15.833V24.1663\" stroke=\"#26D07C\" stroke-width=\"2\" stroke-miterlimit=\"10\" stroke-linecap=\"round\" stroke-linejoin=\"round\"><\/path><path d=\"M15 29.9997C15 31.2497 14.65 32.433 14.0333 33.433C12.8833 35.3663 10.7666 36.6663 8.33329 36.6663C5.89996 36.6663 3.78327 35.3663 2.63327 33.433C2.0166 32.433 1.66663 31.2497 1.66663 29.9997C1.66663 26.3163 4.64996 23.333 8.33329 23.333C12.0166 23.333 15 26.3163 15 29.9997Z\" stroke=\"#171C8F\" stroke-width=\"2\" stroke-miterlimit=\"10\" stroke-linecap=\"round\" stroke-linejoin=\"round\"><\/path><path d=\"M5.73328 29.9995L7.38326 31.6495L10.9333 28.3662\" stroke=\"#171C8F\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\"><\/path><path d=\"M3.33337 25.5003V15.0003C3.33337 9.16699 6.66671 6.66699 11.6667 6.66699H28.3334C33.3334 6.66699 36.6667 9.16699 36.6667 15.0003V25.0003C36.6667 30.8337 33.3334 33.3337 28.3334 33.3337H14.1667\" stroke=\"#171C8F\" stroke-width=\"2\" stroke-miterlimit=\"10\" stroke-linecap=\"round\" stroke-linejoin=\"round\"><\/path><\/svg><\/span>                            <div class=\"ekit-tab-title-group\">\n                                                                <span class=\"elementskit-tab-title\">Mi aplicaci\u00f3n de cr\u00e9dito<\/span>\n                            <\/div>\n                        <\/a>\n                    <\/li>\n                                        <li class=\"elementkit-nav-item elementor-repeater-item-c89dda1\">\n                        <a class=\"elementkit-nav-link  left-pos\" id=\"content-c89dda16a980b399e48a-tab\" data-ekit-handler-id=\"compras-con-emma\" data-ekit-toggle=\"tab\" data-target=\"#content-c89dda16a980b399e48a\" href=\"#content-c89dda16a980b399e48a\"\n                            data-ekit-toggle-trigger=\"click\"\n                            aria-describedby=\"content-c89dda16a980b399e48a\">\n                            <span class=\"elementskit-tab-icon\"><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"40\" height=\"40\" viewBox=\"0 0 40 40\" fill=\"none\"><path d=\"M13.3334 13.333V7.49967C13.3334 4.99967 15 3.33301 17.5 3.33301H22.5C25 3.33301 26.6667 4.99967 26.6667 7.49967V13.333\" stroke=\"#26D07C\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\"><\/path><path d=\"M34.0167 28.3838H13.3334\" stroke=\"#26D07C\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\"><\/path><path d=\"M14 10.833H26.0001C31.6667 10.833 32.2334 13.483 32.6167 16.7163L34.1167 29.2163C34.6001 33.3163 33.3334 36.6663 27.5001 36.6663H12.5167C6.66671 36.6663 5.40004 33.3163 5.90004 29.2163L7.40006 16.7163C7.76672 13.483 8.33337 10.833 14 10.833Z\" stroke=\"#171C8F\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\"><\/path><\/svg><\/span>                            <div class=\"ekit-tab-title-group\">\n                                                                <span class=\"elementskit-tab-title\">Compras con Emma<\/span>\n                            <\/div>\n                        <\/a>\n                    <\/li>\n                                        <li class=\"elementkit-nav-item elementor-repeater-item-64fec06\">\n                        <a class=\"elementkit-nav-link  left-pos\" id=\"content-64fec066a980b399e48a-tab\" data-ekit-handler-id=\"pago-de-mis-cuotas\" data-ekit-toggle=\"tab\" data-target=\"#content-64fec066a980b399e48a\" href=\"#content-64fec066a980b399e48a\"\n                            data-ekit-toggle-trigger=\"click\"\n                            aria-describedby=\"content-64fec066a980b399e48a\">\n                            <span class=\"elementskit-tab-icon\"><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"40\" height=\"40\" viewBox=\"0 0 40 40\" fill=\"none\"><path d=\"M17.9168 28.0996V31.483C17.9168 34.3497 15.2502 36.6663 11.9668 36.6663C8.68348 36.6663 6.00012 34.3497 6.00012 31.483V28.0996C6.00012 30.9663 8.66682 32.9996 11.9668 32.9996C15.2502 32.9996 17.9168 30.9496 17.9168 28.0996Z\" stroke=\"#26D07C\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\"><\/path><path d=\"M17.9163 23.5162C17.9163 24.3496 17.683 25.1162 17.283 25.7829C16.2996 27.3995 14.283 28.4162 11.9496 28.4162C9.61629 28.4162 7.59961 27.3829 6.61627 25.7829C6.21627 25.1162 5.98303 24.3496 5.98303 23.5162C5.98303 22.0829 6.64966 20.7996 7.71633 19.8662C8.79966 18.9162 10.2829 18.3496 11.9329 18.3496C13.5829 18.3496 15.0663 18.9329 16.1497 19.8662C17.2497 20.7829 17.9163 22.0829 17.9163 23.5162Z\" stroke=\"#26D07C\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\"><\/path><path d=\"M17.9168 23.5163V28.0997C17.9168 30.9663 15.2502 32.9997 11.9668 32.9997C8.68348 32.9997 6.00012 30.9497 6.00012 28.0997V23.5163C6.00012 20.6497 8.66682 18.333 11.9668 18.333C13.6168 18.333 15.1002 18.9163 16.1835 19.8496C17.2502 20.783 17.9168 22.083 17.9168 23.5163Z\" stroke=\"#26D07C\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\"><\/path><path d=\"M36.6667 18.2829V21.7164C36.6667 22.633 35.9334 23.383 35 23.4163H31.7333C29.9333 23.4163 28.2834 22.0996 28.1334 20.2996C28.0334 19.2496 28.4333 18.2663 29.1333 17.583C29.75 16.9496 30.6 16.583 31.5333 16.583H35C35.9334 16.6163 36.6667 17.3663 36.6667 18.2829Z\" stroke=\"#171C8F\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\"><\/path><path d=\"M3.33337 17.4997V14.1663C3.33337 9.63301 6.06671 6.46634 10.3167 5.933C10.75 5.86634 11.2 5.83301 11.6667 5.83301H26.6667C27.1 5.83301 27.5167 5.84965 27.9167 5.91632C32.2167 6.41632 35 9.59967 35 14.1663V16.583H31.5333C30.6 16.583 29.75 16.9497 29.1333 17.583C28.4333 18.2663 28.0334 19.2497 28.1334 20.2997C28.2834 22.0997 29.9333 23.4163 31.7333 23.4163H35V25.833C35 30.833 31.6667 34.1663 26.6667 34.1663H22.5\" stroke=\"#171C8F\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\"><\/path><\/svg><\/span>                            <div class=\"ekit-tab-title-group\">\n                                                                <span class=\"elementskit-tab-title\">Pago de mis cuotas<\/span>\n                            <\/div>\n                        <\/a>\n                    <\/li>\n                                        <li class=\"elementkit-nav-item elementor-repeater-item-88288a4\">\n                        <a class=\"elementkit-nav-link  left-pos\" id=\"content-88288a46a980b399e48a-tab\" data-ekit-handler-id=\"seguridad\" data-ekit-toggle=\"tab\" data-target=\"#content-88288a46a980b399e48a\" href=\"#content-88288a46a980b399e48a\"\n                            data-ekit-toggle-trigger=\"click\"\n                            aria-describedby=\"content-88288a46a980b399e48a\">\n                            <span class=\"elementskit-tab-icon\"><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"40\" height=\"40\" viewBox=\"0 0 40 40\" fill=\"none\"><path d=\"M15 36.6663H25C33.3334 36.6663 36.6667 33.333 36.6667 24.9997V14.9997C36.6667 6.66634 33.3334 3.33301 25 3.33301H15C6.66671 3.33301 3.33337 6.66634 3.33337 14.9997V24.9997C3.33337 33.333 6.66671 36.6663 15 36.6663Z\" stroke=\"#171C8F\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\"><\/path><path d=\"M27.132 22.6824C25.2487 24.5658 22.5487 25.1491 20.1653 24.3991L15.8487 28.6991C15.5487 29.0158 14.932 29.2158 14.482 29.1491L12.482 28.8824C11.8153 28.7991 11.2153 28.1658 11.1153 27.5158L10.8487 25.5158C10.782 25.0824 10.9987 24.4658 11.2987 24.1491L15.5987 19.8491C14.8653 17.4658 15.432 14.7658 17.3153 12.8824C20.0153 10.1824 24.4153 10.1824 27.132 12.8824C29.832 15.5658 29.832 19.9658 27.132 22.6824Z\" stroke=\"#26D07C\" stroke-width=\"2\" stroke-miterlimit=\"10\" stroke-linecap=\"round\" stroke-linejoin=\"round\"><\/path><path d=\"M17.4159 27.1326L15.9993 25.6992\" stroke=\"#26D07C\" stroke-width=\"2\" stroke-miterlimit=\"10\" stroke-linecap=\"round\" stroke-linejoin=\"round\"><\/path><path d=\"M22.3248 17.8333H22.3398\" stroke=\"#26D07C\" stroke-width=\"2\" stroke-linecap=\"round\" stroke-linejoin=\"round\"><\/path><\/svg><\/span>                            <div class=\"ekit-tab-title-group\">\n                                                                <span class=\"elementskit-tab-title\">Seguridad<\/span>\n                            <\/div>\n                        <\/a>\n                    <\/li>\n                                <\/ul>\n\n            <div class=\"tab-content elementkit-tab-content\">\n                                    <div class=\"tab-pane elementkit-tab-pane elementor-repeater-item-374d0f0  active show\" id=\"content-374d0f06a980b399e48a\" role=\"tabpanel\"\n                         aria-labelledby=\"content-374d0f06a980b399e48a-tab\">\n                        <div class=\"animated fadeIn\">\n                            \n\t\t<div class=\"widgetarea_warper widgetarea_warper_editable\" data-elementskit-widgetarea-key=\"2cdd4ce9\"  data-elementskit-widgetarea-index=\"374d0f0\">\n\t\t\t<div class=\"widgetarea_warper_edit\" data-elementskit-widgetarea-key=\"2cdd4ce9\" data-elementskit-widgetarea-index=\"374d0f0\">\n\t\t\t\t<i class=\"eicon-edit\" aria-hidden=\"true\"><\/i>\n\t\t\t\t<span>Edit Content<\/span>\n\t\t\t<\/div>\n\n\t\t\t\t\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"2507\" class=\"elementor elementor-2507\" data-elementor-post-type=\"elementskit_content\">\n\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-59100148 e-con-full e-flex e-con e-parent\" data-id=\"59100148\" data-element_type=\"container\" data-settings=\"{&quot;content_width&quot;:&quot;full&quot;,&quot;container_type&quot;:&quot;flex&quot;}\" data-core-v316-plus=\"true\">\n\t\t\t\t<div class=\"elementor-element elementor-element-4c931bf6 elementor-widget elementor-widget-elementskit-advance-accordion\" data-id=\"4c931bf6\" data-element_type=\"widget\" id=\"faq-credito-emma\" data-widget_type=\"elementskit-advance-accordion.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<div class=\"ekit-wid-con\">\n\n        <div class=\"elementskit-accordion accoedion-primary\" id=\"accordion-6a980b39a305e\">\n\n            \n                <div class=\"elementskit-card\">\n                    <div class=\"elementskit-card-header\" id=\"primaryHeading-0-4c931bf6\">\n                        <a href=\"#collapse-9ac97566a980b39a305e\" class=\"elementskit-btn-link collapsed\" data-ekit-toggle=\"collapse\" data-target=\"#Collapse-9ac97566a980b39a305e\" aria-expanded=\"false\" aria-controls=\"Collapse-9ac97566a980b39a305e\">\n                            \n                            <span class=\"ekit-accordion-title\">\u00bfQu\u00e9 es Emma?<\/span>\n\n                            \n                                <div class=\"ekit_accordion_icon_group\">\n\n                                    <div class=\"ekit_accordion_normal_icon\">\n                                        <!-- Normal Icon -->\n                                        <i aria-hidden=\"true\" class=\"icon-open icon-left icon icon-down-arrow1\"><\/i>                                    <\/div>\n\n                                    <div class=\"ekit_accordion_active_icon\">\n                                    <!-- Active Icon -->\n                                    <i aria-hidden=\"true\" class=\"icon-closed icon-left icon icon-up-arrow1\"><\/i>                                    <\/div>\n                                <\/div>\n\n                            \n                                                    <\/a>\n                    <\/div>\n\n                    <div id=\"Collapse-9ac97566a980b39a305e\" class=\" collapse\" aria-labelledby=\"primaryHeading-0-4c931bf6\" data-parent=\"#accordion-6a980b39a305e\">\n                      \n                        <div class=\"elementskit-card-body\">\n                            \n\t\t<div class=\"widgetarea_warper widgetarea_warper_editable\" data-elementskit-widgetarea-key=\"4c931bf6\"  data-elementskit-widgetarea-index=\"9ac9756\">\n\t\t\t<div class=\"widgetarea_warper_edit\" data-elementskit-widgetarea-key=\"4c931bf6\" data-elementskit-widgetarea-index=\"9ac9756\">\n\t\t\t\t<i class=\"eicon-edit\" aria-hidden=\"true\"><\/i>\n\t\t\t\t<span>Edit Content<\/span>\n\t\t\t<\/div>\n\n\t\t\t\t\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"2598\" class=\"elementor elementor-2598\" data-elementor-post-type=\"elementskit_content\">\n\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6874cb75 faq-answer-desktop e-flex e-con-boxed e-con e-parent\" data-id=\"6874cb75\" data-element_type=\"container\" data-settings=\"{&quot;container_type&quot;:&quot;flex&quot;,&quot;content_width&quot;:&quot;boxed&quot;}\" data-core-v316-plus=\"true\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-60376e02 elementor-widget elementor-widget-text-editor\" data-id=\"60376e02\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<style>\/*! elementor - v3.17.0 - 25-10-2023 *\/\n.elementor-widget-text-editor.elementor-drop-cap-view-stacked .elementor-drop-cap{background-color:#69727d;color:#fff}.elementor-widget-text-editor.elementor-drop-cap-view-framed .elementor-drop-cap{color:#69727d;border:3px solid;background-color:transparent}.elementor-widget-text-editor:not(.elementor-drop-cap-view-default) .elementor-drop-cap{margin-top:8px}.elementor-widget-text-editor:not(.elementor-drop-cap-view-default) .elementor-drop-cap-letter{width:1em;height:1em}.elementor-widget-text-editor .elementor-drop-cap{float:left;text-align:center;line-height:1;font-size:50px}.elementor-widget-text-editor .elementor-drop-cap-letter{display:inline-block}<\/style>\t\t\t\t<p>Emma es la app que te d\u00e1 cr\u00e9dito 100% digital desde tu app de forma r\u00e1pida, f\u00e1cil y segura para que lo us\u00e9s en lo que necesit\u00e9s. Podr\u00e1s utilizar el cr\u00e9dito para comprar en m\u00e1s de 4mil comercios afiliados a Emma o hacer retiros de efectivo.<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t                        <\/div>\n\n                    <\/div>\n\n                <\/div><!-- .elementskit-card END --> \n\n                \n                <div class=\"elementskit-card\">\n                    <div class=\"elementskit-card-header\" id=\"primaryHeading-1-4c931bf6\">\n                        <a href=\"#collapse-03f71806a980b39a305e\" class=\"elementskit-btn-link collapsed\" data-ekit-toggle=\"collapse\" data-target=\"#Collapse-03f71806a980b39a305e\" aria-expanded=\"false\" aria-controls=\"Collapse-03f71806a980b39a305e\">\n                            \n                            <span class=\"ekit-accordion-title\">\u00bfCu\u00e1les son los requisitos para solicitar un cr\u00e9dito Emma?<\/span>\n\n                            \n                                <div class=\"ekit_accordion_icon_group\">\n\n                                    <div class=\"ekit_accordion_normal_icon\">\n                                        <!-- Normal Icon -->\n                                        <i aria-hidden=\"true\" class=\"icon-open icon-left icon icon-down-arrow1\"><\/i>                                    <\/div>\n\n                                    <div class=\"ekit_accordion_active_icon\">\n                                    <!-- Active Icon -->\n                                    <i aria-hidden=\"true\" class=\"icon-closed icon-left icon icon-up-arrow1\"><\/i>                                    <\/div>\n                                <\/div>\n\n                            \n                                                    <\/a>\n                    <\/div>\n\n                    <div id=\"Collapse-03f71806a980b39a305e\" class=\" collapse\" aria-labelledby=\"primaryHeading-1-4c931bf6\" data-parent=\"#accordion-6a980b39a305e\">\n                      \n                        <div class=\"elementskit-card-body\">\n                            \n\t\t<div class=\"widgetarea_warper widgetarea_warper_editable\" data-elementskit-widgetarea-key=\"4c931bf6\"  data-elementskit-widgetarea-index=\"03f7180\">\n\t\t\t<div class=\"widgetarea_warper_edit\" data-elementskit-widgetarea-key=\"4c931bf6\" data-elementskit-widgetarea-index=\"03f7180\">\n\t\t\t\t<i class=\"eicon-edit\" aria-hidden=\"true\"><\/i>\n\t\t\t\t<span>Edit Content<\/span>\n\t\t\t<\/div>\n\n\t\t\t\t\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"2605\" class=\"elementor elementor-2605\" data-elementor-post-type=\"elementskit_content\">\n\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6a8b2ec9 faq-answer-desktop e-flex e-con-boxed e-con e-parent\" data-id=\"6a8b2ec9\" data-element_type=\"container\" data-settings=\"{&quot;container_type&quot;:&quot;flex&quot;,&quot;content_width&quot;:&quot;boxed&quot;}\" data-core-v316-plus=\"true\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-2139e346 elementor-widget elementor-widget-text-editor\" data-id=\"2139e346\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>Para solicitar una l\u00ednea de cr\u00e9dito Emma deber\u00e1s:<\/p><ol><li>Ser mayor de edad<\/li><li>Tener tu documento de identidad vigente<\/li><li>Comprobante de ingresos (opcional)<\/li><\/ol>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t                        <\/div>\n\n                    <\/div>\n\n                <\/div><!-- .elementskit-card END --> \n\n                \n                <div class=\"elementskit-card\">\n                    <div class=\"elementskit-card-header\" id=\"primaryHeading-2-4c931bf6\">\n                        <a href=\"#collapse-f540d4d6a980b39a305e\" class=\"elementskit-btn-link collapsed\" data-ekit-toggle=\"collapse\" data-target=\"#Collapse-f540d4d6a980b39a305e\" aria-expanded=\"false\" aria-controls=\"Collapse-f540d4d6a980b39a305e\">\n                            \n                            <span class=\"ekit-accordion-title\">\u00bfQu\u00e9 documentos debo tener a la mano para solicitar mi cr\u00e9dito Emma?<\/span>\n\n                            \n                                <div class=\"ekit_accordion_icon_group\">\n\n                                    <div class=\"ekit_accordion_normal_icon\">\n                                        <!-- Normal Icon -->\n                                        <i aria-hidden=\"true\" class=\"icon-open icon-left icon icon-down-arrow1\"><\/i>                                    <\/div>\n\n                                    <div class=\"ekit_accordion_active_icon\">\n                                    <!-- Active Icon -->\n                                    <i aria-hidden=\"true\" class=\"icon-closed icon-left icon icon-up-arrow1\"><\/i>                                    <\/div>\n                                <\/div>\n\n                            \n                                                    <\/a>\n                    <\/div>\n\n                    <div id=\"Collapse-f540d4d6a980b39a305e\" class=\" collapse\" aria-labelledby=\"primaryHeading-2-4c931bf6\" data-parent=\"#accordion-6a980b39a305e\">\n                      \n                        <div class=\"elementskit-card-body\">\n                            \n\t\t<div class=\"widgetarea_warper widgetarea_warper_editable\" data-elementskit-widgetarea-key=\"4c931bf6\"  data-elementskit-widgetarea-index=\"f540d4d\">\n\t\t\t<div class=\"widgetarea_warper_edit\" data-elementskit-widgetarea-key=\"4c931bf6\" data-elementskit-widgetarea-index=\"f540d4d\">\n\t\t\t\t<i class=\"eicon-edit\" aria-hidden=\"true\"><\/i>\n\t\t\t\t<span>Edit Content<\/span>\n\t\t\t<\/div>\n\n\t\t\t\t\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"2609\" class=\"elementor elementor-2609\" data-elementor-post-type=\"elementskit_content\">\n\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2854b0b4 faq-answer-desktop e-flex e-con-boxed e-con e-parent\" data-id=\"2854b0b4\" data-element_type=\"container\" data-settings=\"{&quot;container_type&quot;:&quot;flex&quot;,&quot;content_width&quot;:&quot;boxed&quot;}\" data-core-v316-plus=\"true\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-2653e46c elementor-widget elementor-widget-text-editor\" data-id=\"2653e46c\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>Para solicitar tu LC deber\u00e1s tener a la mano t\u00fa c\u00e9dula de identidad o c\u00e9dula de residencia.<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t                        <\/div>\n\n                    <\/div>\n\n                <\/div><!-- .elementskit-card END --> \n\n                \n                <div class=\"elementskit-card\">\n                    <div class=\"elementskit-card-header\" id=\"primaryHeading-3-4c931bf6\">\n                        <a href=\"#collapse-f2092806a980b39a305e\" class=\"elementskit-btn-link collapsed\" data-ekit-toggle=\"collapse\" data-target=\"#Collapse-f2092806a980b39a305e\" aria-expanded=\"false\" aria-controls=\"Collapse-f2092806a980b39a305e\">\n                            \n                            <span class=\"ekit-accordion-title\">\u00bfCu\u00e1les son las condiciones del cr\u00e9dito Emma?<\/span>\n\n                            \n                                <div class=\"ekit_accordion_icon_group\">\n\n                                    <div class=\"ekit_accordion_normal_icon\">\n                                        <!-- Normal Icon -->\n                                        <i aria-hidden=\"true\" class=\"icon-open icon-left icon icon-down-arrow1\"><\/i>                                    <\/div>\n\n                                    <div class=\"ekit_accordion_active_icon\">\n                                    <!-- Active Icon -->\n                                    <i aria-hidden=\"true\" class=\"icon-closed icon-left icon icon-up-arrow1\"><\/i>                                    <\/div>\n                                <\/div>\n\n                            \n                                                    <\/a>\n                    <\/div>\n\n                    <div id=\"Collapse-f2092806a980b39a305e\" class=\" collapse\" aria-labelledby=\"primaryHeading-3-4c931bf6\" data-parent=\"#accordion-6a980b39a305e\">\n                      \n                        <div class=\"elementskit-card-body\">\n                            \n\t\t<div class=\"widgetarea_warper widgetarea_warper_editable\" data-elementskit-widgetarea-key=\"4c931bf6\"  data-elementskit-widgetarea-index=\"f209280\">\n\t\t\t<div class=\"widgetarea_warper_edit\" data-elementskit-widgetarea-key=\"4c931bf6\" data-elementskit-widgetarea-index=\"f209280\">\n\t\t\t\t<i class=\"eicon-edit\" aria-hidden=\"true\"><\/i>\n\t\t\t\t<span>Edit Content<\/span>\n\t\t\t<\/div>\n\n\t\t\t\t\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"2613\" class=\"elementor elementor-2613\" data-elementor-post-type=\"elementskit_content\">\n\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4c270b81 faq-answer-desktop e-flex e-con-boxed e-con e-parent\" data-id=\"4c270b81\" data-element_type=\"container\" data-settings=\"{&quot;container_type&quot;:&quot;flex&quot;,&quot;content_width&quot;:&quot;boxed&quot;}\" data-core-v316-plus=\"true\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-9f2ab0e elementor-widget elementor-widget-text-editor\" data-id=\"9f2ab0e\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>T\u00fa l\u00ednea de cr\u00e9dito depende de tu perfil de cliente, por lo que las condiciones pueden variar en cuanto a l\u00edmite y tasa de inter\u00e9s anual.<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t                        <\/div>\n\n                    <\/div>\n\n                <\/div><!-- .elementskit-card END --> \n\n                \n                <div class=\"elementskit-card\">\n                    <div class=\"elementskit-card-header\" id=\"primaryHeading-4-4c931bf6\">\n                        <a href=\"#collapse-6d4a15a6a980b39a305e\" class=\"elementskit-btn-link collapsed\" data-ekit-toggle=\"collapse\" data-target=\"#Collapse-6d4a15a6a980b39a305e\" aria-expanded=\"false\" aria-controls=\"Collapse-6d4a15a6a980b39a305e\">\n                            \n                            <span class=\"ekit-accordion-title\">\u00bfCu\u00e1l es el monto m\u00e1ximo de cr\u00e9dito que puedo obtener?<\/span>\n\n                            \n                                <div class=\"ekit_accordion_icon_group\">\n\n                                    <div class=\"ekit_accordion_normal_icon\">\n                                        <!-- Normal Icon -->\n                                        <i aria-hidden=\"true\" class=\"icon-open icon-left icon icon-down-arrow1\"><\/i>                                    <\/div>\n\n                                    <div class=\"ekit_accordion_active_icon\">\n                                    <!-- Active Icon -->\n                                    <i aria-hidden=\"true\" class=\"icon-closed icon-left icon icon-up-arrow1\"><\/i>                                    <\/div>\n                                <\/div>\n\n                            \n                                                    <\/a>\n                    <\/div>\n\n                    <div id=\"Collapse-6d4a15a6a980b39a305e\" class=\" collapse\" aria-labelledby=\"primaryHeading-4-4c931bf6\" data-parent=\"#accordion-6a980b39a305e\">\n                      \n                        <div class=\"elementskit-card-body\">\n                            \n\t\t<div class=\"widgetarea_warper widgetarea_warper_editable\" data-elementskit-widgetarea-key=\"4c931bf6\"  data-elementskit-widgetarea-index=\"6d4a15a\">\n\t\t\t<div class=\"widgetarea_warper_edit\" data-elementskit-widgetarea-key=\"4c931bf6\" data-elementskit-widgetarea-index=\"6d4a15a\">\n\t\t\t\t<i class=\"eicon-edit\" aria-hidden=\"true\"><\/i>\n\t\t\t\t<span>Edit Content<\/span>\n\t\t\t<\/div>\n\n\t\t\t\t\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"2617\" class=\"elementor elementor-2617\" data-elementor-post-type=\"elementskit_content\">\n\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3918567e faq-answer-desktop e-flex e-con-boxed e-con e-parent\" data-id=\"3918567e\" data-element_type=\"container\" data-settings=\"{&quot;container_type&quot;:&quot;flex&quot;,&quot;content_width&quot;:&quot;boxed&quot;}\" data-core-v316-plus=\"true\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-67edc59d elementor-widget elementor-widget-text-editor\" data-id=\"67edc59d\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>El monto m\u00e1ximo de l\u00ednea de cr\u00e9dito que se puede otorgar a un cliente es de 3 000 000 de colones.<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t                        <\/div>\n\n                    <\/div>\n\n                <\/div><!-- .elementskit-card END --> \n\n                \n                <div class=\"elementskit-card\">\n                    <div class=\"elementskit-card-header\" id=\"primaryHeading-5-4c931bf6\">\n                        <a href=\"#collapse-de8ede36a980b39a305e\" class=\"elementskit-btn-link collapsed\" data-ekit-toggle=\"collapse\" data-target=\"#Collapse-de8ede36a980b39a305e\" aria-expanded=\"false\" aria-controls=\"Collapse-de8ede36a980b39a305e\">\n                            \n                            <span class=\"ekit-accordion-title\">\u00bfC\u00f3mo puedo solicitar una ampliaci\u00f3n de mi l\u00ednea de cr\u00e9dito?<\/span>\n\n                            \n                                <div class=\"ekit_accordion_icon_group\">\n\n                                    <div class=\"ekit_accordion_normal_icon\">\n                                        <!-- Normal Icon -->\n                                        <i aria-hidden=\"true\" class=\"icon-open icon-left icon icon-down-arrow1\"><\/i>                                    <\/div>\n\n                                    <div class=\"ekit_accordion_active_icon\">\n                                    <!-- Active Icon -->\n                                    <i aria-hidden=\"true\" class=\"icon-closed icon-left icon icon-up-arrow1\"><\/i>                                    <\/div>\n                                <\/div>\n\n                            \n                                                    <\/a>\n                    <\/div>\n\n                    <div id=\"Collapse-de8ede36a980b39a305e\" class=\" collapse\" aria-labelledby=\"primaryHeading-5-4c931bf6\" data-parent=\"#accordion-6a980b39a305e\">\n                      \n                        <div class=\"elementskit-card-body\">\n                            \n\t\t<div class=\"widgetarea_warper widgetarea_warper_editable\" data-elementskit-widgetarea-key=\"4c931bf6\"  data-elementskit-widgetarea-index=\"de8ede3\">\n\t\t\t<div class=\"widgetarea_warper_edit\" data-elementskit-widgetarea-key=\"4c931bf6\" data-elementskit-widgetarea-index=\"de8ede3\">\n\t\t\t\t<i class=\"eicon-edit\" aria-hidden=\"true\"><\/i>\n\t\t\t\t<span>Edit Content<\/span>\n\t\t\t<\/div>\n\n\t\t\t\t\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"2621\" class=\"elementor elementor-2621\" data-elementor-post-type=\"elementskit_content\">\n\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-54dd8538 faq-answer-desktop e-flex e-con-boxed e-con e-parent\" data-id=\"54dd8538\" data-element_type=\"container\" data-settings=\"{&quot;container_type&quot;:&quot;flex&quot;,&quot;content_width&quot;:&quot;boxed&quot;}\" data-core-v316-plus=\"true\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-212a275d elementor-widget elementor-widget-text-editor\" data-id=\"212a275d\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>Debes presentarte en una sucursal de Gollo o La Curacao, y solicitar el aumento de l\u00edmite de cr\u00e9dito. Te recomendamos presentar tu orden patronal en caso de asalariados y estados de cuenta de los \u00faltimos 3 meses en caso de independientes.<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t                        <\/div>\n\n                    <\/div>\n\n                <\/div><!-- .elementskit-card END --> \n\n                \n                <div class=\"elementskit-card\">\n                    <div class=\"elementskit-card-header\" id=\"primaryHeading-6-4c931bf6\">\n                        <a href=\"#collapse-f8383a96a980b39a305e\" class=\"elementskit-btn-link collapsed\" data-ekit-toggle=\"collapse\" data-target=\"#Collapse-f8383a96a980b39a305e\" aria-expanded=\"false\" aria-controls=\"Collapse-f8383a96a980b39a305e\">\n                            \n                            <span class=\"ekit-accordion-title\">\u00bfC\u00f3mo funciona el cr\u00e9dito Emma?<\/span>\n\n                            \n                                <div class=\"ekit_accordion_icon_group\">\n\n                                    <div class=\"ekit_accordion_normal_icon\">\n                                        <!-- Normal Icon -->\n                                        <i aria-hidden=\"true\" class=\"icon-open icon-left icon icon-down-arrow1\"><\/i>                                    <\/div>\n\n                                    <div class=\"ekit_accordion_active_icon\">\n                                    <!-- Active Icon -->\n                                    <i aria-hidden=\"true\" class=\"icon-closed icon-left icon icon-up-arrow1\"><\/i>                                    <\/div>\n                                <\/div>\n\n                            \n                                                    <\/a>\n                    <\/div>\n\n                    <div id=\"Collapse-f8383a96a980b39a305e\" class=\" collapse\" aria-labelledby=\"primaryHeading-6-4c931bf6\" data-parent=\"#accordion-6a980b39a305e\">\n                      \n                        <div class=\"elementskit-card-body\">\n                            \n\t\t<div class=\"widgetarea_warper widgetarea_warper_editable\" data-elementskit-widgetarea-key=\"4c931bf6\"  data-elementskit-widgetarea-index=\"f8383a9\">\n\t\t\t<div class=\"widgetarea_warper_edit\" data-elementskit-widgetarea-key=\"4c931bf6\" data-elementskit-widgetarea-index=\"f8383a9\">\n\t\t\t\t<i class=\"eicon-edit\" aria-hidden=\"true\"><\/i>\n\t\t\t\t<span>Edit Content<\/span>\n\t\t\t<\/div>\n\n\t\t\t\t\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"2625\" class=\"elementor elementor-2625\" data-elementor-post-type=\"elementskit_content\">\n\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7c03658d faq-answer-desktop e-flex e-con-boxed e-con e-parent\" data-id=\"7c03658d\" data-element_type=\"container\" data-settings=\"{&quot;container_type&quot;:&quot;flex&quot;,&quot;content_width&quot;:&quot;boxed&quot;}\" data-core-v316-plus=\"true\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-1e086a9c elementor-widget elementor-widget-text-editor\" data-id=\"1e086a9c\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>La l\u00ednea de cr\u00e9dito Emma es revolvente. Es decir que una vez que se utiliza una parte del cr\u00e9dito disponible, la cantidad utilizada se vuelve a poner a disposici\u00f3n del cliente a medida que se realizan los pagos de las cuotas (reembolso), as\u00ed podr\u00e1s utilizar los fondos nuevamente. En otras palabras, es similar al funcionamiento de una tarjeta de cr\u00e9dito.<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t                        <\/div>\n\n                    <\/div>\n\n                <\/div><!-- .elementskit-card END --> \n\n                        <\/div>\n    <\/div>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t                        <\/div>\n                    <\/div>\n                                    <div class=\"tab-pane elementkit-tab-pane elementor-repeater-item-f03385b \" id=\"content-f03385b6a980b399e48a\" role=\"tabpanel\"\n                         aria-labelledby=\"content-f03385b6a980b399e48a-tab\">\n                        <div class=\"animated fadeIn\">\n                            \n\t\t<div class=\"widgetarea_warper widgetarea_warper_editable\" data-elementskit-widgetarea-key=\"2cdd4ce9\"  data-elementskit-widgetarea-index=\"f03385b\">\n\t\t\t<div class=\"widgetarea_warper_edit\" data-elementskit-widgetarea-key=\"2cdd4ce9\" data-elementskit-widgetarea-index=\"f03385b\">\n\t\t\t\t<i class=\"eicon-edit\" aria-hidden=\"true\"><\/i>\n\t\t\t\t<span>Edit Content<\/span>\n\t\t\t<\/div>\n\n\t\t\t\t\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"2525\" class=\"elementor elementor-2525\" data-elementor-post-type=\"elementskit_content\">\n\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-370c78f0 e-con-full e-flex e-con e-parent\" data-id=\"370c78f0\" data-element_type=\"container\" data-settings=\"{&quot;content_width&quot;:&quot;full&quot;,&quot;container_type&quot;:&quot;flex&quot;}\" data-core-v316-plus=\"true\">\n\t\t\t\t<div class=\"elementor-element elementor-element-72493113 elementor-widget elementor-widget-elementskit-advance-accordion\" data-id=\"72493113\" data-element_type=\"widget\" data-widget_type=\"elementskit-advance-accordion.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<div class=\"ekit-wid-con\">\n\n        <div class=\"elementskit-accordion accoedion-primary\" id=\"accordion-6a980b39b7e2a\">\n\n            \n                <div class=\"elementskit-card\">\n                    <div class=\"elementskit-card-header\" id=\"primaryHeading-0-72493113\">\n                        <a href=\"#collapse-9ac97566a980b39b7e2a\" class=\"elementskit-btn-link collapsed\" data-ekit-toggle=\"collapse\" data-target=\"#Collapse-9ac97566a980b39b7e2a\" aria-expanded=\"false\" aria-controls=\"Collapse-9ac97566a980b39b7e2a\">\n                            \n                            <span class=\"ekit-accordion-title\">\u00bfPor qu\u00e9 hay una nueva aplicaci\u00f3n Emma?<\/span>\n\n                            \n                                <div class=\"ekit_accordion_icon_group\">\n\n                                    <div class=\"ekit_accordion_normal_icon\">\n                                        <!-- Normal Icon -->\n                                        <i aria-hidden=\"true\" class=\"icon-open icon-left icon icon-down-arrow1\"><\/i>                                    <\/div>\n\n                                    <div class=\"ekit_accordion_active_icon\">\n                                    <!-- Active Icon -->\n                                    <i aria-hidden=\"true\" class=\"icon-closed icon-left icon icon-up-arrow1\"><\/i>                                    <\/div>\n                                <\/div>\n\n                            \n                                                    <\/a>\n                    <\/div>\n\n                    <div id=\"Collapse-9ac97566a980b39b7e2a\" class=\" collapse\" aria-labelledby=\"primaryHeading-0-72493113\" data-parent=\"#accordion-6a980b39b7e2a\">\n                      \n                        <div class=\"elementskit-card-body\">\n                            \n\t\t<div class=\"widgetarea_warper widgetarea_warper_editable\" data-elementskit-widgetarea-key=\"72493113\"  data-elementskit-widgetarea-index=\"9ac9756\">\n\t\t\t<div class=\"widgetarea_warper_edit\" data-elementskit-widgetarea-key=\"72493113\" data-elementskit-widgetarea-index=\"9ac9756\">\n\t\t\t\t<i class=\"eicon-edit\" aria-hidden=\"true\"><\/i>\n\t\t\t\t<span>Edit Content<\/span>\n\t\t\t<\/div>\n\n\t\t\t\t\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"2642\" class=\"elementor elementor-2642\" data-elementor-post-type=\"elementskit_content\">\n\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4eab0f1b faq-answer-desktop e-flex e-con-boxed e-con e-parent\" data-id=\"4eab0f1b\" data-element_type=\"container\" data-settings=\"{&quot;container_type&quot;:&quot;flex&quot;,&quot;content_width&quot;:&quot;boxed&quot;}\" data-core-v316-plus=\"true\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-73362945 elementor-widget elementor-widget-text-editor\" data-id=\"73362945\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>Porque queremos darle la mejor experiencia a nuestros clientes y comercios aliados. La nueva app es m\u00e1s f\u00e1cil, r\u00e1pida y segura.<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t                        <\/div>\n\n                    <\/div>\n\n                <\/div><!-- .elementskit-card END --> \n\n                \n                <div class=\"elementskit-card\">\n                    <div class=\"elementskit-card-header\" id=\"primaryHeading-1-72493113\">\n                        <a href=\"#collapse-03f71806a980b39b7e2a\" class=\"elementskit-btn-link collapsed\" data-ekit-toggle=\"collapse\" data-target=\"#Collapse-03f71806a980b39b7e2a\" aria-expanded=\"false\" aria-controls=\"Collapse-03f71806a980b39b7e2a\">\n                            \n                            <span class=\"ekit-accordion-title\">Si ya ten\u00eda una l\u00ednea de cr\u00e9dito aprobada en Emma, \u00bfdebo volver a aplicar a un cr\u00e9dito?<\/span>\n\n                            \n                                <div class=\"ekit_accordion_icon_group\">\n\n                                    <div class=\"ekit_accordion_normal_icon\">\n                                        <!-- Normal Icon -->\n                                        <i aria-hidden=\"true\" class=\"icon-open icon-left icon icon-down-arrow1\"><\/i>                                    <\/div>\n\n                                    <div class=\"ekit_accordion_active_icon\">\n                                    <!-- Active Icon -->\n                                    <i aria-hidden=\"true\" class=\"icon-closed icon-left icon icon-up-arrow1\"><\/i>                                    <\/div>\n                                <\/div>\n\n                            \n                                                    <\/a>\n                    <\/div>\n\n                    <div id=\"Collapse-03f71806a980b39b7e2a\" class=\" collapse\" aria-labelledby=\"primaryHeading-1-72493113\" data-parent=\"#accordion-6a980b39b7e2a\">\n                      \n                        <div class=\"elementskit-card-body\">\n                            \n\t\t<div class=\"widgetarea_warper widgetarea_warper_editable\" data-elementskit-widgetarea-key=\"72493113\"  data-elementskit-widgetarea-index=\"03f7180\">\n\t\t\t<div class=\"widgetarea_warper_edit\" data-elementskit-widgetarea-key=\"72493113\" data-elementskit-widgetarea-index=\"03f7180\">\n\t\t\t\t<i class=\"eicon-edit\" aria-hidden=\"true\"><\/i>\n\t\t\t\t<span>Edit Content<\/span>\n\t\t\t<\/div>\n\n\t\t\t\t\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"2646\" class=\"elementor elementor-2646\" data-elementor-post-type=\"elementskit_content\">\n\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1088bcf1 faq-answer-desktop e-flex e-con-boxed e-con e-parent\" data-id=\"1088bcf1\" data-element_type=\"container\" data-settings=\"{&quot;container_type&quot;:&quot;flex&quot;,&quot;content_width&quot;:&quot;boxed&quot;}\" data-core-v316-plus=\"true\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-0922b13 e-flex e-con-boxed e-con e-parent\" data-id=\"0922b13\" data-element_type=\"container\" data-settings=\"{&quot;container_type&quot;:&quot;flex&quot;,&quot;content_width&quot;:&quot;boxed&quot;}\" data-core-v316-plus=\"true\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-db1adc7 elementor-widget elementor-widget-text-editor\" data-id=\"db1adc7\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>No. Si ya ten\u00e9s una l\u00ednea de cr\u00e9dito Emma, no necesit\u00e1s aplicar a una nueva l\u00ednea de cr\u00e9dito. Para acceder a la informaci\u00f3n de tu cr\u00e9dito Emma solo deber\u00e1s:<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-b02ee46 e-flex e-con-boxed e-con e-parent\" data-id=\"b02ee46\" data-element_type=\"container\" data-settings=\"{&quot;container_type&quot;:&quot;flex&quot;,&quot;content_width&quot;:&quot;boxed&quot;}\" data-core-v316-plus=\"true\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-cb05854 e-con-full e-flex e-con e-parent\" data-id=\"cb05854\" data-element_type=\"container\" data-settings=\"{&quot;content_width&quot;:&quot;full&quot;,&quot;container_type&quot;:&quot;flex&quot;}\" data-core-v316-plus=\"true\">\n\t\t\t\t<div class=\"elementor-element elementor-element-a68a225 faq-lnk elementor-widget elementor-widget-elementskit-popup-modal\" data-id=\"a68a225\" data-element_type=\"widget\" data-widget_type=\"elementskit-popup-modal.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<div class=\"ekit-wid-con\" >        <!-- Start Markup -->\n                            <div class='ekit-popup-modal__toggler-wrapper'>\n                    <!-- Button trigger modal -->\n                    <button \n                        type=\"button\" \n                        class=\"elementskit-btn ekit-popup-btn ekit-popup-btn__filled ekit-popup__toggler ekit-popup-modal-toggler whitespace--normal\" \n                        data-toggle=\"modal\" \n                        data-target=\"#ekit-popup-modal\"\n                        id=\"ekit-popup-modal-toggler\"\n                    >\n                                                    <div class='ekit-popup-btn__has-icon'>\n                                                                1. Descargar la nueva app Emma aqui\n                                                            <\/div>\n                                            <\/button>\n                <\/div>\n            \n            <!-- Modal -->\n            <div \n                class=\"ekit-popup-modal ekit-popup-modal__inside middle center\" \n                data-toggleafter=\"0\"\n                data-toggletype=\"button\"\n                data-cookieconsent=\"\"\n            >\n                                <div\n                    class=\"ekit-popup-modal__content ekit-popup__content animated animated-normal\" \n                    style=\"\"\n                    data-animation=\"fade-in-up\"\n                >\n                                            <div class=\"ekit-popup-modal__close popup-top-right\">\n                            <i aria-hidden=\"true\" class=\"icon icon-cross\"><\/i>                        <\/div>\n                    \n                    <!-- Start Header -->\n                                            <div class=\"ekit-popup-modal__header ekit-popup__header \">\n                            <h4 class=\"ekit-popup-modal__title ekit-popup__title\">\n                                                            <\/h4>\n                                                    <\/div>\n                                        <!-- End Header -->\n\n                    <!-- Start Body -->\n                    <div class=\"ekit-popup-modal__body ekit-popup__body\">\n                        \n\t\t<div class=\"widgetarea_warper widgetarea_warper_editable\" data-elementskit-widgetarea-key=\"popup\"  data-elementskit-widgetarea-index=\"a68a225\">\n\t\t\t<div class=\"widgetarea_warper_edit\" data-elementskit-widgetarea-key=\"popup\" data-elementskit-widgetarea-index=\"a68a225\">\n\t\t\t\t<i class=\"eicon-edit\" aria-hidden=\"true\"><\/i>\n\t\t\t\t<span>Edit Content<\/span>\n\t\t\t<\/div>\n\n\t\t\t\t\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"2649\" class=\"elementor elementor-2649\" data-elementor-post-type=\"elementskit_content\">\n\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7f0c1875 e-con-full e-flex e-con e-parent\" data-id=\"7f0c1875\" data-element_type=\"container\" data-settings=\"{&quot;content_width&quot;:&quot;full&quot;,&quot;background_background&quot;:&quot;classic&quot;,&quot;container_type&quot;:&quot;flex&quot;}\" data-e-bg-lazyload=\"\" data-core-v316-plus=\"true\">\n\t\t<div class=\"elementor-element elementor-element-3aa47506 e-flex e-con-boxed e-con e-parent\" data-id=\"3aa47506\" data-element_type=\"container\" data-settings=\"{&quot;container_type&quot;:&quot;flex&quot;,&quot;content_width&quot;:&quot;boxed&quot;}\" data-core-v316-plus=\"true\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-53293551 elementor-widget elementor-widget-heading\" data-id=\"53293551\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Descarg\u00e1 <span class=\"title-strong\">la <span class=\"title-gr\">re<\/span>voluci\u00f3n<\/span><\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-677cd99e elementor-widget elementor-widget-heading\" data-id=\"677cd99e\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">del cr\u00e9dito inmediato<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-308b7020 e-con-full e-flex e-con e-parent\" data-id=\"308b7020\" data-element_type=\"container\" data-settings=\"{&quot;content_width&quot;:&quot;full&quot;,&quot;container_type&quot;:&quot;flex&quot;}\" data-core-v316-plus=\"true\">\n\t\t<div class=\"elementor-element elementor-element-31b264bf e-con-full e-flex e-con e-parent\" data-id=\"31b264bf\" data-element_type=\"container\" data-settings=\"{&quot;content_width&quot;:&quot;full&quot;,&quot;container_type&quot;:&quot;flex&quot;}\" data-core-v316-plus=\"true\">\n\t\t\t\t<div class=\"elementor-element elementor-element-5a121217 elementor-widget elementor-widget-heading\" data-id=\"5a121217\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Una app m\u00e1s f\u00e1cil,<br \/>r\u00e1pida y segura<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<a class=\"elementor-element elementor-element-388006e4 e-con-full e-flex e-con e-parent\" data-id=\"388006e4\" data-element_type=\"container\" data-settings=\"{&quot;content_width&quot;:&quot;full&quot;,&quot;container_type&quot;:&quot;flex&quot;}\" data-core-v316-plus=\"true\" href=\"https:\/\/play.google.com\/store\/apps\/details?id=com.yellowpepper.unicomer.unipay.prod&#038;hl=es\" target=\"_blank\">\n\t\t\t\t<div class=\"elementor-element elementor-element-3cabf0e2 elementor-widget elementor-widget-image\" data-id=\"3cabf0e2\" data-element_type=\"widget\" id=\"androidImage\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<style>\/*! elementor - v3.17.0 - 25-10-2023 *\/\n.elementor-widget-image{text-align:center}.elementor-widget-image a{display:inline-block}.elementor-widget-image a img[src$=\".svg\"]{width:48px}.elementor-widget-image img{vertical-align:middle;display:inline-block}<\/style>\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"198\" height=\"56\" src=\"https:\/\/emmapay.com\/costa-rica\/wp-content\/uploads\/sites\/8\/2023\/09\/GooglePlay-az.svg\" class=\"attachment-large size-large wp-image-112\" alt=\"Descarg\u00e1 Emma en Google Play\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/a>\n\t\t<a class=\"elementor-element elementor-element-7e015f1d e-con-full e-flex e-con e-parent\" data-id=\"7e015f1d\" data-element_type=\"container\" data-settings=\"{&quot;content_width&quot;:&quot;full&quot;,&quot;container_type&quot;:&quot;flex&quot;}\" data-core-v316-plus=\"true\" href=\"https:\/\/apps.apple.com\/cr\/app\/emma-pay\/id1455374257\" target=\"_blank\">\n\t\t\t\t<div class=\"elementor-element elementor-element-32897bdd elementor-widget elementor-widget-image\" data-id=\"32897bdd\" data-element_type=\"widget\" id=\"iosImage\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"198\" height=\"56\" src=\"https:\/\/emmapay.com\/costa-rica\/wp-content\/uploads\/sites\/8\/2023\/09\/AppleStore-az.svg\" class=\"attachment-large size-large wp-image-113\" alt=\"Descarg\u00e1 Emma en la App Store\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-55688b8b e-con-full e-flex e-con e-parent\" data-id=\"55688b8b\" data-element_type=\"container\" data-settings=\"{&quot;content_width&quot;:&quot;full&quot;,&quot;container_type&quot;:&quot;flex&quot;}\" data-core-v316-plus=\"true\">\n\t\t\t\t<div class=\"elementor-element elementor-element-4370d82f elementor-widget elementor-widget-image\" data-id=\"4370d82f\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"418\" height=\"451\" src=\"https:\/\/emmapay.com\/costa-rica\/wp-content\/uploads\/sites\/8\/2023\/09\/EMMA-on-iPhone.png\" class=\"attachment-full size-full wp-image-370\" alt=\"Descarg\u00e1 la revoluci\u00f3n del cr\u00e9dito inmediato\" srcset=\"https:\/\/emmapay.com\/costa-rica\/wp-content\/uploads\/sites\/8\/2023\/09\/EMMA-on-iPhone.png 418w, https:\/\/emmapay.com\/costa-rica\/wp-content\/uploads\/sites\/8\/2023\/09\/EMMA-on-iPhone-278x300.png 278w\" sizes=\"(max-width: 418px) 100vw, 418px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t                    <\/div>\n                    <!-- Emd Body -->\n\n                    <!-- Start Footer -->\n                                            <div class=\"ekit-popup-modal__footer ekit-popup-footer\">\n                            <div \n                                class='ekit-popup-modal__actions'\n                                style=\"\">\n                                                                                            <\/div>\n                        <\/div>\n                                        <!-- End Footer -->\n                <\/div>\n                                    <div class=\"ekit-popup-modal__overlay ekit-popup__close\"><\/div>\n                            <\/div>\n        <!-- End Markup -->\n    <\/div>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-4328a98 e-flex e-con-boxed e-con e-parent\" data-id=\"4328a98\" data-element_type=\"container\" data-settings=\"{&quot;container_type&quot;:&quot;flex&quot;,&quot;content_width&quot;:&quot;boxed&quot;}\" data-core-v316-plus=\"true\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-3f5258d elementor-widget elementor-widget-text-editor\" data-id=\"3f5258d\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ol start=\"2\">\n \t<li>Ingresar con el correo con el que te registraste en la aplicaci\u00f3n anterior<\/li>\n<\/ol>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-58a177d e-flex e-con-boxed e-con e-parent\" data-id=\"58a177d\" data-element_type=\"container\" data-settings=\"{&quot;container_type&quot;:&quot;flex&quot;,&quot;content_width&quot;:&quot;boxed&quot;}\" data-core-v316-plus=\"true\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-da32bf9 elementor-widget elementor-widget-text-editor\" data-id=\"da32bf9\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ol start=\"3\">\n \t<li>Actualizar tu pin<\/li>\n<\/ol>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-22adadc e-flex e-con-boxed e-con e-parent\" data-id=\"22adadc\" data-element_type=\"container\" data-settings=\"{&quot;container_type&quot;:&quot;flex&quot;,&quot;content_width&quot;:&quot;boxed&quot;}\" data-core-v316-plus=\"true\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-2e8c575 elementor-widget elementor-widget-text-editor\" data-id=\"2e8c575\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ol start=\"4\">\n \t<li>\u00a1Listo! Tendr\u00e1s acceso a todas tu informaci\u00f3n: L\u00ednea de cr\u00e9dito disponible, transacciones realizadas, cuotas por pagar, etc.<\/li>\n<\/ol>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t                        <\/div>\n\n                    <\/div>\n\n                <\/div><!-- .elementskit-card END --> \n\n                \n                <div class=\"elementskit-card\">\n                    <div class=\"elementskit-card-header\" id=\"primaryHeading-2-72493113\">\n                        <a href=\"#collapse-f540d4d6a980b39b7e2a\" class=\"elementskit-btn-link collapsed\" data-ekit-toggle=\"collapse\" data-target=\"#Collapse-f540d4d6a980b39b7e2a\" aria-expanded=\"false\" aria-controls=\"Collapse-f540d4d6a980b39b7e2a\">\n                            \n                            <span class=\"ekit-accordion-title\">\u00bfPuedo seguir utilizando la aplicaci\u00f3n anterior?<\/span>\n\n                            \n                                <div class=\"ekit_accordion_icon_group\">\n\n                                    <div class=\"ekit_accordion_normal_icon\">\n                                        <!-- Normal Icon -->\n                                        <i aria-hidden=\"true\" class=\"icon-open icon-left icon icon-down-arrow1\"><\/i>                                    <\/div>\n\n                                    <div class=\"ekit_accordion_active_icon\">\n                                    <!-- Active Icon -->\n                                    <i aria-hidden=\"true\" class=\"icon-closed icon-left icon icon-up-arrow1\"><\/i>                                    <\/div>\n                                <\/div>\n\n                            \n                                                    <\/a>\n                    <\/div>\n\n                    <div id=\"Collapse-f540d4d6a980b39b7e2a\" class=\" collapse\" aria-labelledby=\"primaryHeading-2-72493113\" data-parent=\"#accordion-6a980b39b7e2a\">\n                      \n                        <div class=\"elementskit-card-body\">\n                            \n\t\t<div class=\"widgetarea_warper widgetarea_warper_editable\" data-elementskit-widgetarea-key=\"72493113\"  data-elementskit-widgetarea-index=\"f540d4d\">\n\t\t\t<div class=\"widgetarea_warper_edit\" data-elementskit-widgetarea-key=\"72493113\" data-elementskit-widgetarea-index=\"f540d4d\">\n\t\t\t\t<i class=\"eicon-edit\" aria-hidden=\"true\"><\/i>\n\t\t\t\t<span>Edit Content<\/span>\n\t\t\t<\/div>\n\n\t\t\t\t\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"2674\" class=\"elementor elementor-2674\" data-elementor-post-type=\"elementskit_content\">\n\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5c570c3d faq-answer-desktop e-flex e-con-boxed e-con e-parent\" data-id=\"5c570c3d\" data-element_type=\"container\" data-settings=\"{&quot;container_type&quot;:&quot;flex&quot;,&quot;content_width&quot;:&quot;boxed&quot;}\" data-core-v316-plus=\"true\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-d3d83b4 e-con-full e-flex e-con e-parent\" data-id=\"d3d83b4\" data-element_type=\"container\" data-settings=\"{&quot;content_width&quot;:&quot;full&quot;,&quot;container_type&quot;:&quot;flex&quot;}\" data-core-v316-plus=\"true\">\n\t\t\t\t<div class=\"elementor-element elementor-element-1e2dc58a elementor-widget elementor-widget-text-editor\" data-id=\"1e2dc58a\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>No. A partir del 04\/09\/2022, la versi\u00f3n anterior quedar\u00e1 desactivada.<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-12f3c8a e-con-full e-flex e-con e-parent\" data-id=\"12f3c8a\" data-element_type=\"container\" data-settings=\"{&quot;content_width&quot;:&quot;full&quot;,&quot;container_type&quot;:&quot;flex&quot;}\" data-core-v316-plus=\"true\">\n\t\t<div class=\"elementor-element elementor-element-012c2ac e-con-full e-flex e-con e-parent\" data-id=\"012c2ac\" data-element_type=\"container\" data-settings=\"{&quot;content_width&quot;:&quot;full&quot;,&quot;container_type&quot;:&quot;flex&quot;}\" data-core-v316-plus=\"true\">\n\t\t\t\t<div class=\"elementor-element elementor-element-2815b16 elementor-widget elementor-widget-elementskit-popup-modal\" data-id=\"2815b16\" data-element_type=\"widget\" id=\"downloadtext-popup2\" data-widget_type=\"elementskit-popup-modal.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<div class=\"ekit-wid-con\" >        <!-- Start Markup -->\n                            <div class='ekit-popup-modal__toggler-wrapper'>\n                    <!-- Button trigger modal -->\n                    <button \n                        type=\"button\" \n                        class=\"elementskit-btn ekit-popup-btn ekit-popup-btn__filled ekit-popup__toggler ekit-popup-modal-toggler whitespace--normal\" \n                        data-toggle=\"modal\" \n                        data-target=\"#ekit-popup-modal\"\n                        id=\"ekit-popup-modal-toggler\"\n                    >\n                                                    <div class='ekit-popup-btn__has-icon'>\n                                                                Descarga la nueva aplicaci\u00f3n aqu\u00ed y sumate a la revoluci\u00f3n del cr\u00e9dito inmediato.\n                                                            <\/div>\n                                            <\/button>\n                <\/div>\n            \n            <!-- Modal -->\n            <div \n                class=\"ekit-popup-modal ekit-popup-modal__inside middle center\" \n                data-toggleafter=\"0\"\n                data-toggletype=\"button\"\n                data-cookieconsent=\"\"\n            >\n                                <div\n                    class=\"ekit-popup-modal__content ekit-popup__content animated animated-normal\" \n                    style=\"\"\n                    data-animation=\"fade-in-up\"\n                >\n                                            <div class=\"ekit-popup-modal__close popup-top-right\">\n                            <i aria-hidden=\"true\" class=\"icon icon-cross\"><\/i>                        <\/div>\n                    \n                    <!-- Start Header -->\n                                        <!-- End Header -->\n\n                    <!-- Start Body -->\n                    <div class=\"ekit-popup-modal__body ekit-popup__body\">\n                        \n\t\t<div class=\"widgetarea_warper widgetarea_warper_editable\" data-elementskit-widgetarea-key=\"popup\"  data-elementskit-widgetarea-index=\"2815b16\">\n\t\t\t<div class=\"widgetarea_warper_edit\" data-elementskit-widgetarea-key=\"popup\" data-elementskit-widgetarea-index=\"2815b16\">\n\t\t\t\t<i class=\"eicon-edit\" aria-hidden=\"true\"><\/i>\n\t\t\t\t<span>Edit Content<\/span>\n\t\t\t<\/div>\n\n\t\t\t\t\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"2676\" class=\"elementor elementor-2676\" data-elementor-post-type=\"elementskit_content\">\n\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2103c1db e-con-full e-flex e-con e-parent\" data-id=\"2103c1db\" data-element_type=\"container\" data-settings=\"{&quot;content_width&quot;:&quot;full&quot;,&quot;background_background&quot;:&quot;classic&quot;,&quot;container_type&quot;:&quot;flex&quot;}\" data-e-bg-lazyload=\"\" data-core-v316-plus=\"true\">\n\t\t<div class=\"elementor-element elementor-element-60963e3b e-flex e-con-boxed e-con e-parent\" data-id=\"60963e3b\" data-element_type=\"container\" data-settings=\"{&quot;container_type&quot;:&quot;flex&quot;,&quot;content_width&quot;:&quot;boxed&quot;}\" data-core-v316-plus=\"true\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-3fcb236 elementor-widget elementor-widget-heading\" data-id=\"3fcb236\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Descarg\u00e1 <span class=\"title-strong\">la <span class=\"title-gr\">re<\/span>voluci\u00f3n<\/span><\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-26d1e38 elementor-widget elementor-widget-heading\" data-id=\"26d1e38\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">del cr\u00e9dito inmediato<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-53ade78f e-con-full e-flex e-con e-parent\" data-id=\"53ade78f\" data-element_type=\"container\" data-settings=\"{&quot;content_width&quot;:&quot;full&quot;,&quot;container_type&quot;:&quot;flex&quot;}\" data-core-v316-plus=\"true\">\n\t\t<div class=\"elementor-element elementor-element-4c92dad4 e-con-full e-flex e-con e-parent\" data-id=\"4c92dad4\" data-element_type=\"container\" data-settings=\"{&quot;content_width&quot;:&quot;full&quot;,&quot;container_type&quot;:&quot;flex&quot;}\" data-core-v316-plus=\"true\">\n\t\t\t\t<div class=\"elementor-element elementor-element-4e0442d2 elementor-widget elementor-widget-heading\" data-id=\"4e0442d2\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Una app m\u00e1s f\u00e1cil,<br \/>r\u00e1pida y segura<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<a class=\"elementor-element elementor-element-1f952b34 e-con-full e-flex e-con e-parent\" data-id=\"1f952b34\" data-element_type=\"container\" id=\"popup-google\" data-settings=\"{&quot;content_width&quot;:&quot;full&quot;,&quot;container_type&quot;:&quot;flex&quot;}\" data-core-v316-plus=\"true\" href=\"https:\/\/play.google.com\/store\/apps\/details?id=com.yellowpepper.unicomer.unipay.prod&#038;hl=es\" target=\"_blank\">\n\t\t\t\t<div class=\"elementor-element elementor-element-43de1a0b elementor-widget elementor-widget-image\" data-id=\"43de1a0b\" data-element_type=\"widget\" id=\"androidImage\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"198\" height=\"56\" src=\"https:\/\/emmapay.com\/costa-rica\/wp-content\/uploads\/sites\/8\/2023\/09\/GooglePlay-az.svg\" class=\"attachment-large size-large wp-image-112\" alt=\"Descarg\u00e1 Emma en Google Play\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/a>\n\t\t<a class=\"elementor-element elementor-element-48c4774c e-con-full e-flex e-con e-parent\" data-id=\"48c4774c\" data-element_type=\"container\" id=\"popup-apple\" data-settings=\"{&quot;content_width&quot;:&quot;full&quot;,&quot;container_type&quot;:&quot;flex&quot;}\" data-core-v316-plus=\"true\" href=\"https:\/\/apps.apple.com\/cr\/app\/emma-pay\/id1455374257\" target=\"_blank\">\n\t\t\t\t<div class=\"elementor-element elementor-element-77bba68c elementor-widget elementor-widget-image\" data-id=\"77bba68c\" data-element_type=\"widget\" id=\"iosImage\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"198\" height=\"56\" src=\"https:\/\/emmapay.com\/costa-rica\/wp-content\/uploads\/sites\/8\/2023\/09\/AppleStore-az.svg\" class=\"attachment-large size-large wp-image-113\" alt=\"Descarg\u00e1 Emma en la App Store\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-203eaaf5 e-con-full e-flex e-con e-parent\" data-id=\"203eaaf5\" data-element_type=\"container\" data-settings=\"{&quot;content_width&quot;:&quot;full&quot;,&quot;container_type&quot;:&quot;flex&quot;}\" data-core-v316-plus=\"true\">\n\t\t\t\t<div class=\"elementor-element elementor-element-208c7d25 elementor-widget elementor-widget-image\" data-id=\"208c7d25\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"418\" height=\"451\" src=\"https:\/\/emmapay.com\/costa-rica\/wp-content\/uploads\/sites\/8\/2023\/09\/EMMA-on-iPhone.png\" class=\"attachment-full size-full wp-image-370\" alt=\"Descarg\u00e1 la revoluci\u00f3n del cr\u00e9dito inmediato\" srcset=\"https:\/\/emmapay.com\/costa-rica\/wp-content\/uploads\/sites\/8\/2023\/09\/EMMA-on-iPhone.png 418w, https:\/\/emmapay.com\/costa-rica\/wp-content\/uploads\/sites\/8\/2023\/09\/EMMA-on-iPhone-278x300.png 278w\" sizes=\"(max-width: 418px) 100vw, 418px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t                    <\/div>\n                    <!-- Emd Body -->\n\n                    <!-- Start Footer -->\n                                        <!-- End Footer -->\n                <\/div>\n                                    <div class=\"ekit-popup-modal__overlay ekit-popup__close\"><\/div>\n                            <\/div>\n        <!-- End Markup -->\n    <\/div>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-192f50c e-con-full e-flex e-con e-parent\" data-id=\"192f50c\" data-element_type=\"container\" data-settings=\"{&quot;content_width&quot;:&quot;full&quot;,&quot;container_type&quot;:&quot;flex&quot;}\" data-core-v316-plus=\"true\">\n\t\t\t\t<div class=\"elementor-element elementor-element-56ce050 elementor-widget elementor-widget-elementskit-popup-modal\" data-id=\"56ce050\" data-element_type=\"widget\" id=\"downloadicon-popup2\" data-widget_type=\"elementskit-popup-modal.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<div class=\"ekit-wid-con\" >        <!-- Start Markup -->\n                            <div class='ekit-popup-modal__toggler-wrapper'><img loading=\"lazy\" decoding=\"async\" width=\"44\" height=\"44\" src=\"https:\/\/emmapay.com\/costa-rica\/wp-content\/uploads\/sites\/8\/2023\/09\/cheveron-right-blue.svg\" class=\"attachment-full size-full wp-image-1530\" alt=\"\" \/><\/div>\n            \n            <!-- Modal -->\n            <div \n                class=\"ekit-popup-modal ekit-popup-modal__inside middle center\" \n                data-toggleafter=\"0\"\n                data-toggletype=\"image\"\n                data-cookieconsent=\"\"\n            >\n                                <div\n                    class=\"ekit-popup-modal__content ekit-popup__content animated animated-normal\" \n                    style=\"\"\n                    data-animation=\"fade-in-up\"\n                >\n                                            <div class=\"ekit-popup-modal__close popup-top-right\">\n                            <i aria-hidden=\"true\" class=\"icon icon-cross\"><\/i>                        <\/div>\n                    \n                    <!-- Start Header -->\n                                        <!-- End Header -->\n\n                    <!-- Start Body -->\n                    <div class=\"ekit-popup-modal__body ekit-popup__body\">\n                        \n\t\t<div class=\"widgetarea_warper widgetarea_warper_editable\" data-elementskit-widgetarea-key=\"popup\"  data-elementskit-widgetarea-index=\"56ce050\">\n\t\t\t<div class=\"widgetarea_warper_edit\" data-elementskit-widgetarea-key=\"popup\" data-elementskit-widgetarea-index=\"56ce050\">\n\t\t\t\t<i class=\"eicon-edit\" aria-hidden=\"true\"><\/i>\n\t\t\t\t<span>Edit Content<\/span>\n\t\t\t<\/div>\n\n\t\t\t\t\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"2684\" class=\"elementor elementor-2684\" data-elementor-post-type=\"elementskit_content\">\n\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-546d3662 e-con-full e-flex e-con e-parent\" data-id=\"546d3662\" data-element_type=\"container\" data-settings=\"{&quot;content_width&quot;:&quot;full&quot;,&quot;background_background&quot;:&quot;classic&quot;,&quot;container_type&quot;:&quot;flex&quot;}\" data-e-bg-lazyload=\"\" data-core-v316-plus=\"true\">\n\t\t<div class=\"elementor-element elementor-element-5b613f98 e-flex e-con-boxed e-con e-parent\" data-id=\"5b613f98\" data-element_type=\"container\" data-settings=\"{&quot;container_type&quot;:&quot;flex&quot;,&quot;content_width&quot;:&quot;boxed&quot;}\" data-core-v316-plus=\"true\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-26e9d92b elementor-widget elementor-widget-heading\" data-id=\"26e9d92b\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Descarg\u00e1 <span class=\"title-strong\">la <span class=\"title-gr\">re<\/span>voluci\u00f3n<\/span><\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1c4efaf6 elementor-widget elementor-widget-heading\" data-id=\"1c4efaf6\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">del cr\u00e9dito inmediato<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-1dca678 e-con-full e-flex e-con e-parent\" data-id=\"1dca678\" data-element_type=\"container\" data-settings=\"{&quot;content_width&quot;:&quot;full&quot;,&quot;container_type&quot;:&quot;flex&quot;}\" data-core-v316-plus=\"true\">\n\t\t<div class=\"elementor-element elementor-element-50e80280 e-con-full e-flex e-con e-parent\" data-id=\"50e80280\" data-element_type=\"container\" data-settings=\"{&quot;content_width&quot;:&quot;full&quot;,&quot;container_type&quot;:&quot;flex&quot;}\" data-core-v316-plus=\"true\">\n\t\t\t\t<div class=\"elementor-element elementor-element-74ac03c9 elementor-widget elementor-widget-heading\" data-id=\"74ac03c9\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Una app m\u00e1s f\u00e1cil,<br \/>r\u00e1pida y segura<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<a class=\"elementor-element elementor-element-34922b82 e-con-full e-flex e-con e-parent\" data-id=\"34922b82\" data-element_type=\"container\" data-settings=\"{&quot;content_width&quot;:&quot;full&quot;,&quot;container_type&quot;:&quot;flex&quot;}\" data-core-v316-plus=\"true\" href=\"https:\/\/play.google.com\/store\/apps\/details?id=com.yellowpepper.unicomer.unipay.prod&#038;hl=es\" target=\"_blank\">\n\t\t\t\t<div class=\"elementor-element elementor-element-619edf4e elementor-widget elementor-widget-image\" data-id=\"619edf4e\" data-element_type=\"widget\" id=\"androidImage\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"198\" height=\"56\" src=\"https:\/\/emmapay.com\/costa-rica\/wp-content\/uploads\/sites\/8\/2023\/09\/GooglePlay-az.svg\" class=\"attachment-large size-large wp-image-112\" alt=\"Descarg\u00e1 Emma en Google Play\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/a>\n\t\t<a class=\"elementor-element elementor-element-382f176a e-con-full e-flex e-con e-parent\" data-id=\"382f176a\" data-element_type=\"container\" data-settings=\"{&quot;content_width&quot;:&quot;full&quot;,&quot;container_type&quot;:&quot;flex&quot;}\" data-core-v316-plus=\"true\" href=\"https:\/\/apps.apple.com\/cr\/app\/emma-pay\/id1455374257\" target=\"_blank\">\n\t\t\t\t<div class=\"elementor-element elementor-element-92023d7 elementor-widget elementor-widget-image\" data-id=\"92023d7\" data-element_type=\"widget\" id=\"iosImage\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"198\" height=\"56\" src=\"https:\/\/emmapay.com\/costa-rica\/wp-content\/uploads\/sites\/8\/2023\/09\/AppleStore-az.svg\" class=\"attachment-large size-large wp-image-113\" alt=\"Descarg\u00e1 Emma en la App Store\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-36a5c228 e-con-full e-flex e-con e-parent\" data-id=\"36a5c228\" data-element_type=\"container\" data-settings=\"{&quot;content_width&quot;:&quot;full&quot;,&quot;container_type&quot;:&quot;flex&quot;}\" data-core-v316-plus=\"true\">\n\t\t\t\t<div class=\"elementor-element elementor-element-13c52514 elementor-widget elementor-widget-image\" data-id=\"13c52514\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"418\" height=\"451\" src=\"https:\/\/emmapay.com\/costa-rica\/wp-content\/uploads\/sites\/8\/2023\/09\/EMMA-on-iPhone.png\" class=\"attachment-full size-full wp-image-370\" alt=\"Descarg\u00e1 la revoluci\u00f3n del cr\u00e9dito inmediato\" srcset=\"https:\/\/emmapay.com\/costa-rica\/wp-content\/uploads\/sites\/8\/2023\/09\/EMMA-on-iPhone.png 418w, https:\/\/emmapay.com\/costa-rica\/wp-content\/uploads\/sites\/8\/2023\/09\/EMMA-on-iPhone-278x300.png 278w\" sizes=\"(max-width: 418px) 100vw, 418px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t                    <\/div>\n                    <!-- Emd Body -->\n\n                    <!-- Start Footer -->\n                                        <!-- End Footer -->\n                <\/div>\n                                    <div class=\"ekit-popup-modal__overlay ekit-popup__close\"><\/div>\n                            <\/div>\n        <!-- End Markup -->\n    <\/div>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t                        <\/div>\n\n                    <\/div>\n\n                <\/div><!-- .elementskit-card END --> \n\n                \n                <div class=\"elementskit-card\">\n                    <div class=\"elementskit-card-header\" id=\"primaryHeading-3-72493113\">\n                        <a href=\"#collapse-f2092806a980b39b7e2a\" class=\"elementskit-btn-link collapsed\" data-ekit-toggle=\"collapse\" data-target=\"#Collapse-f2092806a980b39b7e2a\" aria-expanded=\"false\" aria-controls=\"Collapse-f2092806a980b39b7e2a\">\n                            \n                            <span class=\"ekit-accordion-title\">\u00bfLa nueva aplicaci\u00f3n es segura?<\/span>\n\n                            \n                                <div class=\"ekit_accordion_icon_group\">\n\n                                    <div class=\"ekit_accordion_normal_icon\">\n                                        <!-- Normal Icon -->\n                                        <i aria-hidden=\"true\" class=\"icon-open icon-left icon icon-down-arrow1\"><\/i>                                    <\/div>\n\n                                    <div class=\"ekit_accordion_active_icon\">\n                                    <!-- Active Icon -->\n                                    <i aria-hidden=\"true\" class=\"icon-closed icon-left icon icon-up-arrow1\"><\/i>                                    <\/div>\n                                <\/div>\n\n                            \n                                                    <\/a>\n                    <\/div>\n\n                    <div id=\"Collapse-f2092806a980b39b7e2a\" class=\" collapse\" aria-labelledby=\"primaryHeading-3-72493113\" data-parent=\"#accordion-6a980b39b7e2a\">\n                      \n                        <div class=\"elementskit-card-body\">\n                            \n\t\t<div class=\"widgetarea_warper widgetarea_warper_editable\" data-elementskit-widgetarea-key=\"72493113\"  data-elementskit-widgetarea-index=\"f209280\">\n\t\t\t<div class=\"widgetarea_warper_edit\" data-elementskit-widgetarea-key=\"72493113\" data-elementskit-widgetarea-index=\"f209280\">\n\t\t\t\t<i class=\"eicon-edit\" aria-hidden=\"true\"><\/i>\n\t\t\t\t<span>Edit Content<\/span>\n\t\t\t<\/div>\n\n\t\t\t\t\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"2700\" class=\"elementor elementor-2700\" data-elementor-post-type=\"elementskit_content\">\n\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1b950185 faq-answer-desktop e-flex e-con-boxed e-con e-parent\" data-id=\"1b950185\" data-element_type=\"container\" data-settings=\"{&quot;container_type&quot;:&quot;flex&quot;,&quot;content_width&quot;:&quot;boxed&quot;}\" data-core-v316-plus=\"true\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-de70ed0 elementor-widget elementor-widget-text-editor\" data-id=\"de70ed0\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>La nueva aplicaci\u00f3n es re-segura. Contamos con diferentes mecanismos de validaci\u00f3n de identidad como reconocimiento facial y validaciones v\u00eda Token para confirmar las transacciones a realizar.<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t                        <\/div>\n\n                    <\/div>\n\n                <\/div><!-- .elementskit-card END --> \n\n                        <\/div>\n    <\/div>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t                        <\/div>\n                    <\/div>\n                                    <div class=\"tab-pane elementkit-tab-pane elementor-repeater-item-8f344c9 \" id=\"content-8f344c96a980b399e48a\" role=\"tabpanel\"\n                         aria-labelledby=\"content-8f344c96a980b399e48a-tab\">\n                        <div class=\"animated fadeIn\">\n                            \n\t\t<div class=\"widgetarea_warper widgetarea_warper_editable\" data-elementskit-widgetarea-key=\"2cdd4ce9\"  data-elementskit-widgetarea-index=\"8f344c9\">\n\t\t\t<div class=\"widgetarea_warper_edit\" data-elementskit-widgetarea-key=\"2cdd4ce9\" data-elementskit-widgetarea-index=\"8f344c9\">\n\t\t\t\t<i class=\"eicon-edit\" aria-hidden=\"true\"><\/i>\n\t\t\t\t<span>Edit Content<\/span>\n\t\t\t<\/div>\n\n\t\t\t\t\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"2533\" class=\"elementor elementor-2533\" data-elementor-post-type=\"elementskit_content\">\n\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1bce378d e-con-full e-flex e-con e-parent\" data-id=\"1bce378d\" data-element_type=\"container\" data-settings=\"{&quot;content_width&quot;:&quot;full&quot;,&quot;container_type&quot;:&quot;flex&quot;}\" data-core-v316-plus=\"true\">\n\t\t\t\t<div class=\"elementor-element elementor-element-a9c38ad elementor-widget elementor-widget-elementskit-advance-accordion\" data-id=\"a9c38ad\" data-element_type=\"widget\" data-widget_type=\"elementskit-advance-accordion.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<div class=\"ekit-wid-con\">\n\n        <div class=\"elementskit-accordion accoedion-primary\" id=\"accordion-6a980b39e9cc3\">\n\n            \n                <div class=\"elementskit-card\">\n                    <div class=\"elementskit-card-header\" id=\"primaryHeading-0-a9c38ad\">\n                        <a href=\"#collapse-9ac97566a980b39e9cc3\" class=\"elementskit-btn-link collapsed\" data-ekit-toggle=\"collapse\" data-target=\"#Collapse-9ac97566a980b39e9cc3\" aria-expanded=\"false\" aria-controls=\"Collapse-9ac97566a980b39e9cc3\">\n                            \n                            <span class=\"ekit-accordion-title\">\u00bfC\u00f3mo descargar Emma?<\/span>\n\n                            \n                                <div class=\"ekit_accordion_icon_group\">\n\n                                    <div class=\"ekit_accordion_normal_icon\">\n                                        <!-- Normal Icon -->\n                                        <i aria-hidden=\"true\" class=\"icon-open icon-left icon icon-down-arrow1\"><\/i>                                    <\/div>\n\n                                    <div class=\"ekit_accordion_active_icon\">\n                                    <!-- Active Icon -->\n                                    <i aria-hidden=\"true\" class=\"icon-closed icon-left icon icon-up-arrow1\"><\/i>                                    <\/div>\n                                <\/div>\n\n                            \n                                                    <\/a>\n                    <\/div>\n\n                    <div id=\"Collapse-9ac97566a980b39e9cc3\" class=\" collapse\" aria-labelledby=\"primaryHeading-0-a9c38ad\" data-parent=\"#accordion-6a980b39e9cc3\">\n                      \n                        <div class=\"elementskit-card-body\">\n                            \n\t\t<div class=\"widgetarea_warper widgetarea_warper_editable\" data-elementskit-widgetarea-key=\"a9c38ad\"  data-elementskit-widgetarea-index=\"9ac9756\">\n\t\t\t<div class=\"widgetarea_warper_edit\" data-elementskit-widgetarea-key=\"a9c38ad\" data-elementskit-widgetarea-index=\"9ac9756\">\n\t\t\t\t<i class=\"eicon-edit\" aria-hidden=\"true\"><\/i>\n\t\t\t\t<span>Edit Content<\/span>\n\t\t\t<\/div>\n\n\t\t\t\t\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"2707\" class=\"elementor elementor-2707\" data-elementor-post-type=\"elementskit_content\">\n\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5c38575 faq-answer-desktop e-flex e-con-boxed e-con e-parent\" data-id=\"5c38575\" data-element_type=\"container\" data-settings=\"{&quot;container_type&quot;:&quot;flex&quot;,&quot;content_width&quot;:&quot;boxed&quot;}\" data-core-v316-plus=\"true\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-62de7800 elementor-widget elementor-widget-text-editor\" data-id=\"62de7800\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>Pod\u00e9s descarga Emma desde Play Store y APP Store. Buscala con el nombre: Emmapay<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t                        <\/div>\n\n                    <\/div>\n\n                <\/div><!-- .elementskit-card END --> \n\n                \n                <div class=\"elementskit-card\">\n                    <div class=\"elementskit-card-header\" id=\"primaryHeading-1-a9c38ad\">\n                        <a href=\"#collapse-03f71806a980b39e9cc3\" class=\"elementskit-btn-link collapsed\" data-ekit-toggle=\"collapse\" data-target=\"#Collapse-03f71806a980b39e9cc3\" aria-expanded=\"false\" aria-controls=\"Collapse-03f71806a980b39e9cc3\">\n                            \n                            <span class=\"ekit-accordion-title\">\u00bfQue es el PIN de acceso y c\u00f3mo debo crearlo?<\/span>\n\n                            \n                                <div class=\"ekit_accordion_icon_group\">\n\n                                    <div class=\"ekit_accordion_normal_icon\">\n                                        <!-- Normal Icon -->\n                                        <i aria-hidden=\"true\" class=\"icon-open icon-left icon icon-down-arrow1\"><\/i>                                    <\/div>\n\n                                    <div class=\"ekit_accordion_active_icon\">\n                                    <!-- Active Icon -->\n                                    <i aria-hidden=\"true\" class=\"icon-closed icon-left icon icon-up-arrow1\"><\/i>                                    <\/div>\n                                <\/div>\n\n                            \n                                                    <\/a>\n                    <\/div>\n\n                    <div id=\"Collapse-03f71806a980b39e9cc3\" class=\" collapse\" aria-labelledby=\"primaryHeading-1-a9c38ad\" data-parent=\"#accordion-6a980b39e9cc3\">\n                      \n                        <div class=\"elementskit-card-body\">\n                            \n\t\t<div class=\"widgetarea_warper widgetarea_warper_editable\" data-elementskit-widgetarea-key=\"a9c38ad\"  data-elementskit-widgetarea-index=\"03f7180\">\n\t\t\t<div class=\"widgetarea_warper_edit\" data-elementskit-widgetarea-key=\"a9c38ad\" data-elementskit-widgetarea-index=\"03f7180\">\n\t\t\t\t<i class=\"eicon-edit\" aria-hidden=\"true\"><\/i>\n\t\t\t\t<span>Edit Content<\/span>\n\t\t\t<\/div>\n\n\t\t\t\t\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"2711\" class=\"elementor elementor-2711\" data-elementor-post-type=\"elementskit_content\">\n\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4ba37f7d faq-answer-desktop e-flex e-con-boxed e-con e-parent\" data-id=\"4ba37f7d\" data-element_type=\"container\" data-settings=\"{&quot;container_type&quot;:&quot;flex&quot;,&quot;content_width&quot;:&quot;boxed&quot;}\" data-core-v316-plus=\"true\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-73bb1720 elementor-widget elementor-widget-text-editor\" data-id=\"73bb1720\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>El PIN es la contrase\u00f1a de tu cuenta Emma. Debe de ser creado por el cliente, el mismo no puede tener n\u00fameros consecutivos ni repetidos. Recomendamos no compartir tu PIN por motivos de seguridad.<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t                        <\/div>\n\n                    <\/div>\n\n                <\/div><!-- .elementskit-card END --> \n\n                \n                <div class=\"elementskit-card\">\n                    <div class=\"elementskit-card-header\" id=\"primaryHeading-2-a9c38ad\">\n                        <a href=\"#collapse-f540d4d6a980b39e9cc3\" class=\"elementskit-btn-link collapsed\" data-ekit-toggle=\"collapse\" data-target=\"#Collapse-f540d4d6a980b39e9cc3\" aria-expanded=\"false\" aria-controls=\"Collapse-f540d4d6a980b39e9cc3\">\n                            \n                            <span class=\"ekit-accordion-title\">Olvid\u00e9 mi PIN, \u00bfC\u00f3mo puedo restaurarlo?<\/span>\n\n                            \n                                <div class=\"ekit_accordion_icon_group\">\n\n                                    <div class=\"ekit_accordion_normal_icon\">\n                                        <!-- Normal Icon -->\n                                        <i aria-hidden=\"true\" class=\"icon-open icon-left icon icon-down-arrow1\"><\/i>                                    <\/div>\n\n                                    <div class=\"ekit_accordion_active_icon\">\n                                    <!-- Active Icon -->\n                                    <i aria-hidden=\"true\" class=\"icon-closed icon-left icon icon-up-arrow1\"><\/i>                                    <\/div>\n                                <\/div>\n\n                            \n                                                    <\/a>\n                    <\/div>\n\n                    <div id=\"Collapse-f540d4d6a980b39e9cc3\" class=\" collapse\" aria-labelledby=\"primaryHeading-2-a9c38ad\" data-parent=\"#accordion-6a980b39e9cc3\">\n                      \n                        <div class=\"elementskit-card-body\">\n                            \n\t\t<div class=\"widgetarea_warper widgetarea_warper_editable\" data-elementskit-widgetarea-key=\"a9c38ad\"  data-elementskit-widgetarea-index=\"f540d4d\">\n\t\t\t<div class=\"widgetarea_warper_edit\" data-elementskit-widgetarea-key=\"a9c38ad\" data-elementskit-widgetarea-index=\"f540d4d\">\n\t\t\t\t<i class=\"eicon-edit\" aria-hidden=\"true\"><\/i>\n\t\t\t\t<span>Edit Content<\/span>\n\t\t\t<\/div>\n\n\t\t\t\t\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"2715\" class=\"elementor elementor-2715\" data-elementor-post-type=\"elementskit_content\">\n\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3a4f4983 faq-answer-desktop e-flex e-con-boxed e-con e-parent\" data-id=\"3a4f4983\" data-element_type=\"container\" data-settings=\"{&quot;container_type&quot;:&quot;flex&quot;,&quot;content_width&quot;:&quot;boxed&quot;}\" data-core-v316-plus=\"true\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-41f9e3e e-flex e-con-boxed e-con e-parent\" data-id=\"41f9e3e\" data-element_type=\"container\" data-settings=\"{&quot;container_type&quot;:&quot;flex&quot;,&quot;content_width&quot;:&quot;boxed&quot;}\" data-core-v316-plus=\"true\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-77fb1c13 elementor-widget elementor-widget-text-editor\" data-id=\"77fb1c13\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>No te preocup\u00e9s, te ayudamos a recuperarlo. Segu\u00ed estos pasos:<\/p><ol><li>Seleccion\u00e1 en la pantalla de Inicio: Olvide mi contrase\u00f1a<\/li><li>Te enviaremos un c\u00f3digo de seguridad que deber\u00e1s ingresar en la app<\/li><li>Crea un nuevo PIN y listo!<\/li><\/ol>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-890a146 e-flex e-con-boxed e-con e-parent\" data-id=\"890a146\" data-element_type=\"container\" data-settings=\"{&quot;container_type&quot;:&quot;flex&quot;,&quot;content_width&quot;:&quot;boxed&quot;}\" data-core-v316-plus=\"true\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-49b4d12 e-con-full e-flex e-con e-parent\" data-id=\"49b4d12\" data-element_type=\"container\" data-settings=\"{&quot;content_width&quot;:&quot;full&quot;,&quot;container_type&quot;:&quot;flex&quot;}\" data-core-v316-plus=\"true\">\n\t\t\t\t<div class=\"elementor-element elementor-element-78428d3 elementor-widget elementor-widget-wptd_video_popup\" data-id=\"78428d3\" data-element_type=\"widget\" id=\"videopopup-text-1\" data-widget_type=\"wptd_video_popup.default\">\n\t\t\t\t\r\n\t\t<div class=\"elementor-widget-container wptd-video-popup-wrapper\">\r\n\t\t\r\n\t\t\t\t\t\t<span class=\"wptd-video-popup-inline-css\" data-css=\"&quot;.wptd-video-popup-78428d3 .mfp-bg { background-color: #010101E6; }.wptd-video-popup-78428d3 .mfp-iframe-holder .mfp-content { max-width: 900px; }&quot;\"><\/span>\r\n\t\t<a class=\"wptd-video-popup-trigger popup-trigger-txt\" href=\"https:\/\/www.youtube.com\/watch?v=aXRXe94E4DI\">Te mostramos el paso a paso aqu\u00ed.<\/a>\t\t\t\r\n\t\t<\/div>\r\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-4c5a267 e-con-full e-flex e-con e-parent\" data-id=\"4c5a267\" data-element_type=\"container\" data-settings=\"{&quot;content_width&quot;:&quot;full&quot;,&quot;container_type&quot;:&quot;flex&quot;}\" data-core-v316-plus=\"true\">\n\t\t\t\t<div class=\"elementor-element elementor-element-36b43ca wptd-video-popup-view-default elementor-widget elementor-widget-wptd_video_popup\" data-id=\"36b43ca\" data-element_type=\"widget\" id=\"videopopup-icon-1\" data-widget_type=\"wptd_video_popup.default\">\n\t\t\t\t\r\n\t\t<div class=\"elementor-widget-container wptd-video-popup-wrapper\">\r\n\t\t\r\n\t\t\t\t\t\t<span class=\"wptd-video-popup-inline-css\" data-css=\"&quot;.wptd-video-popup-36b43ca .mfp-bg { background-color: #010101E6; }.wptd-video-popup-36b43ca .mfp-iframe-holder .mfp-content { max-width: 900px; }&quot;\"><\/span>\r\n\t\t<a class=\"wptd-video-popup-trigger popup-trigger-icon\" href=\"https:\/\/www.youtube.com\/watch?v=aXRXe94E4DI\"><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"44\" height=\"44\" viewBox=\"0 0 44 44\" fill=\"none\"><circle cx=\"22\" cy=\"22\" r=\"22\" fill=\"#171C8F\"><\/circle><path d=\"M19.7049 16L18.2949 17.41L22.8749 22L18.2949 26.59L19.7049 28L25.7049 22L19.7049 16Z\" fill=\"white\"><\/path><\/svg><\/a>\t\t\t\r\n\t\t<\/div>\r\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t                        <\/div>\n\n                    <\/div>\n\n                <\/div><!-- .elementskit-card END --> \n\n                        <\/div>\n    <\/div>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t                        <\/div>\n                    <\/div>\n                                    <div class=\"tab-pane elementkit-tab-pane elementor-repeater-item-9e97dfa \" id=\"content-9e97dfa6a980b399e48a\" role=\"tabpanel\"\n                         aria-labelledby=\"content-9e97dfa6a980b399e48a-tab\">\n                        <div class=\"animated fadeIn\">\n                            \n\t\t<div class=\"widgetarea_warper widgetarea_warper_editable\" data-elementskit-widgetarea-key=\"2cdd4ce9\"  data-elementskit-widgetarea-index=\"9e97dfa\">\n\t\t\t<div class=\"widgetarea_warper_edit\" data-elementskit-widgetarea-key=\"2cdd4ce9\" data-elementskit-widgetarea-index=\"9e97dfa\">\n\t\t\t\t<i class=\"eicon-edit\" aria-hidden=\"true\"><\/i>\n\t\t\t\t<span>Edit Content<\/span>\n\t\t\t<\/div>\n\n\t\t\t\t\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"2541\" class=\"elementor elementor-2541\" data-elementor-post-type=\"elementskit_content\">\n\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3d9d0fd9 e-con-full e-flex e-con e-parent\" data-id=\"3d9d0fd9\" data-element_type=\"container\" data-settings=\"{&quot;content_width&quot;:&quot;full&quot;,&quot;container_type&quot;:&quot;flex&quot;}\" data-core-v316-plus=\"true\">\n\t\t\t\t<div class=\"elementor-element elementor-element-234a60ca elementor-widget elementor-widget-elementskit-advance-accordion\" data-id=\"234a60ca\" data-element_type=\"widget\" data-widget_type=\"elementskit-advance-accordion.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<div class=\"ekit-wid-con\">\n\n        <div class=\"elementskit-accordion accoedion-primary\" id=\"accordion-6a980b3a04247\">\n\n            \n                <div class=\"elementskit-card\">\n                    <div class=\"elementskit-card-header\" id=\"primaryHeading-0-234a60ca\">\n                        <a href=\"#collapse-9ac97566a980b3a04247\" class=\"elementskit-btn-link collapsed\" data-ekit-toggle=\"collapse\" data-target=\"#Collapse-9ac97566a980b3a04247\" aria-expanded=\"false\" aria-controls=\"Collapse-9ac97566a980b3a04247\">\n                            \n                            <span class=\"ekit-accordion-title\">\u00bfC\u00f3mo debo solicitar mi l\u00ednea de cr\u00e9dito?<\/span>\n\n                            \n                                <div class=\"ekit_accordion_icon_group\">\n\n                                    <div class=\"ekit_accordion_normal_icon\">\n                                        <!-- Normal Icon -->\n                                        <i aria-hidden=\"true\" class=\"icon-open icon-left icon icon-down-arrow1\"><\/i>                                    <\/div>\n\n                                    <div class=\"ekit_accordion_active_icon\">\n                                    <!-- Active Icon -->\n                                    <i aria-hidden=\"true\" class=\"icon-closed icon-left icon icon-up-arrow1\"><\/i>                                    <\/div>\n                                <\/div>\n\n                            \n                                                    <\/a>\n                    <\/div>\n\n                    <div id=\"Collapse-9ac97566a980b3a04247\" class=\" collapse\" aria-labelledby=\"primaryHeading-0-234a60ca\" data-parent=\"#accordion-6a980b3a04247\">\n                      \n                        <div class=\"elementskit-card-body\">\n                            \n\t\t<div class=\"widgetarea_warper widgetarea_warper_editable\" data-elementskit-widgetarea-key=\"234a60ca\"  data-elementskit-widgetarea-index=\"9ac9756\">\n\t\t\t<div class=\"widgetarea_warper_edit\" data-elementskit-widgetarea-key=\"234a60ca\" data-elementskit-widgetarea-index=\"9ac9756\">\n\t\t\t\t<i class=\"eicon-edit\" aria-hidden=\"true\"><\/i>\n\t\t\t\t<span>Edit Content<\/span>\n\t\t\t<\/div>\n\n\t\t\t\t\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"2737\" class=\"elementor elementor-2737\" data-elementor-post-type=\"elementskit_content\">\n\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-26d788e7 faq-answer-desktop e-flex e-con-boxed e-con e-parent\" data-id=\"26d788e7\" data-element_type=\"container\" data-settings=\"{&quot;container_type&quot;:&quot;flex&quot;,&quot;content_width&quot;:&quot;boxed&quot;}\" data-core-v316-plus=\"true\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-2eba261f e-flex e-con-boxed e-con e-parent\" data-id=\"2eba261f\" data-element_type=\"container\" data-settings=\"{&quot;container_type&quot;:&quot;flex&quot;,&quot;content_width&quot;:&quot;boxed&quot;}\" data-core-v316-plus=\"true\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-4937676e elementor-widget elementor-widget-text-editor\" data-id=\"4937676e\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>Para solicitar tu cr\u00e9dito Emma deber\u00e1s seguir estos pasos:<\/p><ol><li>Descarg\u00e1 EMMA<\/li><li>Registrate<\/li><li>Validar tu identidad<\/li><li>Responder algunas preguntas de validaci\u00f3n<\/li><li>Firm\u00e1 los documentos digitalmente para activar tu cr\u00e9dito y \u00a1listo!<\/li><\/ol>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-4c120c2d e-flex e-con-boxed e-con e-parent\" data-id=\"4c120c2d\" data-element_type=\"container\" data-settings=\"{&quot;container_type&quot;:&quot;flex&quot;,&quot;content_width&quot;:&quot;boxed&quot;}\" data-core-v316-plus=\"true\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-4b6db6b5 e-con-full e-flex e-con e-parent\" data-id=\"4b6db6b5\" data-element_type=\"container\" data-settings=\"{&quot;content_width&quot;:&quot;full&quot;,&quot;container_type&quot;:&quot;flex&quot;}\" data-core-v316-plus=\"true\">\n\t\t\t\t<div class=\"elementor-element elementor-element-26e9886b elementor-widget elementor-widget-wptd_video_popup\" data-id=\"26e9886b\" data-element_type=\"widget\" id=\"videopopup-text-2\" data-widget_type=\"wptd_video_popup.default\">\n\t\t\t\t\r\n\t\t<div class=\"elementor-widget-container wptd-video-popup-wrapper\">\r\n\t\t\r\n\t\t\t\t\t\t<span class=\"wptd-video-popup-inline-css\" data-css=\"&quot;.wptd-video-popup-26e9886b .mfp-bg { background-color: #010101E6; }.wptd-video-popup-26e9886b .mfp-iframe-holder .mfp-content { max-width: 900px; }&quot;\"><\/span>\r\n\t\t<a class=\"wptd-video-popup-trigger popup-trigger-txt\" href=\"https:\/\/www.youtube.com\/watch?v=gX3AUFV-Z3o\">Conoc\u00e9 el paso a paso a detalle aqu\u00ed.<\/a>\t\t\t\r\n\t\t<\/div>\r\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-510ea24c e-con-full e-flex e-con e-parent\" data-id=\"510ea24c\" data-element_type=\"container\" data-settings=\"{&quot;content_width&quot;:&quot;full&quot;,&quot;container_type&quot;:&quot;flex&quot;}\" data-core-v316-plus=\"true\">\n\t\t\t\t<div class=\"elementor-element elementor-element-d65a287 wptd-video-popup-view-default elementor-widget elementor-widget-wptd_video_popup\" data-id=\"d65a287\" data-element_type=\"widget\" id=\"videopopup-icon-2\" data-widget_type=\"wptd_video_popup.default\">\n\t\t\t\t\r\n\t\t<div class=\"elementor-widget-container wptd-video-popup-wrapper\">\r\n\t\t\r\n\t\t\t\t\t\t<span class=\"wptd-video-popup-inline-css\" data-css=\"&quot;.wptd-video-popup-d65a287 .mfp-bg { background-color: #010101E6; }.wptd-video-popup-d65a287 .mfp-iframe-holder .mfp-content { max-width: 900px; }&quot;\"><\/span>\r\n\t\t<a class=\"wptd-video-popup-trigger popup-trigger-icon\" href=\"https:\/\/www.youtube.com\/watch?v=gX3AUFV-Z3o\"><svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"44\" height=\"44\" viewBox=\"0 0 44 44\" fill=\"none\"><circle cx=\"22\" cy=\"22\" r=\"22\" fill=\"#171C8F\"><\/circle><path d=\"M19.7049 16L18.2949 17.41L22.8749 22L18.2949 26.59L19.7049 28L25.7049 22L19.7049 16Z\" fill=\"white\"><\/path><\/svg><\/a>\t\t\t\r\n\t\t<\/div>\r\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t                        <\/div>\n\n                    <\/div>\n\n                <\/div><!-- .elementskit-card END --> \n\n                \n                <div class=\"elementskit-card\">\n                    <div class=\"elementskit-card-header\" id=\"primaryHeading-1-234a60ca\">\n                        <a href=\"#collapse-03f71806a980b3a04247\" class=\"elementskit-btn-link collapsed\" data-ekit-toggle=\"collapse\" data-target=\"#Collapse-03f71806a980b3a04247\" aria-expanded=\"false\" aria-controls=\"Collapse-03f71806a980b3a04247\">\n                            \n                            <span class=\"ekit-accordion-title\">\u00bfCu\u00e1nto tardan en aprobar el cr\u00e9dito?<\/span>\n\n                            \n                                <div class=\"ekit_accordion_icon_group\">\n\n                                    <div class=\"ekit_accordion_normal_icon\">\n                                        <!-- Normal Icon -->\n                                        <i aria-hidden=\"true\" class=\"icon-open icon-left icon icon-down-arrow1\"><\/i>                                    <\/div>\n\n                                    <div class=\"ekit_accordion_active_icon\">\n                                    <!-- Active Icon -->\n                                    <i aria-hidden=\"true\" class=\"icon-closed icon-left icon icon-up-arrow1\"><\/i>                                    <\/div>\n                                <\/div>\n\n                            \n                                                    <\/a>\n                    <\/div>\n\n                    <div id=\"Collapse-03f71806a980b3a04247\" class=\" collapse\" aria-labelledby=\"primaryHeading-1-234a60ca\" data-parent=\"#accordion-6a980b3a04247\">\n                      \n                        <div class=\"elementskit-card-body\">\n                            \n\t\t<div class=\"widgetarea_warper widgetarea_warper_editable\" data-elementskit-widgetarea-key=\"234a60ca\"  data-elementskit-widgetarea-index=\"03f7180\">\n\t\t\t<div class=\"widgetarea_warper_edit\" data-elementskit-widgetarea-key=\"234a60ca\" data-elementskit-widgetarea-index=\"03f7180\">\n\t\t\t\t<i class=\"eicon-edit\" aria-hidden=\"true\"><\/i>\n\t\t\t\t<span>Edit Content<\/span>\n\t\t\t<\/div>\n\n\t\t\t\t\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"2744\" class=\"elementor elementor-2744\" data-elementor-post-type=\"elementskit_content\">\n\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-73a04c60 faq-answer-desktop e-flex e-con-boxed e-con e-parent\" data-id=\"73a04c60\" data-element_type=\"container\" data-settings=\"{&quot;container_type&quot;:&quot;flex&quot;,&quot;content_width&quot;:&quot;boxed&quot;}\" data-core-v316-plus=\"true\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-4396ba24 elementor-widget elementor-widget-text-editor\" data-id=\"4396ba24\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>La aprobaci\u00f3n de t\u00fa l\u00ednea de cr\u00e9dito estar\u00e1 aprobada en menos de 20 minutos.<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t                        <\/div>\n\n                    <\/div>\n\n                <\/div><!-- .elementskit-card END --> \n\n                \n                <div class=\"elementskit-card\">\n                    <div class=\"elementskit-card-header\" id=\"primaryHeading-2-234a60ca\">\n                        <a href=\"#collapse-f540d4d6a980b3a04247\" class=\"elementskit-btn-link collapsed\" data-ekit-toggle=\"collapse\" data-target=\"#Collapse-f540d4d6a980b3a04247\" aria-expanded=\"false\" aria-controls=\"Collapse-f540d4d6a980b3a04247\">\n                            \n                            <span class=\"ekit-accordion-title\">Aun no me aprueban el cr\u00e9dito, \u00bfa d\u00f3nde puedo llamar para conocer el estado de mi aplicaci\u00f3n?<\/span>\n\n                            \n                                <div class=\"ekit_accordion_icon_group\">\n\n                                    <div class=\"ekit_accordion_normal_icon\">\n                                        <!-- Normal Icon -->\n                                        <i aria-hidden=\"true\" class=\"icon-open icon-left icon icon-down-arrow1\"><\/i>                                    <\/div>\n\n                                    <div class=\"ekit_accordion_active_icon\">\n                                    <!-- Active Icon -->\n                                    <i aria-hidden=\"true\" class=\"icon-closed icon-left icon icon-up-arrow1\"><\/i>                                    <\/div>\n                                <\/div>\n\n                            \n                                                    <\/a>\n                    <\/div>\n\n                    <div id=\"Collapse-f540d4d6a980b3a04247\" class=\" collapse\" aria-labelledby=\"primaryHeading-2-234a60ca\" data-parent=\"#accordion-6a980b3a04247\">\n                      \n                        <div class=\"elementskit-card-body\">\n                            \n\t\t<div class=\"widgetarea_warper widgetarea_warper_editable\" data-elementskit-widgetarea-key=\"234a60ca\"  data-elementskit-widgetarea-index=\"f540d4d\">\n\t\t\t<div class=\"widgetarea_warper_edit\" data-elementskit-widgetarea-key=\"234a60ca\" data-elementskit-widgetarea-index=\"f540d4d\">\n\t\t\t\t<i class=\"eicon-edit\" aria-hidden=\"true\"><\/i>\n\t\t\t\t<span>Edit Content<\/span>\n\t\t\t<\/div>\n\n\t\t\t\t\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"2748\" class=\"elementor elementor-2748\" data-elementor-post-type=\"elementskit_content\">\n\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-de3eed8 faq-answer-desktop e-flex e-con-boxed e-con e-parent\" data-id=\"de3eed8\" data-element_type=\"container\" data-settings=\"{&quot;container_type&quot;:&quot;flex&quot;,&quot;content_width&quot;:&quot;boxed&quot;}\" data-core-v316-plus=\"true\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-1fde355a elementor-widget elementor-widget-text-editor\" data-id=\"1fde355a\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>Contactate con nosotros al n\u00famero <a href=\"tel:800-000-3662\">800-000-3662<\/a> opci\u00f3n 2, o al correo: <a href=\"mailto:servicioalcliente_cr@emmapay.com\">servicioalcliente_cr@emmapay.com<\/a> Revisaremos tu solicitud con el departamento de cr\u00e9dito para conocer el estatus.<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t                        <\/div>\n\n                    <\/div>\n\n                <\/div><!-- .elementskit-card END --> \n\n                        <\/div>\n    <\/div>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t                        <\/div>\n                    <\/div>\n                                    <div class=\"tab-pane elementkit-tab-pane elementor-repeater-item-c89dda1 \" id=\"content-c89dda16a980b399e48a\" role=\"tabpanel\"\n                         aria-labelledby=\"content-c89dda16a980b399e48a-tab\">\n                        <div class=\"animated fadeIn\">\n                            \n\t\t<div class=\"widgetarea_warper widgetarea_warper_editable\" data-elementskit-widgetarea-key=\"2cdd4ce9\"  data-elementskit-widgetarea-index=\"c89dda1\">\n\t\t\t<div class=\"widgetarea_warper_edit\" data-elementskit-widgetarea-key=\"2cdd4ce9\" data-elementskit-widgetarea-index=\"c89dda1\">\n\t\t\t\t<i class=\"eicon-edit\" aria-hidden=\"true\"><\/i>\n\t\t\t\t<span>Edit Content<\/span>\n\t\t\t<\/div>\n\n\t\t\t\t\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"2548\" class=\"elementor elementor-2548\" data-elementor-post-type=\"elementskit_content\">\n\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-58722d3a e-con-full e-flex e-con e-parent\" data-id=\"58722d3a\" data-element_type=\"container\" data-settings=\"{&quot;content_width&quot;:&quot;full&quot;,&quot;container_type&quot;:&quot;flex&quot;}\" data-core-v316-plus=\"true\">\n\t\t\t\t<div class=\"elementor-element elementor-element-65c9336b elementor-widget elementor-widget-elementskit-advance-accordion\" data-id=\"65c9336b\" data-element_type=\"widget\" data-widget_type=\"elementskit-advance-accordion.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<div class=\"ekit-wid-con\">\n\n        <div class=\"elementskit-accordion accoedion-primary\" id=\"accordion-6a980b3a10ff7\">\n\n            \n                <div class=\"elementskit-card\">\n                    <div class=\"elementskit-card-header\" id=\"primaryHeading-0-65c9336b\">\n                        <a href=\"#collapse-9ac97566a980b3a10ff7\" class=\"elementskit-btn-link collapsed\" data-ekit-toggle=\"collapse\" data-target=\"#Collapse-9ac97566a980b3a10ff7\" aria-expanded=\"false\" aria-controls=\"Collapse-9ac97566a980b3a10ff7\">\n                            \n                            <span class=\"ekit-accordion-title\">\u00bfC\u00f3mo puedo utilizar mi cr\u00e9dito Emma?<\/span>\n\n                            \n                                <div class=\"ekit_accordion_icon_group\">\n\n                                    <div class=\"ekit_accordion_normal_icon\">\n                                        <!-- Normal Icon -->\n                                        <i aria-hidden=\"true\" class=\"icon-open icon-left icon icon-down-arrow1\"><\/i>                                    <\/div>\n\n                                    <div class=\"ekit_accordion_active_icon\">\n                                    <!-- Active Icon -->\n                                    <i aria-hidden=\"true\" class=\"icon-closed icon-left icon icon-up-arrow1\"><\/i>                                    <\/div>\n                                <\/div>\n\n                            \n                                                    <\/a>\n                    <\/div>\n\n                    <div id=\"Collapse-9ac97566a980b3a10ff7\" class=\" collapse\" aria-labelledby=\"primaryHeading-0-65c9336b\" data-parent=\"#accordion-6a980b3a10ff7\">\n                      \n                        <div class=\"elementskit-card-body\">\n                            \n\t\t<div class=\"widgetarea_warper widgetarea_warper_editable\" data-elementskit-widgetarea-key=\"65c9336b\"  data-elementskit-widgetarea-index=\"9ac9756\">\n\t\t\t<div class=\"widgetarea_warper_edit\" data-elementskit-widgetarea-key=\"65c9336b\" data-elementskit-widgetarea-index=\"9ac9756\">\n\t\t\t\t<i class=\"eicon-edit\" aria-hidden=\"true\"><\/i>\n\t\t\t\t<span>Edit Content<\/span>\n\t\t\t<\/div>\n\n\t\t\t\t\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"2768\" class=\"elementor elementor-2768\" data-elementor-post-type=\"elementskit_content\">\n\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-23ba8446 faq-answer-desktop e-flex e-con-boxed e-con e-parent\" data-id=\"23ba8446\" data-element_type=\"container\" data-settings=\"{&quot;container_type&quot;:&quot;flex&quot;,&quot;content_width&quot;:&quot;boxed&quot;}\" data-core-v316-plus=\"true\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-298a38ff e-flex e-con-boxed e-con e-parent\" data-id=\"298a38ff\" data-element_type=\"container\" data-settings=\"{&quot;container_type&quot;:&quot;flex&quot;,&quot;content_width&quot;:&quot;boxed&quot;}\" data-core-v316-plus=\"true\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-224c5396 elementor-widget elementor-widget-text-editor\" data-id=\"224c5396\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>Una vez aprobado tu cr\u00e9dito pod\u00e9s utilizarlo de la siguiente manera:<\/p><ol><li>Comprando en comercios afiliados<\/li><li>Haciendo retiros de efectivo<\/li><\/ol>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-6b976f9e e-flex e-con-boxed e-con e-parent\" data-id=\"6b976f9e\" data-element_type=\"container\" data-settings=\"{&quot;container_type&quot;:&quot;flex&quot;,&quot;content_width&quot;:&quot;boxed&quot;}\" data-core-v316-plus=\"true\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<a class=\"elementor-element elementor-element-7b929c27 e-con-full e-flex e-con e-parent\" data-id=\"7b929c27\" data-element_type=\"container\" id=\"como-usar-link-text1\" data-settings=\"{&quot;content_width&quot;:&quot;full&quot;,&quot;container_type&quot;:&quot;flex&quot;}\" data-core-v316-plus=\"true\" href=\"https:\/\/emmapay.com\/costa-rica\/personas\/como-usar-emma\/\">\n\t\t\t\t<div class=\"elementor-element elementor-element-b512d37 elementor-widget elementor-widget-text-editor\" data-id=\"b512d37\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>Conoce m\u00e1s sobre c\u00f3mo usar tu cr\u00e9dito aqu\u00ed<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/a>\n\t\t<div class=\"elementor-element elementor-element-7cd67307 e-con-full e-flex e-con e-parent\" data-id=\"7cd67307\" data-element_type=\"container\" data-settings=\"{&quot;content_width&quot;:&quot;full&quot;,&quot;container_type&quot;:&quot;flex&quot;}\" data-core-v316-plus=\"true\">\n\t\t\t\t<div class=\"elementor-element elementor-element-e083b92 elementor-view-default elementor-widget elementor-widget-icon\" data-id=\"e083b92\" data-element_type=\"widget\" id=\"como-usar-link-icon1\" data-widget_type=\"icon.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<a class=\"elementor-icon\" href=\"https:\/\/emmapay.com\/costa-rica\/personas\/como-usar-emma\/\">\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"44\" height=\"44\" viewBox=\"0 0 44 44\" fill=\"none\"><circle cx=\"22\" cy=\"22\" r=\"22\" fill=\"#171C8F\"><\/circle><path d=\"M19.7049 16L18.2949 17.41L22.8749 22L18.2949 26.59L19.7049 28L25.7049 22L19.7049 16Z\" fill=\"white\"><\/path><\/svg>\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t                        <\/div>\n\n                    <\/div>\n\n                <\/div><!-- .elementskit-card END --> \n\n                \n                <div class=\"elementskit-card\">\n                    <div class=\"elementskit-card-header\" id=\"primaryHeading-1-65c9336b\">\n                        <a href=\"#collapse-03f71806a980b3a10ff7\" class=\"elementskit-btn-link collapsed\" data-ekit-toggle=\"collapse\" data-target=\"#Collapse-03f71806a980b3a10ff7\" aria-expanded=\"false\" aria-controls=\"Collapse-03f71806a980b3a10ff7\">\n                            \n                            <span class=\"ekit-accordion-title\">\u00bfD\u00f3nde puedo comprar con Emma?<\/span>\n\n                            \n                                <div class=\"ekit_accordion_icon_group\">\n\n                                    <div class=\"ekit_accordion_normal_icon\">\n                                        <!-- Normal Icon -->\n                                        <i aria-hidden=\"true\" class=\"icon-open icon-left icon icon-down-arrow1\"><\/i>                                    <\/div>\n\n                                    <div class=\"ekit_accordion_active_icon\">\n                                    <!-- Active Icon -->\n                                    <i aria-hidden=\"true\" class=\"icon-closed icon-left icon icon-up-arrow1\"><\/i>                                    <\/div>\n                                <\/div>\n\n                            \n                                                    <\/a>\n                    <\/div>\n\n                    <div id=\"Collapse-03f71806a980b3a10ff7\" class=\" collapse\" aria-labelledby=\"primaryHeading-1-65c9336b\" data-parent=\"#accordion-6a980b3a10ff7\">\n                      \n                        <div class=\"elementskit-card-body\">\n                            \n\t\t<div class=\"widgetarea_warper widgetarea_warper_editable\" data-elementskit-widgetarea-key=\"65c9336b\"  data-elementskit-widgetarea-index=\"03f7180\">\n\t\t\t<div class=\"widgetarea_warper_edit\" data-elementskit-widgetarea-key=\"65c9336b\" data-elementskit-widgetarea-index=\"03f7180\">\n\t\t\t\t<i class=\"eicon-edit\" aria-hidden=\"true\"><\/i>\n\t\t\t\t<span>Edit Content<\/span>\n\t\t\t<\/div>\n\n\t\t\t\t\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"2778\" class=\"elementor elementor-2778\" data-elementor-post-type=\"elementskit_content\">\n\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2592df5 faq-answer-desktop e-flex e-con-boxed e-con e-parent\" data-id=\"2592df5\" data-element_type=\"container\" data-settings=\"{&quot;container_type&quot;:&quot;flex&quot;,&quot;content_width&quot;:&quot;boxed&quot;}\" data-core-v316-plus=\"true\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-6fee1a81 elementor-widget elementor-widget-text-editor\" data-id=\"6fee1a81\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>Con Emma pod\u00e9s comprar en m\u00e1s de 4 mil comercios afiliados en Costa Rica, en rubros como tecnolog\u00eda, muebles, salud, viajes, todo lo que necesites.<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t                        <\/div>\n\n                    <\/div>\n\n                <\/div><!-- .elementskit-card END --> \n\n                \n                <div class=\"elementskit-card\">\n                    <div class=\"elementskit-card-header\" id=\"primaryHeading-2-65c9336b\">\n                        <a href=\"#collapse-f540d4d6a980b3a10ff7\" class=\"elementskit-btn-link collapsed\" data-ekit-toggle=\"collapse\" data-target=\"#Collapse-f540d4d6a980b3a10ff7\" aria-expanded=\"false\" aria-controls=\"Collapse-f540d4d6a980b3a10ff7\">\n                            \n                            <span class=\"ekit-accordion-title\">\u00bfC\u00f3mo puedo realizar una compra?<\/span>\n\n                            \n                                <div class=\"ekit_accordion_icon_group\">\n\n                                    <div class=\"ekit_accordion_normal_icon\">\n                                        <!-- Normal Icon -->\n                                        <i aria-hidden=\"true\" class=\"icon-open icon-left icon icon-down-arrow1\"><\/i>                                    <\/div>\n\n                                    <div class=\"ekit_accordion_active_icon\">\n                                    <!-- Active Icon -->\n                                    <i aria-hidden=\"true\" class=\"icon-closed icon-left icon icon-up-arrow1\"><\/i>                                    <\/div>\n                                <\/div>\n\n                            \n                                                    <\/a>\n                    <\/div>\n\n                    <div id=\"Collapse-f540d4d6a980b3a10ff7\" class=\" collapse\" aria-labelledby=\"primaryHeading-2-65c9336b\" data-parent=\"#accordion-6a980b3a10ff7\">\n                      \n                        <div class=\"elementskit-card-body\">\n                            \n\t\t<div class=\"widgetarea_warper widgetarea_warper_editable\" data-elementskit-widgetarea-key=\"65c9336b\"  data-elementskit-widgetarea-index=\"f540d4d\">\n\t\t\t<div class=\"widgetarea_warper_edit\" data-elementskit-widgetarea-key=\"65c9336b\" data-elementskit-widgetarea-index=\"f540d4d\">\n\t\t\t\t<i class=\"eicon-edit\" aria-hidden=\"true\"><\/i>\n\t\t\t\t<span>Edit Content<\/span>\n\t\t\t<\/div>\n\n\t\t\t\t\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"2782\" class=\"elementor elementor-2782\" data-elementor-post-type=\"elementskit_content\">\n\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-6d58c85b faq-answer-desktop e-flex e-con-boxed e-con e-parent\" data-id=\"6d58c85b\" data-element_type=\"container\" data-settings=\"{&quot;container_type&quot;:&quot;flex&quot;,&quot;content_width&quot;:&quot;boxed&quot;}\" data-core-v316-plus=\"true\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-48b01eea e-flex e-con-boxed e-con e-parent\" data-id=\"48b01eea\" data-element_type=\"container\" data-settings=\"{&quot;container_type&quot;:&quot;flex&quot;,&quot;content_width&quot;:&quot;boxed&quot;}\" data-core-v316-plus=\"true\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-66515f19 elementor-widget elementor-widget-text-editor\" data-id=\"66515f19\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\tPara realizar una compra, deber\u00e1s tener tu l\u00ednea de cr\u00e9dito aprobada y activa. Puedes realizar una compra v\u00eda:\n<ul class=\"faq-bullet\">\n \t<li>Scan and Pay<\/li>\n \t<li>Solcitud de Pago<\/li>\n<\/ul>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-6706f2ff e-flex e-con-boxed e-con e-parent\" data-id=\"6706f2ff\" data-element_type=\"container\" data-settings=\"{&quot;container_type&quot;:&quot;flex&quot;,&quot;content_width&quot;:&quot;boxed&quot;}\" data-core-v316-plus=\"true\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<a class=\"elementor-element elementor-element-433ef172 e-con-full e-flex e-con e-parent\" data-id=\"433ef172\" data-element_type=\"container\" id=\"como-usar-link-text1\" data-settings=\"{&quot;content_width&quot;:&quot;full&quot;,&quot;container_type&quot;:&quot;flex&quot;}\" data-core-v316-plus=\"true\" href=\"https:\/\/emmapay.com\/costa-rica\/personas\/como-usar-emma\/\">\n\t\t\t\t<div class=\"elementor-element elementor-element-607d61dc elementor-widget elementor-widget-text-editor\" data-id=\"607d61dc\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>Conoce el paso a paso aqu\u00ed<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/a>\n\t\t<div class=\"elementor-element elementor-element-707c0b90 e-con-full e-flex e-con e-parent\" data-id=\"707c0b90\" data-element_type=\"container\" data-settings=\"{&quot;content_width&quot;:&quot;full&quot;,&quot;container_type&quot;:&quot;flex&quot;}\" data-core-v316-plus=\"true\">\n\t\t\t\t<div class=\"elementor-element elementor-element-2340919e elementor-view-default elementor-widget elementor-widget-icon\" data-id=\"2340919e\" data-element_type=\"widget\" id=\"como-usar-link-icon1\" data-widget_type=\"icon.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-icon-wrapper\">\n\t\t\t<a class=\"elementor-icon\" href=\"https:\/\/emmapay.com\/costa-rica\/personas\/como-usar-emma\/\">\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"44\" height=\"44\" viewBox=\"0 0 44 44\" fill=\"none\"><circle cx=\"22\" cy=\"22\" r=\"22\" fill=\"#171C8F\"><\/circle><path d=\"M19.7049 16L18.2949 17.41L22.8749 22L18.2949 26.59L19.7049 28L25.7049 22L19.7049 16Z\" fill=\"white\"><\/path><\/svg>\t\t\t<\/a>\n\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t                        <\/div>\n\n                    <\/div>\n\n                <\/div><!-- .elementskit-card END --> \n\n                \n                <div class=\"elementskit-card\">\n                    <div class=\"elementskit-card-header\" id=\"primaryHeading-3-65c9336b\">\n                        <a href=\"#collapse-f2092806a980b3a10ff7\" class=\"elementskit-btn-link collapsed\" data-ekit-toggle=\"collapse\" data-target=\"#Collapse-f2092806a980b3a10ff7\" aria-expanded=\"false\" aria-controls=\"Collapse-f2092806a980b3a10ff7\">\n                            \n                            <span class=\"ekit-accordion-title\">\u00bfD\u00f3nde puedo retirar efectivo?<\/span>\n\n                            \n                                <div class=\"ekit_accordion_icon_group\">\n\n                                    <div class=\"ekit_accordion_normal_icon\">\n                                        <!-- Normal Icon -->\n                                        <i aria-hidden=\"true\" class=\"icon-open icon-left icon icon-down-arrow1\"><\/i>                                    <\/div>\n\n                                    <div class=\"ekit_accordion_active_icon\">\n                                    <!-- Active Icon -->\n                                    <i aria-hidden=\"true\" class=\"icon-closed icon-left icon icon-up-arrow1\"><\/i>                                    <\/div>\n                                <\/div>\n\n                            \n                                                    <\/a>\n                    <\/div>\n\n                    <div id=\"Collapse-f2092806a980b3a10ff7\" class=\" collapse\" aria-labelledby=\"primaryHeading-3-65c9336b\" data-parent=\"#accordion-6a980b3a10ff7\">\n                      \n                        <div class=\"elementskit-card-body\">\n                            \n\t\t<div class=\"widgetarea_warper widgetarea_warper_editable\" data-elementskit-widgetarea-key=\"65c9336b\"  data-elementskit-widgetarea-index=\"f209280\">\n\t\t\t<div class=\"widgetarea_warper_edit\" data-elementskit-widgetarea-key=\"65c9336b\" data-elementskit-widgetarea-index=\"f209280\">\n\t\t\t\t<i class=\"eicon-edit\" aria-hidden=\"true\"><\/i>\n\t\t\t\t<span>Edit Content<\/span>\n\t\t\t<\/div>\n\n\t\t\t\t\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"2790\" class=\"elementor elementor-2790\" data-elementor-post-type=\"elementskit_content\">\n\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-269e81a6 faq-answer-desktop e-flex e-con-boxed e-con e-parent\" data-id=\"269e81a6\" data-element_type=\"container\" data-settings=\"{&quot;container_type&quot;:&quot;flex&quot;,&quot;content_width&quot;:&quot;boxed&quot;}\" data-core-v316-plus=\"true\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-4baebaa2 elementor-widget elementor-widget-text-editor\" data-id=\"4baebaa2\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>Debes solicitar tu efectivo desde EMMA, y lo puedes retirar en todas las tiendas Gollo y La Curacao del pa\u00eds.<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t                        <\/div>\n\n                    <\/div>\n\n                <\/div><!-- .elementskit-card END --> \n\n                \n                <div class=\"elementskit-card\">\n                    <div class=\"elementskit-card-header\" id=\"primaryHeading-4-65c9336b\">\n                        <a href=\"#collapse-6d4a15a6a980b3a10ff7\" class=\"elementskit-btn-link collapsed\" data-ekit-toggle=\"collapse\" data-target=\"#Collapse-6d4a15a6a980b3a10ff7\" aria-expanded=\"false\" aria-controls=\"Collapse-6d4a15a6a980b3a10ff7\">\n                            \n                            <span class=\"ekit-accordion-title\">He recibido una solicitud de pago, \u00bfqu\u00e9 debo hacer?<\/span>\n\n                            \n                                <div class=\"ekit_accordion_icon_group\">\n\n                                    <div class=\"ekit_accordion_normal_icon\">\n                                        <!-- Normal Icon -->\n                                        <i aria-hidden=\"true\" class=\"icon-open icon-left icon icon-down-arrow1\"><\/i>                                    <\/div>\n\n                                    <div class=\"ekit_accordion_active_icon\">\n                                    <!-- Active Icon -->\n                                    <i aria-hidden=\"true\" class=\"icon-closed icon-left icon icon-up-arrow1\"><\/i>                                    <\/div>\n                                <\/div>\n\n                            \n                                                    <\/a>\n                    <\/div>\n\n                    <div id=\"Collapse-6d4a15a6a980b3a10ff7\" class=\" collapse\" aria-labelledby=\"primaryHeading-4-65c9336b\" data-parent=\"#accordion-6a980b3a10ff7\">\n                      \n                        <div class=\"elementskit-card-body\">\n                            \n\t\t<div class=\"widgetarea_warper widgetarea_warper_editable\" data-elementskit-widgetarea-key=\"65c9336b\"  data-elementskit-widgetarea-index=\"6d4a15a\">\n\t\t\t<div class=\"widgetarea_warper_edit\" data-elementskit-widgetarea-key=\"65c9336b\" data-elementskit-widgetarea-index=\"6d4a15a\">\n\t\t\t\t<i class=\"eicon-edit\" aria-hidden=\"true\"><\/i>\n\t\t\t\t<span>Edit Content<\/span>\n\t\t\t<\/div>\n\n\t\t\t\t\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"2794\" class=\"elementor elementor-2794\" data-elementor-post-type=\"elementskit_content\">\n\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2d569c8b faq-answer-desktop e-flex e-con-boxed e-con e-parent\" data-id=\"2d569c8b\" data-element_type=\"container\" data-settings=\"{&quot;container_type&quot;:&quot;flex&quot;,&quot;content_width&quot;:&quot;boxed&quot;}\" data-core-v316-plus=\"true\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-6bb4a7ef elementor-widget elementor-widget-text-editor\" data-id=\"6bb4a7ef\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>Te llegar\u00e1 una notificaci\u00f3n de solicitud de pago a tu celular. Para completar la compra deber\u00e1s:<\/p><ol><li>Inicia sesi\u00f3n<\/li><li>Selecciona el plazo de tu compra<\/li><li>Valida tu compra con el Token y \u00a1listo!<\/li><\/ol>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t                        <\/div>\n\n                    <\/div>\n\n                <\/div><!-- .elementskit-card END --> \n\n                        <\/div>\n    <\/div>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t                        <\/div>\n                    <\/div>\n                                    <div class=\"tab-pane elementkit-tab-pane elementor-repeater-item-64fec06 \" id=\"content-64fec066a980b399e48a\" role=\"tabpanel\"\n                         aria-labelledby=\"content-64fec066a980b399e48a-tab\">\n                        <div class=\"animated fadeIn\">\n                            \n\t\t<div class=\"widgetarea_warper widgetarea_warper_editable\" data-elementskit-widgetarea-key=\"2cdd4ce9\"  data-elementskit-widgetarea-index=\"64fec06\">\n\t\t\t<div class=\"widgetarea_warper_edit\" data-elementskit-widgetarea-key=\"2cdd4ce9\" data-elementskit-widgetarea-index=\"64fec06\">\n\t\t\t\t<i class=\"eicon-edit\" aria-hidden=\"true\"><\/i>\n\t\t\t\t<span>Edit Content<\/span>\n\t\t\t<\/div>\n\n\t\t\t\t\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"2555\" class=\"elementor elementor-2555\" data-elementor-post-type=\"elementskit_content\">\n\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-621c8d43 e-con-full e-flex e-con e-parent\" data-id=\"621c8d43\" data-element_type=\"container\" data-settings=\"{&quot;content_width&quot;:&quot;full&quot;,&quot;container_type&quot;:&quot;flex&quot;}\" data-core-v316-plus=\"true\">\n\t\t\t\t<div class=\"elementor-element elementor-element-bbad5b6 elementor-widget elementor-widget-elementskit-advance-accordion\" data-id=\"bbad5b6\" data-element_type=\"widget\" data-widget_type=\"elementskit-advance-accordion.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<div class=\"ekit-wid-con\">\n\n        <div class=\"elementskit-accordion accoedion-primary\" id=\"accordion-6a980b3a26666\">\n\n            \n                <div class=\"elementskit-card\">\n                    <div class=\"elementskit-card-header\" id=\"primaryHeading-0-bbad5b6\">\n                        <a href=\"#collapse-9ac97566a980b3a26666\" class=\"elementskit-btn-link collapsed\" data-ekit-toggle=\"collapse\" data-target=\"#Collapse-9ac97566a980b3a26666\" aria-expanded=\"false\" aria-controls=\"Collapse-9ac97566a980b3a26666\">\n                            \n                            <span class=\"ekit-accordion-title\">\u00bfD\u00f3nde puedo pagar mis cuotas?<\/span>\n\n                            \n                                <div class=\"ekit_accordion_icon_group\">\n\n                                    <div class=\"ekit_accordion_normal_icon\">\n                                        <!-- Normal Icon -->\n                                        <i aria-hidden=\"true\" class=\"icon-open icon-left icon icon-down-arrow1\"><\/i>                                    <\/div>\n\n                                    <div class=\"ekit_accordion_active_icon\">\n                                    <!-- Active Icon -->\n                                    <i aria-hidden=\"true\" class=\"icon-closed icon-left icon icon-up-arrow1\"><\/i>                                    <\/div>\n                                <\/div>\n\n                            \n                                                    <\/a>\n                    <\/div>\n\n                    <div id=\"Collapse-9ac97566a980b3a26666\" class=\" collapse\" aria-labelledby=\"primaryHeading-0-bbad5b6\" data-parent=\"#accordion-6a980b3a26666\">\n                      \n                        <div class=\"elementskit-card-body\">\n                            \n\t\t<div class=\"widgetarea_warper widgetarea_warper_editable\" data-elementskit-widgetarea-key=\"bbad5b6\"  data-elementskit-widgetarea-index=\"9ac9756\">\n\t\t\t<div class=\"widgetarea_warper_edit\" data-elementskit-widgetarea-key=\"bbad5b6\" data-elementskit-widgetarea-index=\"9ac9756\">\n\t\t\t\t<i class=\"eicon-edit\" aria-hidden=\"true\"><\/i>\n\t\t\t\t<span>Edit Content<\/span>\n\t\t\t<\/div>\n\n\t\t\t\t\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"2804\" class=\"elementor elementor-2804\" data-elementor-post-type=\"elementskit_content\">\n\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-525650f5 faq-answer-desktop e-flex e-con-boxed e-con e-parent\" data-id=\"525650f5\" data-element_type=\"container\" data-settings=\"{&quot;container_type&quot;:&quot;flex&quot;,&quot;content_width&quot;:&quot;boxed&quot;}\" data-core-v316-plus=\"true\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-446cdd69 elementor-widget elementor-widget-text-editor\" data-id=\"446cdd69\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>Realiz\u00e1 los pagos de tus cuotas en todas las tiendas Gollo, La Curacao o RadioShack del pa\u00eds.<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t                        <\/div>\n\n                    <\/div>\n\n                <\/div><!-- .elementskit-card END --> \n\n                \n                <div class=\"elementskit-card\">\n                    <div class=\"elementskit-card-header\" id=\"primaryHeading-1-bbad5b6\">\n                        <a href=\"#collapse-03f71806a980b3a26666\" class=\"elementskit-btn-link collapsed\" data-ekit-toggle=\"collapse\" data-target=\"#Collapse-03f71806a980b3a26666\" aria-expanded=\"false\" aria-controls=\"Collapse-03f71806a980b3a26666\">\n                            \n                            <span class=\"ekit-accordion-title\">\u00bfPuedo cancelar mis cuotas antes del plazo establecido?<\/span>\n\n                            \n                                <div class=\"ekit_accordion_icon_group\">\n\n                                    <div class=\"ekit_accordion_normal_icon\">\n                                        <!-- Normal Icon -->\n                                        <i aria-hidden=\"true\" class=\"icon-open icon-left icon icon-down-arrow1\"><\/i>                                    <\/div>\n\n                                    <div class=\"ekit_accordion_active_icon\">\n                                    <!-- Active Icon -->\n                                    <i aria-hidden=\"true\" class=\"icon-closed icon-left icon icon-up-arrow1\"><\/i>                                    <\/div>\n                                <\/div>\n\n                            \n                                                    <\/a>\n                    <\/div>\n\n                    <div id=\"Collapse-03f71806a980b3a26666\" class=\" collapse\" aria-labelledby=\"primaryHeading-1-bbad5b6\" data-parent=\"#accordion-6a980b3a26666\">\n                      \n                        <div class=\"elementskit-card-body\">\n                            \n\t\t<div class=\"widgetarea_warper widgetarea_warper_editable\" data-elementskit-widgetarea-key=\"bbad5b6\"  data-elementskit-widgetarea-index=\"03f7180\">\n\t\t\t<div class=\"widgetarea_warper_edit\" data-elementskit-widgetarea-key=\"bbad5b6\" data-elementskit-widgetarea-index=\"03f7180\">\n\t\t\t\t<i class=\"eicon-edit\" aria-hidden=\"true\"><\/i>\n\t\t\t\t<span>Edit Content<\/span>\n\t\t\t<\/div>\n\n\t\t\t\t\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"2808\" class=\"elementor elementor-2808\" data-elementor-post-type=\"elementskit_content\">\n\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7b3b383e faq-answer-desktop e-flex e-con-boxed e-con e-parent\" data-id=\"7b3b383e\" data-element_type=\"container\" data-settings=\"{&quot;container_type&quot;:&quot;flex&quot;,&quot;content_width&quot;:&quot;boxed&quot;}\" data-core-v316-plus=\"true\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-1364c45e elementor-widget elementor-widget-text-editor\" data-id=\"1364c45e\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>Pod\u00e9s cancelar la totalidad de tu cr\u00e9dito o hacer abonos extraordinarios en el momento que quer\u00e1s, sin penalizaciones.<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t                        <\/div>\n\n                    <\/div>\n\n                <\/div><!-- .elementskit-card END --> \n\n                \n                <div class=\"elementskit-card\">\n                    <div class=\"elementskit-card-header\" id=\"primaryHeading-2-bbad5b6\">\n                        <a href=\"#collapse-f540d4d6a980b3a26666\" class=\"elementskit-btn-link collapsed\" data-ekit-toggle=\"collapse\" data-target=\"#Collapse-f540d4d6a980b3a26666\" aria-expanded=\"false\" aria-controls=\"Collapse-f540d4d6a980b3a26666\">\n                            \n                            <span class=\"ekit-accordion-title\">\u00bfHacer pagos extraordinarios disminuye el monto de mi cuota?<\/span>\n\n                            \n                                <div class=\"ekit_accordion_icon_group\">\n\n                                    <div class=\"ekit_accordion_normal_icon\">\n                                        <!-- Normal Icon -->\n                                        <i aria-hidden=\"true\" class=\"icon-open icon-left icon icon-down-arrow1\"><\/i>                                    <\/div>\n\n                                    <div class=\"ekit_accordion_active_icon\">\n                                    <!-- Active Icon -->\n                                    <i aria-hidden=\"true\" class=\"icon-closed icon-left icon icon-up-arrow1\"><\/i>                                    <\/div>\n                                <\/div>\n\n                            \n                                                    <\/a>\n                    <\/div>\n\n                    <div id=\"Collapse-f540d4d6a980b3a26666\" class=\" collapse\" aria-labelledby=\"primaryHeading-2-bbad5b6\" data-parent=\"#accordion-6a980b3a26666\">\n                      \n                        <div class=\"elementskit-card-body\">\n                            \n\t\t<div class=\"widgetarea_warper widgetarea_warper_editable\" data-elementskit-widgetarea-key=\"bbad5b6\"  data-elementskit-widgetarea-index=\"f540d4d\">\n\t\t\t<div class=\"widgetarea_warper_edit\" data-elementskit-widgetarea-key=\"bbad5b6\" data-elementskit-widgetarea-index=\"f540d4d\">\n\t\t\t\t<i class=\"eicon-edit\" aria-hidden=\"true\"><\/i>\n\t\t\t\t<span>Edit Content<\/span>\n\t\t\t<\/div>\n\n\t\t\t\t\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"2812\" class=\"elementor elementor-2812\" data-elementor-post-type=\"elementskit_content\">\n\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-425fdf54 faq-answer-desktop e-flex e-con-boxed e-con e-parent\" data-id=\"425fdf54\" data-element_type=\"container\" data-settings=\"{&quot;container_type&quot;:&quot;flex&quot;,&quot;content_width&quot;:&quot;boxed&quot;}\" data-core-v316-plus=\"true\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-52a9b739 elementor-widget elementor-widget-text-editor\" data-id=\"52a9b739\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>No disminuye el monto de las cuotas, sino disminuir\u00e1 la cantidad de cuotas restantes a pagar.<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t                        <\/div>\n\n                    <\/div>\n\n                <\/div><!-- .elementskit-card END --> \n\n                        <\/div>\n    <\/div>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t                        <\/div>\n                    <\/div>\n                                    <div class=\"tab-pane elementkit-tab-pane elementor-repeater-item-88288a4 \" id=\"content-88288a46a980b399e48a\" role=\"tabpanel\"\n                         aria-labelledby=\"content-88288a46a980b399e48a-tab\">\n                        <div class=\"animated fadeIn\">\n                            \n\t\t<div class=\"widgetarea_warper widgetarea_warper_editable\" data-elementskit-widgetarea-key=\"2cdd4ce9\"  data-elementskit-widgetarea-index=\"88288a4\">\n\t\t\t<div class=\"widgetarea_warper_edit\" data-elementskit-widgetarea-key=\"2cdd4ce9\" data-elementskit-widgetarea-index=\"88288a4\">\n\t\t\t\t<i class=\"eicon-edit\" aria-hidden=\"true\"><\/i>\n\t\t\t\t<span>Edit Content<\/span>\n\t\t\t<\/div>\n\n\t\t\t\t\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"2559\" class=\"elementor elementor-2559\" data-elementor-post-type=\"elementskit_content\">\n\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3178a8b e-con-full e-flex e-con e-parent\" data-id=\"3178a8b\" data-element_type=\"container\" data-settings=\"{&quot;content_width&quot;:&quot;full&quot;,&quot;container_type&quot;:&quot;flex&quot;}\" data-core-v316-plus=\"true\">\n\t\t\t\t<div class=\"elementor-element elementor-element-5256edc2 elementor-widget elementor-widget-elementskit-advance-accordion\" data-id=\"5256edc2\" data-element_type=\"widget\" data-widget_type=\"elementskit-advance-accordion.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<div class=\"ekit-wid-con\">\n\n        <div class=\"elementskit-accordion accoedion-primary\" id=\"accordion-6a980b3a3140a\">\n\n            \n                <div class=\"elementskit-card\">\n                    <div class=\"elementskit-card-header\" id=\"primaryHeading-0-5256edc2\">\n                        <a href=\"#collapse-9ac97566a980b3a3140a\" class=\"elementskit-btn-link collapsed\" data-ekit-toggle=\"collapse\" data-target=\"#Collapse-9ac97566a980b3a3140a\" aria-expanded=\"false\" aria-controls=\"Collapse-9ac97566a980b3a3140a\">\n                            \n                            <span class=\"ekit-accordion-title\">\u00bfPuedo compartir mi PIN de seguridad?<\/span>\n\n                            \n                                <div class=\"ekit_accordion_icon_group\">\n\n                                    <div class=\"ekit_accordion_normal_icon\">\n                                        <!-- Normal Icon -->\n                                        <i aria-hidden=\"true\" class=\"icon-open icon-left icon icon-down-arrow1\"><\/i>                                    <\/div>\n\n                                    <div class=\"ekit_accordion_active_icon\">\n                                    <!-- Active Icon -->\n                                    <i aria-hidden=\"true\" class=\"icon-closed icon-left icon icon-up-arrow1\"><\/i>                                    <\/div>\n                                <\/div>\n\n                            \n                                                    <\/a>\n                    <\/div>\n\n                    <div id=\"Collapse-9ac97566a980b3a3140a\" class=\" collapse\" aria-labelledby=\"primaryHeading-0-5256edc2\" data-parent=\"#accordion-6a980b3a3140a\">\n                      \n                        <div class=\"elementskit-card-body\">\n                            \n\t\t<div class=\"widgetarea_warper widgetarea_warper_editable\" data-elementskit-widgetarea-key=\"5256edc2\"  data-elementskit-widgetarea-index=\"9ac9756\">\n\t\t\t<div class=\"widgetarea_warper_edit\" data-elementskit-widgetarea-key=\"5256edc2\" data-elementskit-widgetarea-index=\"9ac9756\">\n\t\t\t\t<i class=\"eicon-edit\" aria-hidden=\"true\"><\/i>\n\t\t\t\t<span>Edit Content<\/span>\n\t\t\t<\/div>\n\n\t\t\t\t\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"2819\" class=\"elementor elementor-2819\" data-elementor-post-type=\"elementskit_content\">\n\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2e72fd51 faq-answer-desktop e-flex e-con-boxed e-con e-parent\" data-id=\"2e72fd51\" data-element_type=\"container\" data-settings=\"{&quot;container_type&quot;:&quot;flex&quot;,&quot;content_width&quot;:&quot;boxed&quot;}\" data-core-v316-plus=\"true\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-365cadd8 elementor-widget elementor-widget-text-editor\" data-id=\"365cadd8\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>No, nunca deb\u00e9s compartir tu PIN de seguridad o datos personales por seguridad.<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t                        <\/div>\n\n                    <\/div>\n\n                <\/div><!-- .elementskit-card END --> \n\n                \n                <div class=\"elementskit-card\">\n                    <div class=\"elementskit-card-header\" id=\"primaryHeading-1-5256edc2\">\n                        <a href=\"#collapse-03f71806a980b3a3140a\" class=\"elementskit-btn-link collapsed\" data-ekit-toggle=\"collapse\" data-target=\"#Collapse-03f71806a980b3a3140a\" aria-expanded=\"false\" aria-controls=\"Collapse-03f71806a980b3a3140a\">\n                            \n                            <span class=\"ekit-accordion-title\">\u00bfUna tercera persona puede comprar con mi aplicaci\u00f3n EMMA?<\/span>\n\n                            \n                                <div class=\"ekit_accordion_icon_group\">\n\n                                    <div class=\"ekit_accordion_normal_icon\">\n                                        <!-- Normal Icon -->\n                                        <i aria-hidden=\"true\" class=\"icon-open icon-left icon icon-down-arrow1\"><\/i>                                    <\/div>\n\n                                    <div class=\"ekit_accordion_active_icon\">\n                                    <!-- Active Icon -->\n                                    <i aria-hidden=\"true\" class=\"icon-closed icon-left icon icon-up-arrow1\"><\/i>                                    <\/div>\n                                <\/div>\n\n                            \n                                                    <\/a>\n                    <\/div>\n\n                    <div id=\"Collapse-03f71806a980b3a3140a\" class=\" collapse\" aria-labelledby=\"primaryHeading-1-5256edc2\" data-parent=\"#accordion-6a980b3a3140a\">\n                      \n                        <div class=\"elementskit-card-body\">\n                            \n\t\t<div class=\"widgetarea_warper widgetarea_warper_editable\" data-elementskit-widgetarea-key=\"5256edc2\"  data-elementskit-widgetarea-index=\"03f7180\">\n\t\t\t<div class=\"widgetarea_warper_edit\" data-elementskit-widgetarea-key=\"5256edc2\" data-elementskit-widgetarea-index=\"03f7180\">\n\t\t\t\t<i class=\"eicon-edit\" aria-hidden=\"true\"><\/i>\n\t\t\t\t<span>Edit Content<\/span>\n\t\t\t<\/div>\n\n\t\t\t\t\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"2824\" class=\"elementor elementor-2824\" data-elementor-post-type=\"elementskit_content\">\n\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-477ad152 faq-answer-desktop e-flex e-con-boxed e-con e-parent\" data-id=\"477ad152\" data-element_type=\"container\" data-settings=\"{&quot;container_type&quot;:&quot;flex&quot;,&quot;content_width&quot;:&quot;boxed&quot;}\" data-core-v316-plus=\"true\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-d84b6cc elementor-widget elementor-widget-text-editor\" data-id=\"d84b6cc\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>No, EMMA es de uso personal por lo que no debe permitir bajo ninguna circunstancia que terceras personas utilicen sus datos para ejecutar compras con EMMA.<\/p>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t                        <\/div>\n\n                    <\/div>\n\n                <\/div><!-- .elementskit-card END --> \n\n                        <\/div>\n    <\/div>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t                        <\/div>\n                    <\/div>\n                            <\/div>\n        <\/div>\n    <\/div>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-28667988 elementor-hidden-widescreen elementor-hidden-desktop e-flex e-con-boxed e-con e-parent\" data-id=\"28667988\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;,&quot;container_type&quot;:&quot;flex&quot;,&quot;content_width&quot;:&quot;boxed&quot;}\" data-e-bg-lazyload=\"\" data-core-v316-plus=\"true\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-603415b5 e-con-full e-flex e-con e-parent\" data-id=\"603415b5\" data-element_type=\"container\" data-settings=\"{&quot;content_width&quot;:&quot;full&quot;,&quot;container_type&quot;:&quot;flex&quot;}\" data-core-v316-plus=\"true\">\n\t\t\t\t<div class=\"elementor-element elementor-element-490181e7 elementor-widget elementor-widget-elementskit-advance-accordion\" data-id=\"490181e7\" data-element_type=\"widget\" id=\"tablet-faq-persona\" data-widget_type=\"elementskit-advance-accordion.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<div class=\"ekit-wid-con\">\n\n        <div class=\"elementskit-accordion accoedion-primary\" id=\"accordion-6a980b3a38332\">\n\n            \n                <div class=\"elementskit-card\">\n                    <div class=\"elementskit-card-header\" id=\"primaryHeading-0-490181e7\">\n                        <a href=\"#collapse-1ae46396a980b3a38332\" class=\"elementskit-btn-link collapsed\" data-ekit-toggle=\"collapse\" data-target=\"#Collapse-1ae46396a980b3a38332\" aria-expanded=\"false\" aria-controls=\"Collapse-1ae46396a980b3a38332\">\n                            \n                            <span class=\"ekit-accordion-title\"> <img decoding=\"async\" src=\"https:\/\/emmapaycostarica.local.tt\/wp-content\/uploads\/2023\/08\/credito-emma.svg\"><span class=\"accordion-title\"> Cr\u00e9dito Emma<\/span><\/span>\n\n                            \n                                <div class=\"ekit_accordion_icon_group\">\n\n                                    <div class=\"ekit_accordion_normal_icon\">\n                                        <!-- Normal Icon -->\n                                        <svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"36\" height=\"36\" viewBox=\"0 0 36 36\" fill=\"none\"><circle cx=\"18\" cy=\"18\" r=\"18\" fill=\"#171C8F\"><\/circle><path d=\"M19 13H17V17H13V19H17V23H19V19H23V17H19V13ZM18 8C12.48 8 8 12.48 8 18C8 23.52 12.48 28 18 28C23.52 28 28 23.52 28 18C28 12.48 23.52 8 18 8ZM18 26C13.59 26 10 22.41 10 18C10 13.59 13.59 10 18 10C22.41 10 26 13.59 26 18C26 22.41 22.41 26 18 26Z\" fill=\"white\"><\/path><\/svg>                                    <\/div>\n\n                                    <div class=\"ekit_accordion_active_icon\">\n                                    <!-- Active Icon -->\n                                    <svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"36\" height=\"36\" viewBox=\"0 0 36 36\" fill=\"none\"><circle cx=\"18\" cy=\"18\" r=\"18\" fill=\"#26D07C\"><\/circle><path d=\"M13 17V19H23V17H13ZM18 8C12.48 8 8 12.48 8 18C8 23.52 12.48 28 18 28C23.52 28 28 23.52 28 18C28 12.48 23.52 8 18 8ZM18 26C13.59 26 10 22.41 10 18C10 13.59 13.59 10 18 10C22.41 10 26 13.59 26 18C26 22.41 22.41 26 18 26Z\" fill=\"white\"><\/path><\/svg>                                    <\/div>\n                                <\/div>\n\n                            \n                                                    <\/a>\n                    <\/div>\n\n                    <div id=\"Collapse-1ae46396a980b3a38332\" class=\" collapse\" aria-labelledby=\"primaryHeading-0-490181e7\" data-parent=\"#accordion-6a980b3a38332\">\n                      \n                        <div class=\"elementskit-card-body\">\n                            \n\t\t<div class=\"widgetarea_warper widgetarea_warper_editable\" data-elementskit-widgetarea-key=\"490181e7\"  data-elementskit-widgetarea-index=\"1ae4639\">\n\t\t\t<div class=\"widgetarea_warper_edit\" data-elementskit-widgetarea-key=\"490181e7\" data-elementskit-widgetarea-index=\"1ae4639\">\n\t\t\t\t<i class=\"eicon-edit\" aria-hidden=\"true\"><\/i>\n\t\t\t\t<span>Edit Content<\/span>\n\t\t\t<\/div>\n\n\t\t\t\t\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"2567\" class=\"elementor elementor-2567\" data-elementor-post-type=\"elementskit_content\">\n\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-e85ba2b e-con-full e-flex e-con e-parent\" data-id=\"e85ba2b\" data-element_type=\"container\" data-settings=\"{&quot;content_width&quot;:&quot;full&quot;,&quot;container_type&quot;:&quot;flex&quot;}\" data-core-v316-plus=\"true\">\n\t\t\t\t<div class=\"elementor-element elementor-element-1a49463e elementor-widget__width-inherit elementor-widget elementor-widget-elementskit-accordion\" data-id=\"1a49463e\" data-element_type=\"widget\" id=\"tablet-faq-2\" data-widget_type=\"elementskit-accordion.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<div class=\"ekit-wid-con\" >\n        <div class=\"elementskit-accordion accoedion-primary\" id=\"accordion-6a980b3a3bb50\">\n\n            \n                <div class=\"elementskit-card \">\n                    <div class=\"elementskit-card-header\" id=\"primaryHeading-0-1a49463e\">\n                        <a href=\"#collapse-897e1af6a980b3a3bb50\" class=\"ekit-accordion--toggler elementskit-btn-link collapsed\" data-ekit-toggle=\"collapse\" data-target=\"#Collapse-897e1af6a980b3a3bb50\" aria-expanded=\"false\" aria-controls=\"Collapse-897e1af6a980b3a3bb50\">\n                            \n                            <span class=\"ekit-accordion-title\">\u00bfQu\u00e9 es Emma?<\/span>\n\n                            \n                                <div class=\"ekit_accordion_icon_group\">\n                                    <div class=\"ekit_accordion_normal_icon\">\n                                        <!-- Normal Icon -->\n                                        <i aria-hidden=\"true\" class=\"icon-open icon-right icon icon-down-arrow1\"><\/i>                                    <\/div>\n\n                                    <div class=\"ekit_accordion_active_icon\">\n                                        <!-- Active Icon -->\n                                        <i aria-hidden=\"true\" class=\"icon-closed icon-right icon icon-up-arrow1\"><\/i>                                    <\/div>\n\n                                <\/div>\n\n                            \n                                                    <\/a>\n                    <\/div>\n\n                    <div id=\"Collapse-897e1af6a980b3a3bb50\" class=\" collapse\" aria-labelledby=\"primaryHeading-0-1a49463e\" data-parent=\"#accordion-6a980b3a3bb50\">\n\n                        <div class=\"elementskit-card-body ekit-accordion--content\">\n                            <div class=\"faq-tablet-answer\"><p><img decoding=\"async\" class=\"faqhr alignnone size-medium wp-image-21301\" src=\"https:\/\/emmapay.com\/costa-rica\/wp-content\/uploads\/sites\/8\/2023\/09\/Line-69.png\" alt=\"\" width=\"100%\" height=\"1\" \/><\/p><p>Emma es la app que te d\u00e1 cr\u00e9dito 100% digital desde tu app de forma r\u00e1pida, f\u00e1cil y segura para que lo us\u00e9s en lo que necesit\u00e9s. <br \/>Podr\u00e1s utilizar el cr\u00e9dito para comprar en m\u00e1s de 4mil comercios afiliados a Emma o hacer retiros de efectivo.<\/p><\/div>                        <\/div>\n\n                    <\/div>\n\n                <\/div><!-- .elementskit-card END -->\n\n                \n                <div class=\"elementskit-card \">\n                    <div class=\"elementskit-card-header\" id=\"primaryHeading-1-1a49463e\">\n                        <a href=\"#collapse-4f961c16a980b3a3bb50\" class=\"ekit-accordion--toggler elementskit-btn-link collapsed\" data-ekit-toggle=\"collapse\" data-target=\"#Collapse-4f961c16a980b3a3bb50\" aria-expanded=\"false\" aria-controls=\"Collapse-4f961c16a980b3a3bb50\">\n                            \n                            <span class=\"ekit-accordion-title\">\u00bfCu\u00e1les son los requisitos para solicitar un cr\u00e9dito Emma?<\/span>\n\n                            \n                                <div class=\"ekit_accordion_icon_group\">\n                                    <div class=\"ekit_accordion_normal_icon\">\n                                        <!-- Normal Icon -->\n                                        <i aria-hidden=\"true\" class=\"icon-open icon-right icon icon-down-arrow1\"><\/i>                                    <\/div>\n\n                                    <div class=\"ekit_accordion_active_icon\">\n                                        <!-- Active Icon -->\n                                        <i aria-hidden=\"true\" class=\"icon-closed icon-right icon icon-up-arrow1\"><\/i>                                    <\/div>\n\n                                <\/div>\n\n                            \n                                                    <\/a>\n                    <\/div>\n\n                    <div id=\"Collapse-4f961c16a980b3a3bb50\" class=\" collapse\" aria-labelledby=\"primaryHeading-1-1a49463e\" data-parent=\"#accordion-6a980b3a3bb50\">\n\n                        <div class=\"elementskit-card-body ekit-accordion--content\">\n                            <div class=\"faq-tablet-answer\"><img decoding=\"async\" class=\"faqhr alignnone size-medium wp-image-21301\" src=\"https:\/\/emmapay.com\/costa-rica\/wp-content\/uploads\/sites\/8\/2023\/09\/Line-69.png\" alt=\"\" width=\"100%\" height=\"1\" \/>Para solicitar una l\u00ednea de cr\u00e9dito Emma deber\u00e1s:\n<ol>\n \t<li>Ser mayor de edad<\/li>\n \t<li>Tener tu documento de identidad vigente<\/li>\n \t<li>Comprobante de ingresos (opcional)<\/li>\n<\/ol>\n<\/div>                        <\/div>\n\n                    <\/div>\n\n                <\/div><!-- .elementskit-card END -->\n\n                \n                <div class=\"elementskit-card \">\n                    <div class=\"elementskit-card-header\" id=\"primaryHeading-2-1a49463e\">\n                        <a href=\"#collapse-0c7a8396a980b3a3bb50\" class=\"ekit-accordion--toggler elementskit-btn-link collapsed\" data-ekit-toggle=\"collapse\" data-target=\"#Collapse-0c7a8396a980b3a3bb50\" aria-expanded=\"false\" aria-controls=\"Collapse-0c7a8396a980b3a3bb50\">\n                            \n                            <span class=\"ekit-accordion-title\">\u00bfQu\u00e9 documentos debo tener a la mano para solicitar mi cr\u00e9dito Emma?<\/span>\n\n                            \n                                <div class=\"ekit_accordion_icon_group\">\n                                    <div class=\"ekit_accordion_normal_icon\">\n                                        <!-- Normal Icon -->\n                                        <i aria-hidden=\"true\" class=\"icon-open icon-right icon icon-down-arrow1\"><\/i>                                    <\/div>\n\n                                    <div class=\"ekit_accordion_active_icon\">\n                                        <!-- Active Icon -->\n                                        <i aria-hidden=\"true\" class=\"icon-closed icon-right icon icon-up-arrow1\"><\/i>                                    <\/div>\n\n                                <\/div>\n\n                            \n                                                    <\/a>\n                    <\/div>\n\n                    <div id=\"Collapse-0c7a8396a980b3a3bb50\" class=\" collapse\" aria-labelledby=\"primaryHeading-2-1a49463e\" data-parent=\"#accordion-6a980b3a3bb50\">\n\n                        <div class=\"elementskit-card-body ekit-accordion--content\">\n                            <div class=\"faq-tablet-answer\">\n\n<img decoding=\"async\" class=\"faqhr alignnone size-medium wp-image-21301\" src=\"https:\/\/emmapay.com\/costa-rica\/wp-content\/uploads\/sites\/8\/2023\/09\/Line-69.png\" alt=\"\" width=\"100%\" height=\"1\" \/>\n\nPara solicitar tu LC deber\u00e1s tener a la mano t\u00fa c\u00e9dula de identidad o c\u00e9dula de residencia.\n\n<\/div>                        <\/div>\n\n                    <\/div>\n\n                <\/div><!-- .elementskit-card END -->\n\n                \n                <div class=\"elementskit-card \">\n                    <div class=\"elementskit-card-header\" id=\"primaryHeading-3-1a49463e\">\n                        <a href=\"#collapse-5e2d3ae6a980b3a3bb50\" class=\"ekit-accordion--toggler elementskit-btn-link collapsed\" data-ekit-toggle=\"collapse\" data-target=\"#Collapse-5e2d3ae6a980b3a3bb50\" aria-expanded=\"false\" aria-controls=\"Collapse-5e2d3ae6a980b3a3bb50\">\n                            \n                            <span class=\"ekit-accordion-title\">\u00bfCu\u00e1les son las condiciones del cr\u00e9dito Emma?<\/span>\n\n                            \n                                <div class=\"ekit_accordion_icon_group\">\n                                    <div class=\"ekit_accordion_normal_icon\">\n                                        <!-- Normal Icon -->\n                                        <i aria-hidden=\"true\" class=\"icon-open icon-right icon icon-down-arrow1\"><\/i>                                    <\/div>\n\n                                    <div class=\"ekit_accordion_active_icon\">\n                                        <!-- Active Icon -->\n                                        <i aria-hidden=\"true\" class=\"icon-closed icon-right icon icon-up-arrow1\"><\/i>                                    <\/div>\n\n                                <\/div>\n\n                            \n                                                    <\/a>\n                    <\/div>\n\n                    <div id=\"Collapse-5e2d3ae6a980b3a3bb50\" class=\" collapse\" aria-labelledby=\"primaryHeading-3-1a49463e\" data-parent=\"#accordion-6a980b3a3bb50\">\n\n                        <div class=\"elementskit-card-body ekit-accordion--content\">\n                            <div class=\"faq-tablet-answer\">\n\n<img decoding=\"async\" class=\"faqhr alignnone size-medium wp-image-21301\" src=\"https:\/\/emmapay.com\/costa-rica\/wp-content\/uploads\/sites\/8\/2023\/09\/Line-69.png\" alt=\"\" width=\"100%\" height=\"1\" \/>\n\nT\u00fa l\u00ednea de cr\u00e9dito depende de tu perfil de cliente, por lo que las condiciones pueden variar en cuanto a l\u00edmite y tasa de inter\u00e9s anual.\n\n<\/div>                        <\/div>\n\n                    <\/div>\n\n                <\/div><!-- .elementskit-card END -->\n\n                \n                <div class=\"elementskit-card \">\n                    <div class=\"elementskit-card-header\" id=\"primaryHeading-4-1a49463e\">\n                        <a href=\"#collapse-1994d826a980b3a3bb50\" class=\"ekit-accordion--toggler elementskit-btn-link collapsed\" data-ekit-toggle=\"collapse\" data-target=\"#Collapse-1994d826a980b3a3bb50\" aria-expanded=\"false\" aria-controls=\"Collapse-1994d826a980b3a3bb50\">\n                            \n                            <span class=\"ekit-accordion-title\">\u00bfCu\u00e1l es el monto m\u00e1ximo de cr\u00e9dito que puedo obtener?<\/span>\n\n                            \n                                <div class=\"ekit_accordion_icon_group\">\n                                    <div class=\"ekit_accordion_normal_icon\">\n                                        <!-- Normal Icon -->\n                                        <i aria-hidden=\"true\" class=\"icon-open icon-right icon icon-down-arrow1\"><\/i>                                    <\/div>\n\n                                    <div class=\"ekit_accordion_active_icon\">\n                                        <!-- Active Icon -->\n                                        <i aria-hidden=\"true\" class=\"icon-closed icon-right icon icon-up-arrow1\"><\/i>                                    <\/div>\n\n                                <\/div>\n\n                            \n                                                    <\/a>\n                    <\/div>\n\n                    <div id=\"Collapse-1994d826a980b3a3bb50\" class=\" collapse\" aria-labelledby=\"primaryHeading-4-1a49463e\" data-parent=\"#accordion-6a980b3a3bb50\">\n\n                        <div class=\"elementskit-card-body ekit-accordion--content\">\n                            <div class=\"faq-tablet-answer\">\n\n<img decoding=\"async\" class=\"faqhr alignnone size-medium wp-image-21301\" src=\"https:\/\/emmapay.com\/costa-rica\/wp-content\/uploads\/sites\/8\/2023\/09\/Line-69.png\" alt=\"\" width=\"100%\" height=\"1\" \/>\n\nEl monto m\u00e1ximo de l\u00ednea de cr\u00e9dito que se puede otorgar a un cliente es de 3 000 000 de colones.\n\n<\/div>                        <\/div>\n\n                    <\/div>\n\n                <\/div><!-- .elementskit-card END -->\n\n                \n                <div class=\"elementskit-card \">\n                    <div class=\"elementskit-card-header\" id=\"primaryHeading-5-1a49463e\">\n                        <a href=\"#collapse-54fa6026a980b3a3bb50\" class=\"ekit-accordion--toggler elementskit-btn-link collapsed\" data-ekit-toggle=\"collapse\" data-target=\"#Collapse-54fa6026a980b3a3bb50\" aria-expanded=\"false\" aria-controls=\"Collapse-54fa6026a980b3a3bb50\">\n                            \n                            <span class=\"ekit-accordion-title\">\u00bfC\u00f3mo puedo solicitar una ampliaci\u00f3n de mi l\u00ednea de cr\u00e9dito?<\/span>\n\n                            \n                                <div class=\"ekit_accordion_icon_group\">\n                                    <div class=\"ekit_accordion_normal_icon\">\n                                        <!-- Normal Icon -->\n                                        <i aria-hidden=\"true\" class=\"icon-open icon-right icon icon-down-arrow1\"><\/i>                                    <\/div>\n\n                                    <div class=\"ekit_accordion_active_icon\">\n                                        <!-- Active Icon -->\n                                        <i aria-hidden=\"true\" class=\"icon-closed icon-right icon icon-up-arrow1\"><\/i>                                    <\/div>\n\n                                <\/div>\n\n                            \n                                                    <\/a>\n                    <\/div>\n\n                    <div id=\"Collapse-54fa6026a980b3a3bb50\" class=\" collapse\" aria-labelledby=\"primaryHeading-5-1a49463e\" data-parent=\"#accordion-6a980b3a3bb50\">\n\n                        <div class=\"elementskit-card-body ekit-accordion--content\">\n                            <div class=\"faq-tablet-answer\">\n\n<img decoding=\"async\" class=\"faqhr alignnone size-medium wp-image-21301\" src=\"https:\/\/emmapay.com\/costa-rica\/wp-content\/uploads\/sites\/8\/2023\/09\/Line-69.png\" alt=\"\" width=\"100%\" height=\"1\" \/>\n\nDebes presentarte en una sucursal de Gollo o La Curacao, y solicitar el aumento de l\u00edmite de cr\u00e9dito. Te recomendamos presentar tu orden patronal en caso de asalariados y estados de cuenta de los \u00faltimos 3 meses en caso de independientes.\n\n<\/div>                        <\/div>\n\n                    <\/div>\n\n                <\/div><!-- .elementskit-card END -->\n\n                \n                <div class=\"elementskit-card \">\n                    <div class=\"elementskit-card-header\" id=\"primaryHeading-6-1a49463e\">\n                        <a href=\"#collapse-f45c7176a980b3a3bb50\" class=\"ekit-accordion--toggler elementskit-btn-link collapsed\" data-ekit-toggle=\"collapse\" data-target=\"#Collapse-f45c7176a980b3a3bb50\" aria-expanded=\"false\" aria-controls=\"Collapse-f45c7176a980b3a3bb50\">\n                            \n                            <span class=\"ekit-accordion-title\">\u00bfC\u00f3mo funciona el cr\u00e9dito Emma?<\/span>\n\n                            \n                                <div class=\"ekit_accordion_icon_group\">\n                                    <div class=\"ekit_accordion_normal_icon\">\n                                        <!-- Normal Icon -->\n                                        <i aria-hidden=\"true\" class=\"icon-open icon-right icon icon-down-arrow1\"><\/i>                                    <\/div>\n\n                                    <div class=\"ekit_accordion_active_icon\">\n                                        <!-- Active Icon -->\n                                        <i aria-hidden=\"true\" class=\"icon-closed icon-right icon icon-up-arrow1\"><\/i>                                    <\/div>\n\n                                <\/div>\n\n                            \n                                                    <\/a>\n                    <\/div>\n\n                    <div id=\"Collapse-f45c7176a980b3a3bb50\" class=\" collapse\" aria-labelledby=\"primaryHeading-6-1a49463e\" data-parent=\"#accordion-6a980b3a3bb50\">\n\n                        <div class=\"elementskit-card-body ekit-accordion--content\">\n                            <div class=\"faq-tablet-answer\"><p><img decoding=\"async\" class=\"faqhr alignnone size-medium wp-image-21301\" src=\"https:\/\/emmapay.com\/costa-rica\/wp-content\/uploads\/sites\/8\/2023\/09\/Line-69.png\" alt=\"\" width=\"100%\" height=\"1\" \/><\/p><p>La l\u00ednea de cr\u00e9dito Emma es revolvente. Es decir que una vez que se utiliza una parte del cr\u00e9dito disponible, la cantidad utilizada se vuelve a poner a disposici\u00f3n del cliente a medida que se realizan los pagos de las cuotas (reembolso), as\u00ed podr\u00e1s utilizar los fondos nuevamente. En otras palabras, es similar al funcionamiento de una tarjeta de cr\u00e9dito.<\/p><\/div>                        <\/div>\n\n                    <\/div>\n\n                <\/div><!-- .elementskit-card END -->\n\n                        <\/div>\n    <\/div>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t                        <\/div>\n\n                    <\/div>\n\n                <\/div><!-- .elementskit-card END --> \n\n                \n                <div class=\"elementskit-card\">\n                    <div class=\"elementskit-card-header\" id=\"primaryHeading-1-490181e7\">\n                        <a href=\"#collapse-becbd066a980b3a38332\" class=\"elementskit-btn-link collapsed\" data-ekit-toggle=\"collapse\" data-target=\"#Collapse-becbd066a980b3a38332\" aria-expanded=\"false\" aria-controls=\"Collapse-becbd066a980b3a38332\">\n                            \n                            <span class=\"ekit-accordion-title\"> <img decoding=\"async\" src=\"https:\/\/emmapaycostarica.local.tt\/wp-content\/uploads\/2023\/08\/nueva-app.svg\"><span class=\"accordion-title\"> Nueva App<\/span><\/span>\n\n                            \n                                <div class=\"ekit_accordion_icon_group\">\n\n                                    <div class=\"ekit_accordion_normal_icon\">\n                                        <!-- Normal Icon -->\n                                        <svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"36\" height=\"36\" viewBox=\"0 0 36 36\" fill=\"none\"><circle cx=\"18\" cy=\"18\" r=\"18\" fill=\"#171C8F\"><\/circle><path d=\"M19 13H17V17H13V19H17V23H19V19H23V17H19V13ZM18 8C12.48 8 8 12.48 8 18C8 23.52 12.48 28 18 28C23.52 28 28 23.52 28 18C28 12.48 23.52 8 18 8ZM18 26C13.59 26 10 22.41 10 18C10 13.59 13.59 10 18 10C22.41 10 26 13.59 26 18C26 22.41 22.41 26 18 26Z\" fill=\"white\"><\/path><\/svg>                                    <\/div>\n\n                                    <div class=\"ekit_accordion_active_icon\">\n                                    <!-- Active Icon -->\n                                    <svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"36\" height=\"36\" viewBox=\"0 0 36 36\" fill=\"none\"><circle cx=\"18\" cy=\"18\" r=\"18\" fill=\"#26D07C\"><\/circle><path d=\"M13 17V19H23V17H13ZM18 8C12.48 8 8 12.48 8 18C8 23.52 12.48 28 18 28C23.52 28 28 23.52 28 18C28 12.48 23.52 8 18 8ZM18 26C13.59 26 10 22.41 10 18C10 13.59 13.59 10 18 10C22.41 10 26 13.59 26 18C26 22.41 22.41 26 18 26Z\" fill=\"white\"><\/path><\/svg>                                    <\/div>\n                                <\/div>\n\n                            \n                                                    <\/a>\n                    <\/div>\n\n                    <div id=\"Collapse-becbd066a980b3a38332\" class=\" collapse\" aria-labelledby=\"primaryHeading-1-490181e7\" data-parent=\"#accordion-6a980b3a38332\">\n                      \n                        <div class=\"elementskit-card-body\">\n                            \n\t\t<div class=\"widgetarea_warper widgetarea_warper_editable\" data-elementskit-widgetarea-key=\"490181e7\"  data-elementskit-widgetarea-index=\"becbd06\">\n\t\t\t<div class=\"widgetarea_warper_edit\" data-elementskit-widgetarea-key=\"490181e7\" data-elementskit-widgetarea-index=\"becbd06\">\n\t\t\t\t<i class=\"eicon-edit\" aria-hidden=\"true\"><\/i>\n\t\t\t\t<span>Edit Content<\/span>\n\t\t\t<\/div>\n\n\t\t\t\t\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"2574\" class=\"elementor elementor-2574\" data-elementor-post-type=\"elementskit_content\">\n\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-74a56111 e-con-full e-flex e-con e-parent\" data-id=\"74a56111\" data-element_type=\"container\" data-settings=\"{&quot;content_width&quot;:&quot;full&quot;,&quot;container_type&quot;:&quot;flex&quot;}\" data-core-v316-plus=\"true\">\n\t\t\t\t<div class=\"elementor-element elementor-element-502b3329 elementor-widget__width-inherit elementor-widget elementor-widget-elementskit-accordion\" data-id=\"502b3329\" data-element_type=\"widget\" id=\"tablet-faq-2\" data-widget_type=\"elementskit-accordion.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<div class=\"ekit-wid-con\" >\n        <div class=\"elementskit-accordion accoedion-primary\" id=\"accordion-6a980b3a3eeda\">\n\n            \n                <div class=\"elementskit-card \">\n                    <div class=\"elementskit-card-header\" id=\"primaryHeading-0-502b3329\">\n                        <a href=\"#collapse-897e1af6a980b3a3eeda\" class=\"ekit-accordion--toggler elementskit-btn-link collapsed\" data-ekit-toggle=\"collapse\" data-target=\"#Collapse-897e1af6a980b3a3eeda\" aria-expanded=\"false\" aria-controls=\"Collapse-897e1af6a980b3a3eeda\">\n                            \n                            <span class=\"ekit-accordion-title\">\u00bfPor qu\u00e9 hay una nueva aplicaci\u00f3n Emma?<\/span>\n\n                            \n                                <div class=\"ekit_accordion_icon_group\">\n                                    <div class=\"ekit_accordion_normal_icon\">\n                                        <!-- Normal Icon -->\n                                        <i aria-hidden=\"true\" class=\"icon-open icon-right icon icon-down-arrow1\"><\/i>                                    <\/div>\n\n                                    <div class=\"ekit_accordion_active_icon\">\n                                        <!-- Active Icon -->\n                                        <i aria-hidden=\"true\" class=\"icon-closed icon-right icon icon-up-arrow1\"><\/i>                                    <\/div>\n\n                                <\/div>\n\n                            \n                                                    <\/a>\n                    <\/div>\n\n                    <div id=\"Collapse-897e1af6a980b3a3eeda\" class=\" collapse\" aria-labelledby=\"primaryHeading-0-502b3329\" data-parent=\"#accordion-6a980b3a3eeda\">\n\n                        <div class=\"elementskit-card-body ekit-accordion--content\">\n                            <div class=\"faq-answer-tablet\">\n\n<img decoding=\"async\" class=\"faqhr alignnone size-medium wp-image-21301\" src=\"https:\/\/emmapay.com\/costa-rica\/wp-content\/uploads\/sites\/8\/2023\/09\/Line-69.png\" alt=\"\" width=\"100%\" height=\"1\" \/>\n\nPorque queremos darle la mejor experiencia a nuestros clientes y comercios aliados.\nLa nueva app es m\u00e1s f\u00e1cil, r\u00e1pida y segura.\n\n<\/div>                        <\/div>\n\n                    <\/div>\n\n                <\/div><!-- .elementskit-card END -->\n\n                \n                <div class=\"elementskit-card \">\n                    <div class=\"elementskit-card-header\" id=\"primaryHeading-1-502b3329\">\n                        <a href=\"#collapse-4f961c16a980b3a3eeda\" class=\"ekit-accordion--toggler elementskit-btn-link collapsed\" data-ekit-toggle=\"collapse\" data-target=\"#Collapse-4f961c16a980b3a3eeda\" aria-expanded=\"false\" aria-controls=\"Collapse-4f961c16a980b3a3eeda\">\n                            \n                            <span class=\"ekit-accordion-title\">Si ya ten\u00eda una l\u00ednea de cr\u00e9dito aprobada en Emma, \u00bfdebo volver a aplicar a un cr\u00e9dito?<\/span>\n\n                            \n                                <div class=\"ekit_accordion_icon_group\">\n                                    <div class=\"ekit_accordion_normal_icon\">\n                                        <!-- Normal Icon -->\n                                        <i aria-hidden=\"true\" class=\"icon-open icon-right icon icon-down-arrow1\"><\/i>                                    <\/div>\n\n                                    <div class=\"ekit_accordion_active_icon\">\n                                        <!-- Active Icon -->\n                                        <i aria-hidden=\"true\" class=\"icon-closed icon-right icon icon-up-arrow1\"><\/i>                                    <\/div>\n\n                                <\/div>\n\n                            \n                                                    <\/a>\n                    <\/div>\n\n                    <div id=\"Collapse-4f961c16a980b3a3eeda\" class=\" collapse\" aria-labelledby=\"primaryHeading-1-502b3329\" data-parent=\"#accordion-6a980b3a3eeda\">\n\n                        <div class=\"elementskit-card-body ekit-accordion--content\">\n                            <div class=\"faq-answer-tablet\">\n\n<img decoding=\"async\" class=\"faqhr alignnone size-medium wp-image-21301\" src=\"https:\/\/emmapay.com\/costa-rica\/wp-content\/uploads\/sites\/8\/2023\/09\/Line-69.png\" alt=\"\" width=\"100%\" height=\"1\" \/>\n\nNo. Si ya tienes una l\u00ednea de cr\u00e9dito Emma, no necesitas aplicar a una nueva l\u00ednea de cr\u00e9dito.\nPara acceder a la informaci\u00f3n de tu cr\u00e9dito Emma solo deber\u00e1s:\n<ol>\n \t<li><a href=\"https:\/\/play.google.com\/store\/apps\/details?id=com.yellowpepper.unicomer.unipay.prod&amp;hl=es\">Descargar la nueva app Emma aqui<\/a><\/li>\n \t<li>Ingresar con el correo con el que te registraste en la aplicaci\u00f3n anterior<\/li>\n \t<li>Actualizar tu pin<\/li>\n \t<li>\u00a1Listo! Tendr\u00e1s acceso a todas tu informaci\u00f3n: L\u00ednea de cr\u00e9dito disponible, transacciones realizadas, cuotas por pagar, etc.<\/li>\n<\/ol>\n<\/div>                        <\/div>\n\n                    <\/div>\n\n                <\/div><!-- .elementskit-card END -->\n\n                \n                <div class=\"elementskit-card \">\n                    <div class=\"elementskit-card-header\" id=\"primaryHeading-2-502b3329\">\n                        <a href=\"#collapse-0c7a8396a980b3a3eeda\" class=\"ekit-accordion--toggler elementskit-btn-link collapsed\" data-ekit-toggle=\"collapse\" data-target=\"#Collapse-0c7a8396a980b3a3eeda\" aria-expanded=\"false\" aria-controls=\"Collapse-0c7a8396a980b3a3eeda\">\n                            \n                            <span class=\"ekit-accordion-title\">\u00bfPuedo seguir utilizando la aplicaci\u00f3n anterior?<\/span>\n\n                            \n                                <div class=\"ekit_accordion_icon_group\">\n                                    <div class=\"ekit_accordion_normal_icon\">\n                                        <!-- Normal Icon -->\n                                        <i aria-hidden=\"true\" class=\"icon-open icon-right icon icon-down-arrow1\"><\/i>                                    <\/div>\n\n                                    <div class=\"ekit_accordion_active_icon\">\n                                        <!-- Active Icon -->\n                                        <i aria-hidden=\"true\" class=\"icon-closed icon-right icon icon-up-arrow1\"><\/i>                                    <\/div>\n\n                                <\/div>\n\n                            \n                                                    <\/a>\n                    <\/div>\n\n                    <div id=\"Collapse-0c7a8396a980b3a3eeda\" class=\" collapse\" aria-labelledby=\"primaryHeading-2-502b3329\" data-parent=\"#accordion-6a980b3a3eeda\">\n\n                        <div class=\"elementskit-card-body ekit-accordion--content\">\n                            <div class=\"faq-answer-tablet\">\n\n<img decoding=\"async\" class=\"faqhr alignnone size-medium wp-image-21301\" src=\"https:\/\/emmapay.com\/costa-rica\/wp-content\/uploads\/sites\/8\/2023\/09\/Line-69.png\" alt=\"\" width=\"100%\" height=\"1\" \/>\n\nNo. A partir del 04\/09\/2022, la versi\u00f3n anterior quedar\u00e1 desactivada.<br \/>\n\n<a class=\"faq-lnk\" href=\"https:\/\/play.google.com\/store\/apps\/details?id=com.yellowpepper.unicomer.unipay.prod&amp;hl=es\" target=\"_blank\" rel=\"noopener\">Descarga la nueva aplicaci\u00f3n aqu\u00ed y sumate a la revoluci\u00f3n del cr\u00e9dito inmediato. <\/a>\n\n<\/div>                        <\/div>\n\n                    <\/div>\n\n                <\/div><!-- .elementskit-card END -->\n\n                \n                <div class=\"elementskit-card \">\n                    <div class=\"elementskit-card-header\" id=\"primaryHeading-3-502b3329\">\n                        <a href=\"#collapse-df649506a980b3a3eeda\" class=\"ekit-accordion--toggler elementskit-btn-link collapsed\" data-ekit-toggle=\"collapse\" data-target=\"#Collapse-df649506a980b3a3eeda\" aria-expanded=\"false\" aria-controls=\"Collapse-df649506a980b3a3eeda\">\n                            \n                            <span class=\"ekit-accordion-title\">\u00bfLa nueva aplicaci\u00f3n es segura?<\/span>\n\n                            \n                                <div class=\"ekit_accordion_icon_group\">\n                                    <div class=\"ekit_accordion_normal_icon\">\n                                        <!-- Normal Icon -->\n                                        <i aria-hidden=\"true\" class=\"icon-open icon-right icon icon-down-arrow1\"><\/i>                                    <\/div>\n\n                                    <div class=\"ekit_accordion_active_icon\">\n                                        <!-- Active Icon -->\n                                        <i aria-hidden=\"true\" class=\"icon-closed icon-right icon icon-up-arrow1\"><\/i>                                    <\/div>\n\n                                <\/div>\n\n                            \n                                                    <\/a>\n                    <\/div>\n\n                    <div id=\"Collapse-df649506a980b3a3eeda\" class=\" collapse\" aria-labelledby=\"primaryHeading-3-502b3329\" data-parent=\"#accordion-6a980b3a3eeda\">\n\n                        <div class=\"elementskit-card-body ekit-accordion--content\">\n                            <div class=\"faq-answer-tablet\">\n\n<img decoding=\"async\" class=\"faqhr alignnone size-medium wp-image-21301\" src=\"https:\/\/emmapay.com\/costa-rica\/wp-content\/uploads\/sites\/8\/2023\/09\/Line-69.png\" alt=\"\" width=\"100%\" height=\"1\" \/>\n\nLa nueva aplicaci\u00f3n es re-segura. Contamos con diferentes mecanismos de validaci\u00f3n de identidad como reconocimiento facial y validaciones v\u00eda Token para confirmar las transacciones a realizar.\n\n<\/div>                        <\/div>\n\n                    <\/div>\n\n                <\/div><!-- .elementskit-card END -->\n\n                        <\/div>\n    <\/div>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t                        <\/div>\n\n                    <\/div>\n\n                <\/div><!-- .elementskit-card END --> \n\n                \n                <div class=\"elementskit-card\">\n                    <div class=\"elementskit-card-header\" id=\"primaryHeading-2-490181e7\">\n                        <a href=\"#collapse-5a07f3f6a980b3a38332\" class=\"elementskit-btn-link collapsed\" data-ekit-toggle=\"collapse\" data-target=\"#Collapse-5a07f3f6a980b3a38332\" aria-expanded=\"false\" aria-controls=\"Collapse-5a07f3f6a980b3a38332\">\n                            \n                            <span class=\"ekit-accordion-title\"><img decoding=\"async\" src=\"https:\/\/emmapaycostarica.local.tt\/wp-content\/uploads\/2023\/08\/descarga-y-registro.svg\"> <span class=\"accordion-title\">Descarga y registro<\/span>\n\n                            \n                                <div class=\"ekit_accordion_icon_group\">\n\n                                    <div class=\"ekit_accordion_normal_icon\">\n                                        <!-- Normal Icon -->\n                                        <svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"36\" height=\"36\" viewBox=\"0 0 36 36\" fill=\"none\"><circle cx=\"18\" cy=\"18\" r=\"18\" fill=\"#171C8F\"><\/circle><path d=\"M19 13H17V17H13V19H17V23H19V19H23V17H19V13ZM18 8C12.48 8 8 12.48 8 18C8 23.52 12.48 28 18 28C23.52 28 28 23.52 28 18C28 12.48 23.52 8 18 8ZM18 26C13.59 26 10 22.41 10 18C10 13.59 13.59 10 18 10C22.41 10 26 13.59 26 18C26 22.41 22.41 26 18 26Z\" fill=\"white\"><\/path><\/svg>                                    <\/div>\n\n                                    <div class=\"ekit_accordion_active_icon\">\n                                    <!-- Active Icon -->\n                                    <svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"36\" height=\"36\" viewBox=\"0 0 36 36\" fill=\"none\"><circle cx=\"18\" cy=\"18\" r=\"18\" fill=\"#26D07C\"><\/circle><path d=\"M13 17V19H23V17H13ZM18 8C12.48 8 8 12.48 8 18C8 23.52 12.48 28 18 28C23.52 28 28 23.52 28 18C28 12.48 23.52 8 18 8ZM18 26C13.59 26 10 22.41 10 18C10 13.59 13.59 10 18 10C22.41 10 26 13.59 26 18C26 22.41 22.41 26 18 26Z\" fill=\"white\"><\/path><\/svg>                                    <\/div>\n                                <\/div>\n\n                            \n                                                    <\/a>\n                    <\/div>\n\n                    <div id=\"Collapse-5a07f3f6a980b3a38332\" class=\" collapse\" aria-labelledby=\"primaryHeading-2-490181e7\" data-parent=\"#accordion-6a980b3a38332\">\n                      \n                        <div class=\"elementskit-card-body\">\n                            \n\t\t<div class=\"widgetarea_warper widgetarea_warper_editable\" data-elementskit-widgetarea-key=\"490181e7\"  data-elementskit-widgetarea-index=\"5a07f3f\">\n\t\t\t<div class=\"widgetarea_warper_edit\" data-elementskit-widgetarea-key=\"490181e7\" data-elementskit-widgetarea-index=\"5a07f3f\">\n\t\t\t\t<i class=\"eicon-edit\" aria-hidden=\"true\"><\/i>\n\t\t\t\t<span>Edit Content<\/span>\n\t\t\t<\/div>\n\n\t\t\t\t\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"2841\" class=\"elementor elementor-2841\" data-elementor-post-type=\"elementskit_content\">\n\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-1be5d3c5 e-con-full e-flex e-con e-parent\" data-id=\"1be5d3c5\" data-element_type=\"container\" data-settings=\"{&quot;content_width&quot;:&quot;full&quot;,&quot;container_type&quot;:&quot;flex&quot;}\" data-core-v316-plus=\"true\">\n\t\t\t\t<div class=\"elementor-element elementor-element-68b4ff1d elementor-widget__width-inherit elementor-widget elementor-widget-elementskit-accordion\" data-id=\"68b4ff1d\" data-element_type=\"widget\" id=\"tablet-faq-3\" data-widget_type=\"elementskit-accordion.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<div class=\"ekit-wid-con\" >\n        <div class=\"elementskit-accordion accoedion-primary\" id=\"accordion-6a980b3a41d36\">\n\n            \n                <div class=\"elementskit-card \">\n                    <div class=\"elementskit-card-header\" id=\"primaryHeading-0-68b4ff1d\">\n                        <a href=\"#collapse-897e1af6a980b3a41d36\" class=\"ekit-accordion--toggler elementskit-btn-link collapsed\" data-ekit-toggle=\"collapse\" data-target=\"#Collapse-897e1af6a980b3a41d36\" aria-expanded=\"false\" aria-controls=\"Collapse-897e1af6a980b3a41d36\">\n                            \n                            <span class=\"ekit-accordion-title\">\u00bfC\u00f3mo descargar Emma?<\/span>\n\n                            \n                                <div class=\"ekit_accordion_icon_group\">\n                                    <div class=\"ekit_accordion_normal_icon\">\n                                        <!-- Normal Icon -->\n                                        <i aria-hidden=\"true\" class=\"icon-open icon-right icon icon-down-arrow1\"><\/i>                                    <\/div>\n\n                                    <div class=\"ekit_accordion_active_icon\">\n                                        <!-- Active Icon -->\n                                        <i aria-hidden=\"true\" class=\"icon-closed icon-right icon icon-up-arrow1\"><\/i>                                    <\/div>\n\n                                <\/div>\n\n                            \n                                                    <\/a>\n                    <\/div>\n\n                    <div id=\"Collapse-897e1af6a980b3a41d36\" class=\" collapse\" aria-labelledby=\"primaryHeading-0-68b4ff1d\" data-parent=\"#accordion-6a980b3a41d36\">\n\n                        <div class=\"elementskit-card-body ekit-accordion--content\">\n                            <div class=\"faq-answer-tablet\"><img decoding=\"async\" class=\"faqhr alignnone size-medium wp-image-21301\" src=\"https:\/\/emmapaycostarica.local.tt\/wp-content\/uploads\/2023\/08\/Line-69-300x1.png\" alt=\"\" width=\"100%\" height=\"1\" \/>\n\nPuedes descarga Emma desde Play Store y APP Store. Buscala con el nombre: Emmapay<\/div>                        <\/div>\n\n                    <\/div>\n\n                <\/div><!-- .elementskit-card END -->\n\n                \n                <div class=\"elementskit-card \">\n                    <div class=\"elementskit-card-header\" id=\"primaryHeading-1-68b4ff1d\">\n                        <a href=\"#collapse-4f961c16a980b3a41d36\" class=\"ekit-accordion--toggler elementskit-btn-link collapsed\" data-ekit-toggle=\"collapse\" data-target=\"#Collapse-4f961c16a980b3a41d36\" aria-expanded=\"false\" aria-controls=\"Collapse-4f961c16a980b3a41d36\">\n                            \n                            <span class=\"ekit-accordion-title\">\u00bfQue es el PIN de acceso y c\u00f3mo debo crearlo?<\/span>\n\n                            \n                                <div class=\"ekit_accordion_icon_group\">\n                                    <div class=\"ekit_accordion_normal_icon\">\n                                        <!-- Normal Icon -->\n                                        <i aria-hidden=\"true\" class=\"icon-open icon-right icon icon-down-arrow1\"><\/i>                                    <\/div>\n\n                                    <div class=\"ekit_accordion_active_icon\">\n                                        <!-- Active Icon -->\n                                        <i aria-hidden=\"true\" class=\"icon-closed icon-right icon icon-up-arrow1\"><\/i>                                    <\/div>\n\n                                <\/div>\n\n                            \n                                                    <\/a>\n                    <\/div>\n\n                    <div id=\"Collapse-4f961c16a980b3a41d36\" class=\" collapse\" aria-labelledby=\"primaryHeading-1-68b4ff1d\" data-parent=\"#accordion-6a980b3a41d36\">\n\n                        <div class=\"elementskit-card-body ekit-accordion--content\">\n                            <div class=\"faq-answer-tablet\">\n\n<img decoding=\"async\" class=\"faqhr alignnone size-medium wp-image-21301\" src=\"https:\/\/emmapay.com\/costa-rica\/wp-content\/uploads\/sites\/8\/2023\/09\/Line-69.png\" alt=\"\" width=\"100%\" height=\"1\" \/>\n\nEl PIN es la contrase\u00f1a de tu cuenta Emma. Debe de ser creado por el cliente, el mismo no puede tener n\u00fameros consecutivos ni repetidos. Recomendamos no compartir tu PIN por motivos de seguridad.\n\n<\/div>                        <\/div>\n\n                    <\/div>\n\n                <\/div><!-- .elementskit-card END -->\n\n                \n                <div class=\"elementskit-card \">\n                    <div class=\"elementskit-card-header\" id=\"primaryHeading-2-68b4ff1d\">\n                        <a href=\"#collapse-0c7a8396a980b3a41d36\" class=\"ekit-accordion--toggler elementskit-btn-link collapsed\" data-ekit-toggle=\"collapse\" data-target=\"#Collapse-0c7a8396a980b3a41d36\" aria-expanded=\"false\" aria-controls=\"Collapse-0c7a8396a980b3a41d36\">\n                            \n                            <span class=\"ekit-accordion-title\">Olvid\u00e9 mi PIN, \u00bfC\u00f3mo puedo restaurarlo?<\/span>\n\n                            \n                                <div class=\"ekit_accordion_icon_group\">\n                                    <div class=\"ekit_accordion_normal_icon\">\n                                        <!-- Normal Icon -->\n                                        <i aria-hidden=\"true\" class=\"icon-open icon-right icon icon-down-arrow1\"><\/i>                                    <\/div>\n\n                                    <div class=\"ekit_accordion_active_icon\">\n                                        <!-- Active Icon -->\n                                        <i aria-hidden=\"true\" class=\"icon-closed icon-right icon icon-up-arrow1\"><\/i>                                    <\/div>\n\n                                <\/div>\n\n                            \n                                                    <\/a>\n                    <\/div>\n\n                    <div id=\"Collapse-0c7a8396a980b3a41d36\" class=\" collapse\" aria-labelledby=\"primaryHeading-2-68b4ff1d\" data-parent=\"#accordion-6a980b3a41d36\">\n\n                        <div class=\"elementskit-card-body ekit-accordion--content\">\n                            <div class=\"faq-answer-tablet\">\n\n<img decoding=\"async\" class=\"faqhr alignnone size-medium wp-image-21301\" src=\"https:\/\/emmapay.com\/costa-rica\/wp-content\/uploads\/sites\/8\/2023\/09\/Line-69.png\" alt=\"\" width=\"100%\" height=\"1\" \/>\n\nNo te preocup\u00e9s, te ayudamos a recuperarlo.\nSigue estos pasos:\n<ol>\n \t<li>Selecciona en la pantalla de Inicio: Olvide mi contrase\u00f1a<\/li>\n \t<li>Te enviaremos un c\u00f3digo de seguridad que deber\u00e1s ingresar en la app<\/li>\n \t<li>Crea un nuevo PIN y listo!<\/li>\n<\/ol>\n<a class=\"faq-lnk\" href=\"https:\/\/www.youtube.com\/watch?v=gX3AUFV-Z3o\" target=\"_blank\" rel=\"noopener\">Te mostramos el paso a paso aqu\u00ed.<\/a>\n\n<\/div>                        <\/div>\n\n                    <\/div>\n\n                <\/div><!-- .elementskit-card END -->\n\n                        <\/div>\n    <\/div>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t                        <\/div>\n\n                    <\/div>\n\n                <\/div><!-- .elementskit-card END --> \n\n                \n                <div class=\"elementskit-card\">\n                    <div class=\"elementskit-card-header\" id=\"primaryHeading-3-490181e7\">\n                        <a href=\"#collapse-c1874846a980b3a38332\" class=\"elementskit-btn-link collapsed\" data-ekit-toggle=\"collapse\" data-target=\"#Collapse-c1874846a980b3a38332\" aria-expanded=\"false\" aria-controls=\"Collapse-c1874846a980b3a38332\">\n                            \n                            <span class=\"ekit-accordion-title\"><img decoding=\"async\" src=\"https:\/\/emmapaycostarica.local.tt\/wp-content\/uploads\/2023\/08\/mi-aplicacion.svg\"><span class=\"accordion-title\">Mi aplicaci\u00f3n de cr\u00e9dito<\/span><\/span>\n\n                            \n                                <div class=\"ekit_accordion_icon_group\">\n\n                                    <div class=\"ekit_accordion_normal_icon\">\n                                        <!-- Normal Icon -->\n                                        <svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"36\" height=\"36\" viewBox=\"0 0 36 36\" fill=\"none\"><circle cx=\"18\" cy=\"18\" r=\"18\" fill=\"#171C8F\"><\/circle><path d=\"M19 13H17V17H13V19H17V23H19V19H23V17H19V13ZM18 8C12.48 8 8 12.48 8 18C8 23.52 12.48 28 18 28C23.52 28 28 23.52 28 18C28 12.48 23.52 8 18 8ZM18 26C13.59 26 10 22.41 10 18C10 13.59 13.59 10 18 10C22.41 10 26 13.59 26 18C26 22.41 22.41 26 18 26Z\" fill=\"white\"><\/path><\/svg>                                    <\/div>\n\n                                    <div class=\"ekit_accordion_active_icon\">\n                                    <!-- Active Icon -->\n                                    <svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"36\" height=\"36\" viewBox=\"0 0 36 36\" fill=\"none\"><circle cx=\"18\" cy=\"18\" r=\"18\" fill=\"#26D07C\"><\/circle><path d=\"M13 17V19H23V17H13ZM18 8C12.48 8 8 12.48 8 18C8 23.52 12.48 28 18 28C23.52 28 28 23.52 28 18C28 12.48 23.52 8 18 8ZM18 26C13.59 26 10 22.41 10 18C10 13.59 13.59 10 18 10C22.41 10 26 13.59 26 18C26 22.41 22.41 26 18 26Z\" fill=\"white\"><\/path><\/svg>                                    <\/div>\n                                <\/div>\n\n                            \n                                                    <\/a>\n                    <\/div>\n\n                    <div id=\"Collapse-c1874846a980b3a38332\" class=\" collapse\" aria-labelledby=\"primaryHeading-3-490181e7\" data-parent=\"#accordion-6a980b3a38332\">\n                      \n                        <div class=\"elementskit-card-body\">\n                            \n\t\t<div class=\"widgetarea_warper widgetarea_warper_editable\" data-elementskit-widgetarea-key=\"9289fa4\"  data-elementskit-widgetarea-index=\"c187484\">\n\t\t\t<div class=\"widgetarea_warper_edit\" data-elementskit-widgetarea-key=\"9289fa4\" data-elementskit-widgetarea-index=\"c187484\">\n\t\t\t\t<i class=\"eicon-edit\" aria-hidden=\"true\"><\/i>\n\t\t\t\t<span>Edit Content<\/span>\n\t\t\t<\/div>\n\n\t\t\t\t\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"1482\" class=\"elementor elementor-1482\" data-elementor-post-type=\"elementskit_content\">\n\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2bcf0761 e-con-full e-flex e-con e-parent\" data-id=\"2bcf0761\" data-element_type=\"container\" data-settings=\"{&quot;content_width&quot;:&quot;full&quot;,&quot;container_type&quot;:&quot;flex&quot;}\" data-core-v316-plus=\"true\">\n\t\t\t\t<div class=\"elementor-element elementor-element-55bdbb32 elementor-widget__width-inherit elementor-widget elementor-widget-elementskit-accordion\" data-id=\"55bdbb32\" data-element_type=\"widget\" id=\"tablet-faq-2\" data-widget_type=\"elementskit-accordion.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<div class=\"ekit-wid-con\" >\n        <div class=\"elementskit-accordion accoedion-primary\" id=\"accordion-6a980b3a44c09\">\n\n            \n                <div class=\"elementskit-card \">\n                    <div class=\"elementskit-card-header\" id=\"primaryHeading-0-55bdbb32\">\n                        <a href=\"#collapse-897e1af6a980b3a44c09\" class=\"ekit-accordion--toggler elementskit-btn-link collapsed\" data-ekit-toggle=\"collapse\" data-target=\"#Collapse-897e1af6a980b3a44c09\" aria-expanded=\"false\" aria-controls=\"Collapse-897e1af6a980b3a44c09\">\n                            \n                            <span class=\"ekit-accordion-title\">\u00bfC\u00f3mo debo solicitar mi l\u00ednea de cr\u00e9dito?<\/span>\n\n                            \n                                <div class=\"ekit_accordion_icon_group\">\n                                    <div class=\"ekit_accordion_normal_icon\">\n                                        <!-- Normal Icon -->\n                                        <i aria-hidden=\"true\" class=\"icon-open icon-right icon icon-down-arrow1\"><\/i>                                    <\/div>\n\n                                    <div class=\"ekit_accordion_active_icon\">\n                                        <!-- Active Icon -->\n                                        <i aria-hidden=\"true\" class=\"icon-closed icon-right icon icon-up-arrow1\"><\/i>                                    <\/div>\n\n                                <\/div>\n\n                            \n                                                    <\/a>\n                    <\/div>\n\n                    <div id=\"Collapse-897e1af6a980b3a44c09\" class=\" collapse\" aria-labelledby=\"primaryHeading-0-55bdbb32\" data-parent=\"#accordion-6a980b3a44c09\">\n\n                        <div class=\"elementskit-card-body ekit-accordion--content\">\n                            <div class=\"faq-answer-tablet\"><img decoding=\"async\" class=\"faqhr alignnone size-medium wp-image-21301\" src=\"https:\/\/emmapaycostarica.local.tt\/wp-content\/uploads\/2023\/08\/Line-69-300x1.png\" alt=\"\" width=\"100%\" height=\"1\" \/>\n\nPara solicitar tu cr\u00e9dito Emma deber\u00e1s:\n<ol>\n \t<li>Descarga EMMA<\/li>\n \t<li>Registrate<\/li>\n \t<li>Validar tu identidad<\/li>\n \t<li>Responder algunas preguntas de validaci\u00f3n<\/li>\n \t<li>Firma los documentos digitalmente para activar tu cr\u00e9dito y \u00a1listo!<\/li>\n<\/ol>\nConoce el paso a paso a detalle aqu\u00ed.<\/div>                        <\/div>\n\n                    <\/div>\n\n                <\/div><!-- .elementskit-card END -->\n\n                \n                <div class=\"elementskit-card \">\n                    <div class=\"elementskit-card-header\" id=\"primaryHeading-1-55bdbb32\">\n                        <a href=\"#collapse-4f961c16a980b3a44c09\" class=\"ekit-accordion--toggler elementskit-btn-link collapsed\" data-ekit-toggle=\"collapse\" data-target=\"#Collapse-4f961c16a980b3a44c09\" aria-expanded=\"false\" aria-controls=\"Collapse-4f961c16a980b3a44c09\">\n                            \n                            <span class=\"ekit-accordion-title\">\u00bfCu\u00e1nto tardan en aprobar el cr\u00e9dito?<\/span>\n\n                            \n                                <div class=\"ekit_accordion_icon_group\">\n                                    <div class=\"ekit_accordion_normal_icon\">\n                                        <!-- Normal Icon -->\n                                        <i aria-hidden=\"true\" class=\"icon-open icon-right icon icon-down-arrow1\"><\/i>                                    <\/div>\n\n                                    <div class=\"ekit_accordion_active_icon\">\n                                        <!-- Active Icon -->\n                                        <i aria-hidden=\"true\" class=\"icon-closed icon-right icon icon-up-arrow1\"><\/i>                                    <\/div>\n\n                                <\/div>\n\n                            \n                                                    <\/a>\n                    <\/div>\n\n                    <div id=\"Collapse-4f961c16a980b3a44c09\" class=\" collapse\" aria-labelledby=\"primaryHeading-1-55bdbb32\" data-parent=\"#accordion-6a980b3a44c09\">\n\n                        <div class=\"elementskit-card-body ekit-accordion--content\">\n                            <div class=\"faq-answer-tablet\"><img decoding=\"async\" class=\"faqhr alignnone size-medium wp-image-21301\" src=\"https:\/\/emmapaycostarica.local.tt\/wp-content\/uploads\/2023\/08\/Line-69-300x1.png\" alt=\"\" width=\"100%\" height=\"1\" \/>\n\nLa aprobaci\u00f3n de t\u00fa l\u00ednea de cr\u00e9dito estar\u00e1 aprobada en menos de 20 minutos.<\/div>                        <\/div>\n\n                    <\/div>\n\n                <\/div><!-- .elementskit-card END -->\n\n                \n                <div class=\"elementskit-card \">\n                    <div class=\"elementskit-card-header\" id=\"primaryHeading-2-55bdbb32\">\n                        <a href=\"#collapse-0c7a8396a980b3a44c09\" class=\"ekit-accordion--toggler elementskit-btn-link collapsed\" data-ekit-toggle=\"collapse\" data-target=\"#Collapse-0c7a8396a980b3a44c09\" aria-expanded=\"false\" aria-controls=\"Collapse-0c7a8396a980b3a44c09\">\n                            \n                            <span class=\"ekit-accordion-title\">Aun no me aprueban el cr\u00e9dito, \u00bfa d\u00f3nde puedo llamar para conocer el estado de mi aplicaci\u00f3n?<\/span>\n\n                            \n                                <div class=\"ekit_accordion_icon_group\">\n                                    <div class=\"ekit_accordion_normal_icon\">\n                                        <!-- Normal Icon -->\n                                        <i aria-hidden=\"true\" class=\"icon-open icon-right icon icon-down-arrow1\"><\/i>                                    <\/div>\n\n                                    <div class=\"ekit_accordion_active_icon\">\n                                        <!-- Active Icon -->\n                                        <i aria-hidden=\"true\" class=\"icon-closed icon-right icon icon-up-arrow1\"><\/i>                                    <\/div>\n\n                                <\/div>\n\n                            \n                                                    <\/a>\n                    <\/div>\n\n                    <div id=\"Collapse-0c7a8396a980b3a44c09\" class=\" collapse\" aria-labelledby=\"primaryHeading-2-55bdbb32\" data-parent=\"#accordion-6a980b3a44c09\">\n\n                        <div class=\"elementskit-card-body ekit-accordion--content\">\n                            <div class=\"faq-answer-tablet\"><p><img decoding=\"async\" class=\"faqhr alignnone size-medium wp-image-21301\" src=\"https:\/\/emmapaycostarica.local.tt\/wp-content\/uploads\/2023\/08\/Line-69-300x1.png\" alt=\"\" width=\"100%\" height=\"1\" \/><\/p><p>Cont\u00e1ctate con nosotros al n\u00famero <a href=\"tel:800-000-3662\">800-000-3662<\/a> opci\u00f3n 2, o al correo: <a href=\"mailto:servicioalcliente_cr@emmapay.com\">servicioalcliente_cr@emmapay.com<\/a><\/p><p>Revisaremos tu solicitud con el departamento de cr\u00e9dito para conocer el estatus.<\/p><\/div>                        <\/div>\n\n                    <\/div>\n\n                <\/div><!-- .elementskit-card END -->\n\n                        <\/div>\n    <\/div>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t                        <\/div>\n\n                    <\/div>\n\n                <\/div><!-- .elementskit-card END --> \n\n                \n                <div class=\"elementskit-card\">\n                    <div class=\"elementskit-card-header\" id=\"primaryHeading-4-490181e7\">\n                        <a href=\"#collapse-11dcf546a980b3a38332\" class=\"elementskit-btn-link collapsed\" data-ekit-toggle=\"collapse\" data-target=\"#Collapse-11dcf546a980b3a38332\" aria-expanded=\"false\" aria-controls=\"Collapse-11dcf546a980b3a38332\">\n                            \n                            <span class=\"ekit-accordion-title\"><img decoding=\"async\" src=\"https:\/\/emmapaycostarica.local.tt\/wp-content\/uploads\/2023\/08\/compras-con-emma.svg\">     <span class=\"accordion-title\">Compras con Emma<\/span><\/span>\n\n                            \n                                <div class=\"ekit_accordion_icon_group\">\n\n                                    <div class=\"ekit_accordion_normal_icon\">\n                                        <!-- Normal Icon -->\n                                        <svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"36\" height=\"36\" viewBox=\"0 0 36 36\" fill=\"none\"><circle cx=\"18\" cy=\"18\" r=\"18\" fill=\"#171C8F\"><\/circle><path d=\"M19 13H17V17H13V19H17V23H19V19H23V17H19V13ZM18 8C12.48 8 8 12.48 8 18C8 23.52 12.48 28 18 28C23.52 28 28 23.52 28 18C28 12.48 23.52 8 18 8ZM18 26C13.59 26 10 22.41 10 18C10 13.59 13.59 10 18 10C22.41 10 26 13.59 26 18C26 22.41 22.41 26 18 26Z\" fill=\"white\"><\/path><\/svg>                                    <\/div>\n\n                                    <div class=\"ekit_accordion_active_icon\">\n                                    <!-- Active Icon -->\n                                    <svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"36\" height=\"36\" viewBox=\"0 0 36 36\" fill=\"none\"><circle cx=\"18\" cy=\"18\" r=\"18\" fill=\"#26D07C\"><\/circle><path d=\"M13 17V19H23V17H13ZM18 8C12.48 8 8 12.48 8 18C8 23.52 12.48 28 18 28C23.52 28 28 23.52 28 18C28 12.48 23.52 8 18 8ZM18 26C13.59 26 10 22.41 10 18C10 13.59 13.59 10 18 10C22.41 10 26 13.59 26 18C26 22.41 22.41 26 18 26Z\" fill=\"white\"><\/path><\/svg>                                    <\/div>\n                                <\/div>\n\n                            \n                                                    <\/a>\n                    <\/div>\n\n                    <div id=\"Collapse-11dcf546a980b3a38332\" class=\" collapse\" aria-labelledby=\"primaryHeading-4-490181e7\" data-parent=\"#accordion-6a980b3a38332\">\n                      \n                        <div class=\"elementskit-card-body\">\n                            \n\t\t<div class=\"widgetarea_warper widgetarea_warper_editable\" data-elementskit-widgetarea-key=\"9289fa4\"  data-elementskit-widgetarea-index=\"11dcf54\">\n\t\t\t<div class=\"widgetarea_warper_edit\" data-elementskit-widgetarea-key=\"9289fa4\" data-elementskit-widgetarea-index=\"11dcf54\">\n\t\t\t\t<i class=\"eicon-edit\" aria-hidden=\"true\"><\/i>\n\t\t\t\t<span>Edit Content<\/span>\n\t\t\t<\/div>\n\n\t\t\t\t\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"1489\" class=\"elementor elementor-1489\" data-elementor-post-type=\"elementskit_content\">\n\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-12f5ae29 e-con-full e-flex e-con e-parent\" data-id=\"12f5ae29\" data-element_type=\"container\" data-settings=\"{&quot;content_width&quot;:&quot;full&quot;,&quot;container_type&quot;:&quot;flex&quot;}\" data-core-v316-plus=\"true\">\n\t\t\t\t<div class=\"elementor-element elementor-element-67d861bc elementor-widget__width-inherit elementor-widget elementor-widget-elementskit-accordion\" data-id=\"67d861bc\" data-element_type=\"widget\" id=\"tablet-faq-2\" data-widget_type=\"elementskit-accordion.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<div class=\"ekit-wid-con\" >\n        <div class=\"elementskit-accordion accoedion-primary\" id=\"accordion-6a980b3a482fa\">\n\n            \n                <div class=\"elementskit-card \">\n                    <div class=\"elementskit-card-header\" id=\"primaryHeading-0-67d861bc\">\n                        <a href=\"#collapse-897e1af6a980b3a482fa\" class=\"ekit-accordion--toggler elementskit-btn-link collapsed\" data-ekit-toggle=\"collapse\" data-target=\"#Collapse-897e1af6a980b3a482fa\" aria-expanded=\"false\" aria-controls=\"Collapse-897e1af6a980b3a482fa\">\n                            \n                            <span class=\"ekit-accordion-title\">\u00bfC\u00f3mo puedo utilizar mi cr\u00e9dito Emma?<\/span>\n\n                            \n                                <div class=\"ekit_accordion_icon_group\">\n                                    <div class=\"ekit_accordion_normal_icon\">\n                                        <!-- Normal Icon -->\n                                        <i aria-hidden=\"true\" class=\"icon-open icon-right icon icon-down-arrow1\"><\/i>                                    <\/div>\n\n                                    <div class=\"ekit_accordion_active_icon\">\n                                        <!-- Active Icon -->\n                                        <i aria-hidden=\"true\" class=\"icon-closed icon-right icon icon-up-arrow1\"><\/i>                                    <\/div>\n\n                                <\/div>\n\n                            \n                                                    <\/a>\n                    <\/div>\n\n                    <div id=\"Collapse-897e1af6a980b3a482fa\" class=\" collapse\" aria-labelledby=\"primaryHeading-0-67d861bc\" data-parent=\"#accordion-6a980b3a482fa\">\n\n                        <div class=\"elementskit-card-body ekit-accordion--content\">\n                            <div class=\"faq-answer-tablet\">\n\n<img decoding=\"async\" class=\"faqhr alignnone size-medium wp-image-21301\" src=\"https:\/\/emmapay.com\/costa-rica\/wp-content\/uploads\/sites\/8\/2023\/09\/Line-69.png\" alt=\"\" width=\"100%\" height=\"1\" \/>\n\nUna vez aprobado tu cr\u00e9dito puedes utilizarlo de la siguiente manera:\n<ol>\n \t<li>Comprando en comercios afiliados<\/li>\n \t<li>Haciendo retiros de efectivo<\/li>\n<\/ol>\n<a href=\"https:\/\/emmapay.com\/costa-rica\/personas\/como-usar-emma\/\" class=\"faq-lnk\">Conoce m\u00e1s sobre c\u00f3mo usar tu cr\u00e9dito aqu\u00ed.<\/a>\n\n<\/div>                        <\/div>\n\n                    <\/div>\n\n                <\/div><!-- .elementskit-card END -->\n\n                \n                <div class=\"elementskit-card \">\n                    <div class=\"elementskit-card-header\" id=\"primaryHeading-1-67d861bc\">\n                        <a href=\"#collapse-4f961c16a980b3a482fa\" class=\"ekit-accordion--toggler elementskit-btn-link collapsed\" data-ekit-toggle=\"collapse\" data-target=\"#Collapse-4f961c16a980b3a482fa\" aria-expanded=\"false\" aria-controls=\"Collapse-4f961c16a980b3a482fa\">\n                            \n                            <span class=\"ekit-accordion-title\">\u00bfD\u00f3nde puedo comprar con Emma?<\/span>\n\n                            \n                                <div class=\"ekit_accordion_icon_group\">\n                                    <div class=\"ekit_accordion_normal_icon\">\n                                        <!-- Normal Icon -->\n                                        <i aria-hidden=\"true\" class=\"icon-open icon-right icon icon-down-arrow1\"><\/i>                                    <\/div>\n\n                                    <div class=\"ekit_accordion_active_icon\">\n                                        <!-- Active Icon -->\n                                        <i aria-hidden=\"true\" class=\"icon-closed icon-right icon icon-up-arrow1\"><\/i>                                    <\/div>\n\n                                <\/div>\n\n                            \n                                                    <\/a>\n                    <\/div>\n\n                    <div id=\"Collapse-4f961c16a980b3a482fa\" class=\" collapse\" aria-labelledby=\"primaryHeading-1-67d861bc\" data-parent=\"#accordion-6a980b3a482fa\">\n\n                        <div class=\"elementskit-card-body ekit-accordion--content\">\n                            <div class=\"faq-answer-tablet\"><p><img decoding=\"async\" class=\"faqhr alignnone size-medium wp-image-21301\" src=\"https:\/\/emmapay.com\/costa-rica\/wp-content\/uploads\/sites\/8\/2023\/09\/Line-69.png\" alt=\"\" width=\"100%\" height=\"1\" \/><\/p><p>Con Emma pod\u00e9s comprar en m\u00e1s de 4 mil comercios afiliados en Costa Rica, en rubros como tecnolog\u00eda, muebles, salud, viajes, todo lo que necesites.<\/p><\/div>                        <\/div>\n\n                    <\/div>\n\n                <\/div><!-- .elementskit-card END -->\n\n                \n                <div class=\"elementskit-card \">\n                    <div class=\"elementskit-card-header\" id=\"primaryHeading-2-67d861bc\">\n                        <a href=\"#collapse-0c7a8396a980b3a482fa\" class=\"ekit-accordion--toggler elementskit-btn-link collapsed\" data-ekit-toggle=\"collapse\" data-target=\"#Collapse-0c7a8396a980b3a482fa\" aria-expanded=\"false\" aria-controls=\"Collapse-0c7a8396a980b3a482fa\">\n                            \n                            <span class=\"ekit-accordion-title\">\u00bfC\u00f3mo puedo realizar una compra?<\/span>\n\n                            \n                                <div class=\"ekit_accordion_icon_group\">\n                                    <div class=\"ekit_accordion_normal_icon\">\n                                        <!-- Normal Icon -->\n                                        <i aria-hidden=\"true\" class=\"icon-open icon-right icon icon-down-arrow1\"><\/i>                                    <\/div>\n\n                                    <div class=\"ekit_accordion_active_icon\">\n                                        <!-- Active Icon -->\n                                        <i aria-hidden=\"true\" class=\"icon-closed icon-right icon icon-up-arrow1\"><\/i>                                    <\/div>\n\n                                <\/div>\n\n                            \n                                                    <\/a>\n                    <\/div>\n\n                    <div id=\"Collapse-0c7a8396a980b3a482fa\" class=\" collapse\" aria-labelledby=\"primaryHeading-2-67d861bc\" data-parent=\"#accordion-6a980b3a482fa\">\n\n                        <div class=\"elementskit-card-body ekit-accordion--content\">\n                            <div class=\"faq-answer-tablet\"><p><img decoding=\"async\" class=\"faqhr alignnone size-medium wp-image-21301\" src=\"https:\/\/emmapay.com\/costa-rica\/wp-content\/uploads\/sites\/8\/2023\/09\/Line-69.png\" alt=\"\" width=\"100%\" height=\"1\" \/><\/p><p>Para realizar una compra, deber\u00e1s tener tu l\u00ednea de cr\u00e9dito aprobada y activa.<br \/>Puedes realizar una compra v\u00eda:<\/p><ul class=\"faq-bullet\"><li>\u00a0Scan and Pay<\/li><li>\u00a0Solcitud de Pago<\/li><\/ul><p><a class=\"faq-lnk\" href=\"https:\/\/emmapay.com\/costa-rica\/personas\/como-usar-emma\/\">Conoce el paso a paso aqu\u00ed.<\/a><\/p><\/div>                        <\/div>\n\n                    <\/div>\n\n                <\/div><!-- .elementskit-card END -->\n\n                \n                <div class=\"elementskit-card \">\n                    <div class=\"elementskit-card-header\" id=\"primaryHeading-3-67d861bc\">\n                        <a href=\"#collapse-cce971c6a980b3a482fa\" class=\"ekit-accordion--toggler elementskit-btn-link collapsed\" data-ekit-toggle=\"collapse\" data-target=\"#Collapse-cce971c6a980b3a482fa\" aria-expanded=\"false\" aria-controls=\"Collapse-cce971c6a980b3a482fa\">\n                            \n                            <span class=\"ekit-accordion-title\">\u00bfD\u00f3nde puedo retirar efectivo?<\/span>\n\n                            \n                                <div class=\"ekit_accordion_icon_group\">\n                                    <div class=\"ekit_accordion_normal_icon\">\n                                        <!-- Normal Icon -->\n                                        <i aria-hidden=\"true\" class=\"icon-open icon-right icon icon-down-arrow1\"><\/i>                                    <\/div>\n\n                                    <div class=\"ekit_accordion_active_icon\">\n                                        <!-- Active Icon -->\n                                        <i aria-hidden=\"true\" class=\"icon-closed icon-right icon icon-up-arrow1\"><\/i>                                    <\/div>\n\n                                <\/div>\n\n                            \n                                                    <\/a>\n                    <\/div>\n\n                    <div id=\"Collapse-cce971c6a980b3a482fa\" class=\" collapse\" aria-labelledby=\"primaryHeading-3-67d861bc\" data-parent=\"#accordion-6a980b3a482fa\">\n\n                        <div class=\"elementskit-card-body ekit-accordion--content\">\n                            <div class=\"faq-answer-tablet\">\n\n<img decoding=\"async\" class=\"faqhr alignnone size-medium wp-image-21301\" src=\"https:\/\/emmapay.com\/costa-rica\/wp-content\/uploads\/sites\/8\/2023\/09\/Line-69.png\" alt=\"\" width=\"100%\" height=\"1\" \/>\n\nDebes solicitar tu efectivo desde EMMA, y lo puedes retirar en todas las tiendas Gollo y La Curacao del pa\u00eds.\n\n<\/div>                        <\/div>\n\n                    <\/div>\n\n                <\/div><!-- .elementskit-card END -->\n\n                \n                <div class=\"elementskit-card \">\n                    <div class=\"elementskit-card-header\" id=\"primaryHeading-4-67d861bc\">\n                        <a href=\"#collapse-2e67fe46a980b3a482fa\" class=\"ekit-accordion--toggler elementskit-btn-link collapsed\" data-ekit-toggle=\"collapse\" data-target=\"#Collapse-2e67fe46a980b3a482fa\" aria-expanded=\"false\" aria-controls=\"Collapse-2e67fe46a980b3a482fa\">\n                            \n                            <span class=\"ekit-accordion-title\">He recibido una solicitud de pago, \u00bfqu\u00e9 debo hacer?<\/span>\n\n                            \n                                <div class=\"ekit_accordion_icon_group\">\n                                    <div class=\"ekit_accordion_normal_icon\">\n                                        <!-- Normal Icon -->\n                                        <i aria-hidden=\"true\" class=\"icon-open icon-right icon icon-down-arrow1\"><\/i>                                    <\/div>\n\n                                    <div class=\"ekit_accordion_active_icon\">\n                                        <!-- Active Icon -->\n                                        <i aria-hidden=\"true\" class=\"icon-closed icon-right icon icon-up-arrow1\"><\/i>                                    <\/div>\n\n                                <\/div>\n\n                            \n                                                    <\/a>\n                    <\/div>\n\n                    <div id=\"Collapse-2e67fe46a980b3a482fa\" class=\" collapse\" aria-labelledby=\"primaryHeading-4-67d861bc\" data-parent=\"#accordion-6a980b3a482fa\">\n\n                        <div class=\"elementskit-card-body ekit-accordion--content\">\n                            <div class=\"faq-answer-tablet\">\n\n<img decoding=\"async\" class=\"faqhr alignnone size-medium wp-image-21301\" src=\"https:\/\/emmapay.com\/costa-rica\/wp-content\/uploads\/sites\/8\/2023\/09\/Line-69.png\" alt=\"\" width=\"100%\" height=\"1\" \/>\n\nTe llegar\u00e1 una notificaci\u00f3n de solicitud de pago a tu celular. Para completar la compra deber\u00e1s:\n<ol>\n \t<li>Inicia sesi\u00f3n<\/li>\n \t<li>Selecciona el plazo de tu compra<\/li>\n \t<li>Valida tu compra con el Token y \u00a1listo!<\/li>\n<\/ol>\n<\/div>                        <\/div>\n\n                    <\/div>\n\n                <\/div><!-- .elementskit-card END -->\n\n                        <\/div>\n    <\/div>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t                        <\/div>\n\n                    <\/div>\n\n                <\/div><!-- .elementskit-card END --> \n\n                \n                <div class=\"elementskit-card\">\n                    <div class=\"elementskit-card-header\" id=\"primaryHeading-5-490181e7\">\n                        <a href=\"#collapse-715cd036a980b3a38332\" class=\"elementskit-btn-link collapsed\" data-ekit-toggle=\"collapse\" data-target=\"#Collapse-715cd036a980b3a38332\" aria-expanded=\"false\" aria-controls=\"Collapse-715cd036a980b3a38332\">\n                            \n                            <span class=\"ekit-accordion-title\"><img decoding=\"async\" src=\"https:\/\/emmapaycostarica.local.tt\/wp-content\/uploads\/2023\/08\/pago-de-mis-cuotas.svg\">     <span class=\"accordion-title\">Pago de mis cuotas<\/span><\/span>\n\n                            \n                                <div class=\"ekit_accordion_icon_group\">\n\n                                    <div class=\"ekit_accordion_normal_icon\">\n                                        <!-- Normal Icon -->\n                                        <svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"36\" height=\"36\" viewBox=\"0 0 36 36\" fill=\"none\"><circle cx=\"18\" cy=\"18\" r=\"18\" fill=\"#171C8F\"><\/circle><path d=\"M19 13H17V17H13V19H17V23H19V19H23V17H19V13ZM18 8C12.48 8 8 12.48 8 18C8 23.52 12.48 28 18 28C23.52 28 28 23.52 28 18C28 12.48 23.52 8 18 8ZM18 26C13.59 26 10 22.41 10 18C10 13.59 13.59 10 18 10C22.41 10 26 13.59 26 18C26 22.41 22.41 26 18 26Z\" fill=\"white\"><\/path><\/svg>                                    <\/div>\n\n                                    <div class=\"ekit_accordion_active_icon\">\n                                    <!-- Active Icon -->\n                                    <svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"36\" height=\"36\" viewBox=\"0 0 36 36\" fill=\"none\"><circle cx=\"18\" cy=\"18\" r=\"18\" fill=\"#26D07C\"><\/circle><path d=\"M13 17V19H23V17H13ZM18 8C12.48 8 8 12.48 8 18C8 23.52 12.48 28 18 28C23.52 28 28 23.52 28 18C28 12.48 23.52 8 18 8ZM18 26C13.59 26 10 22.41 10 18C10 13.59 13.59 10 18 10C22.41 10 26 13.59 26 18C26 22.41 22.41 26 18 26Z\" fill=\"white\"><\/path><\/svg>                                    <\/div>\n                                <\/div>\n\n                            \n                                                    <\/a>\n                    <\/div>\n\n                    <div id=\"Collapse-715cd036a980b3a38332\" class=\" collapse\" aria-labelledby=\"primaryHeading-5-490181e7\" data-parent=\"#accordion-6a980b3a38332\">\n                      \n                        <div class=\"elementskit-card-body\">\n                            \n\t\t<div class=\"widgetarea_warper widgetarea_warper_editable\" data-elementskit-widgetarea-key=\"490181e7\"  data-elementskit-widgetarea-index=\"715cd03\">\n\t\t\t<div class=\"widgetarea_warper_edit\" data-elementskit-widgetarea-key=\"490181e7\" data-elementskit-widgetarea-index=\"715cd03\">\n\t\t\t\t<i class=\"eicon-edit\" aria-hidden=\"true\"><\/i>\n\t\t\t\t<span>Edit Content<\/span>\n\t\t\t<\/div>\n\n\t\t\t\t\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"2849\" class=\"elementor elementor-2849\" data-elementor-post-type=\"elementskit_content\">\n\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-58bd5da3 e-con-full e-flex e-con e-parent\" data-id=\"58bd5da3\" data-element_type=\"container\" data-settings=\"{&quot;content_width&quot;:&quot;full&quot;,&quot;container_type&quot;:&quot;flex&quot;}\" data-core-v316-plus=\"true\">\n\t\t\t\t<div class=\"elementor-element elementor-element-2533c3ad elementor-widget__width-inherit elementor-widget elementor-widget-elementskit-accordion\" data-id=\"2533c3ad\" data-element_type=\"widget\" id=\"tablet-faq-2\" data-widget_type=\"elementskit-accordion.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<div class=\"ekit-wid-con\" >\n        <div class=\"elementskit-accordion accoedion-primary\" id=\"accordion-6a980b3a4b5a4\">\n\n            \n                <div class=\"elementskit-card \">\n                    <div class=\"elementskit-card-header\" id=\"primaryHeading-0-2533c3ad\">\n                        <a href=\"#collapse-897e1af6a980b3a4b5a4\" class=\"ekit-accordion--toggler elementskit-btn-link collapsed\" data-ekit-toggle=\"collapse\" data-target=\"#Collapse-897e1af6a980b3a4b5a4\" aria-expanded=\"false\" aria-controls=\"Collapse-897e1af6a980b3a4b5a4\">\n                            \n                            <span class=\"ekit-accordion-title\">\u00bfD\u00f3nde puedo pagar mis cuotas?<\/span>\n\n                            \n                                <div class=\"ekit_accordion_icon_group\">\n                                    <div class=\"ekit_accordion_normal_icon\">\n                                        <!-- Normal Icon -->\n                                        <i aria-hidden=\"true\" class=\"icon-open icon-right icon icon-down-arrow1\"><\/i>                                    <\/div>\n\n                                    <div class=\"ekit_accordion_active_icon\">\n                                        <!-- Active Icon -->\n                                        <i aria-hidden=\"true\" class=\"icon-closed icon-right icon icon-up-arrow1\"><\/i>                                    <\/div>\n\n                                <\/div>\n\n                            \n                                                    <\/a>\n                    <\/div>\n\n                    <div id=\"Collapse-897e1af6a980b3a4b5a4\" class=\" collapse\" aria-labelledby=\"primaryHeading-0-2533c3ad\" data-parent=\"#accordion-6a980b3a4b5a4\">\n\n                        <div class=\"elementskit-card-body ekit-accordion--content\">\n                            <div class=\"faq-answer-tablet\">\n\n<img decoding=\"async\" class=\"faqhr alignnone size-medium wp-image-21301\" src=\"https:\/\/emmapay.com\/costa-rica\/wp-content\/uploads\/sites\/8\/2023\/09\/Line-69.png\" alt=\"\" width=\"100%\" height=\"1\" \/>\n\nRealiz\u00e1 los pagos de tus cuotas en todas las tiendas Gollo, La Curacao o RadioShack del pa\u00eds.\n\n<\/div>                        <\/div>\n\n                    <\/div>\n\n                <\/div><!-- .elementskit-card END -->\n\n                \n                <div class=\"elementskit-card \">\n                    <div class=\"elementskit-card-header\" id=\"primaryHeading-1-2533c3ad\">\n                        <a href=\"#collapse-4f961c16a980b3a4b5a4\" class=\"ekit-accordion--toggler elementskit-btn-link collapsed\" data-ekit-toggle=\"collapse\" data-target=\"#Collapse-4f961c16a980b3a4b5a4\" aria-expanded=\"false\" aria-controls=\"Collapse-4f961c16a980b3a4b5a4\">\n                            \n                            <span class=\"ekit-accordion-title\">\u00bfPuedo cancelar mis cuotas antes del plazo establecido?<\/span>\n\n                            \n                                <div class=\"ekit_accordion_icon_group\">\n                                    <div class=\"ekit_accordion_normal_icon\">\n                                        <!-- Normal Icon -->\n                                        <i aria-hidden=\"true\" class=\"icon-open icon-right icon icon-down-arrow1\"><\/i>                                    <\/div>\n\n                                    <div class=\"ekit_accordion_active_icon\">\n                                        <!-- Active Icon -->\n                                        <i aria-hidden=\"true\" class=\"icon-closed icon-right icon icon-up-arrow1\"><\/i>                                    <\/div>\n\n                                <\/div>\n\n                            \n                                                    <\/a>\n                    <\/div>\n\n                    <div id=\"Collapse-4f961c16a980b3a4b5a4\" class=\" collapse\" aria-labelledby=\"primaryHeading-1-2533c3ad\" data-parent=\"#accordion-6a980b3a4b5a4\">\n\n                        <div class=\"elementskit-card-body ekit-accordion--content\">\n                            <div class=\"faq-answer-tablet\">\n\n<img decoding=\"async\" class=\"faqhr alignnone size-medium wp-image-21301\" src=\"https:\/\/emmapay.com\/costa-rica\/wp-content\/uploads\/sites\/8\/2023\/09\/Line-69.png\" alt=\"\" width=\"100%\" height=\"1\" \/>\n\nPod\u00e9s cancelar la totalidad de tu cr\u00e9dito o hacer abonos extraordinarios en el momento que quer\u00e1s, sin penalizaciones.\n\n<\/div>                        <\/div>\n\n                    <\/div>\n\n                <\/div><!-- .elementskit-card END -->\n\n                \n                <div class=\"elementskit-card \">\n                    <div class=\"elementskit-card-header\" id=\"primaryHeading-2-2533c3ad\">\n                        <a href=\"#collapse-0c7a8396a980b3a4b5a4\" class=\"ekit-accordion--toggler elementskit-btn-link collapsed\" data-ekit-toggle=\"collapse\" data-target=\"#Collapse-0c7a8396a980b3a4b5a4\" aria-expanded=\"false\" aria-controls=\"Collapse-0c7a8396a980b3a4b5a4\">\n                            \n                            <span class=\"ekit-accordion-title\">\u00bfHacer pagos extraordinarios disminuye el monto de mi cuota?<\/span>\n\n                            \n                                <div class=\"ekit_accordion_icon_group\">\n                                    <div class=\"ekit_accordion_normal_icon\">\n                                        <!-- Normal Icon -->\n                                        <i aria-hidden=\"true\" class=\"icon-open icon-right icon icon-down-arrow1\"><\/i>                                    <\/div>\n\n                                    <div class=\"ekit_accordion_active_icon\">\n                                        <!-- Active Icon -->\n                                        <i aria-hidden=\"true\" class=\"icon-closed icon-right icon icon-up-arrow1\"><\/i>                                    <\/div>\n\n                                <\/div>\n\n                            \n                                                    <\/a>\n                    <\/div>\n\n                    <div id=\"Collapse-0c7a8396a980b3a4b5a4\" class=\" collapse\" aria-labelledby=\"primaryHeading-2-2533c3ad\" data-parent=\"#accordion-6a980b3a4b5a4\">\n\n                        <div class=\"elementskit-card-body ekit-accordion--content\">\n                            <div class=\"faq-answer-tablet\">\n\n<img decoding=\"async\" class=\"faqhr alignnone size-medium wp-image-21301\" src=\"https:\/\/emmapay.com\/costa-rica\/wp-content\/uploads\/sites\/8\/2023\/09\/Line-69.png\" alt=\"\" width=\"100%\" height=\"1\" \/>\n\nNo disminuye el monto de las cuotas, sino disminuir\u00e1 la cantidad de cuotas restantes a pagar.\n\n<\/div>                        <\/div>\n\n                    <\/div>\n\n                <\/div><!-- .elementskit-card END -->\n\n                        <\/div>\n    <\/div>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t                        <\/div>\n\n                    <\/div>\n\n                <\/div><!-- .elementskit-card END --> \n\n                \n                <div class=\"elementskit-card\">\n                    <div class=\"elementskit-card-header\" id=\"primaryHeading-6-490181e7\">\n                        <a href=\"#collapse-0da8f0d6a980b3a38332\" class=\"elementskit-btn-link collapsed\" data-ekit-toggle=\"collapse\" data-target=\"#Collapse-0da8f0d6a980b3a38332\" aria-expanded=\"false\" aria-controls=\"Collapse-0da8f0d6a980b3a38332\">\n                            \n                            <span class=\"ekit-accordion-title\"><img decoding=\"async\" src=\"https:\/\/emmapaycostarica.local.tt\/wp-content\/uploads\/2023\/08\/seguridad.svg\">     <span class=\"accordion-title\">Seguridad<\/span><\/span>\n\n                            \n                                <div class=\"ekit_accordion_icon_group\">\n\n                                    <div class=\"ekit_accordion_normal_icon\">\n                                        <!-- Normal Icon -->\n                                        <svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"36\" height=\"36\" viewBox=\"0 0 36 36\" fill=\"none\"><circle cx=\"18\" cy=\"18\" r=\"18\" fill=\"#171C8F\"><\/circle><path d=\"M19 13H17V17H13V19H17V23H19V19H23V17H19V13ZM18 8C12.48 8 8 12.48 8 18C8 23.52 12.48 28 18 28C23.52 28 28 23.52 28 18C28 12.48 23.52 8 18 8ZM18 26C13.59 26 10 22.41 10 18C10 13.59 13.59 10 18 10C22.41 10 26 13.59 26 18C26 22.41 22.41 26 18 26Z\" fill=\"white\"><\/path><\/svg>                                    <\/div>\n\n                                    <div class=\"ekit_accordion_active_icon\">\n                                    <!-- Active Icon -->\n                                    <svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"36\" height=\"36\" viewBox=\"0 0 36 36\" fill=\"none\"><circle cx=\"18\" cy=\"18\" r=\"18\" fill=\"#26D07C\"><\/circle><path d=\"M13 17V19H23V17H13ZM18 8C12.48 8 8 12.48 8 18C8 23.52 12.48 28 18 28C23.52 28 28 23.52 28 18C28 12.48 23.52 8 18 8ZM18 26C13.59 26 10 22.41 10 18C10 13.59 13.59 10 18 10C22.41 10 26 13.59 26 18C26 22.41 22.41 26 18 26Z\" fill=\"white\"><\/path><\/svg>                                    <\/div>\n                                <\/div>\n\n                            \n                                                    <\/a>\n                    <\/div>\n\n                    <div id=\"Collapse-0da8f0d6a980b3a38332\" class=\" collapse\" aria-labelledby=\"primaryHeading-6-490181e7\" data-parent=\"#accordion-6a980b3a38332\">\n                      \n                        <div class=\"elementskit-card-body\">\n                            \n\t\t<div class=\"widgetarea_warper widgetarea_warper_editable\" data-elementskit-widgetarea-key=\"9289fa4\"  data-elementskit-widgetarea-index=\"0da8f0d\">\n\t\t\t<div class=\"widgetarea_warper_edit\" data-elementskit-widgetarea-key=\"9289fa4\" data-elementskit-widgetarea-index=\"0da8f0d\">\n\t\t\t\t<i class=\"eicon-edit\" aria-hidden=\"true\"><\/i>\n\t\t\t\t<span>Edit Content<\/span>\n\t\t\t<\/div>\n\n\t\t\t\t\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"2886\" class=\"elementor elementor-2886\" data-elementor-post-type=\"elementskit_content\">\n\t\t\t\t\t\t\t<div class=\"elementor-element elementor-element-437c266 e-con-full e-flex e-con e-parent\" data-id=\"437c266\" data-element_type=\"container\" data-settings=\"{&quot;content_width&quot;:&quot;full&quot;,&quot;container_type&quot;:&quot;flex&quot;}\" data-core-v316-plus=\"true\">\n\t\t\t\t<div class=\"elementor-element elementor-element-162d1c24 elementor-widget__width-inherit elementor-widget elementor-widget-elementskit-accordion\" data-id=\"162d1c24\" data-element_type=\"widget\" id=\"tablet-faq-6\" data-widget_type=\"elementskit-accordion.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<div class=\"ekit-wid-con\" >\n        <div class=\"elementskit-accordion accoedion-primary\" id=\"accordion-6a980b3a4e5a3\">\n\n            \n                <div class=\"elementskit-card \">\n                    <div class=\"elementskit-card-header\" id=\"primaryHeading-0-162d1c24\">\n                        <a href=\"#collapse-897e1af6a980b3a4e5a3\" class=\"ekit-accordion--toggler elementskit-btn-link collapsed\" data-ekit-toggle=\"collapse\" data-target=\"#Collapse-897e1af6a980b3a4e5a3\" aria-expanded=\"false\" aria-controls=\"Collapse-897e1af6a980b3a4e5a3\">\n                            \n                            <span class=\"ekit-accordion-title\">\u00bfPuedo compartir mi PIN de seguridad?<\/span>\n\n                            \n                                <div class=\"ekit_accordion_icon_group\">\n                                    <div class=\"ekit_accordion_normal_icon\">\n                                        <!-- Normal Icon -->\n                                        <i aria-hidden=\"true\" class=\"icon-open icon-right icon icon-down-arrow1\"><\/i>                                    <\/div>\n\n                                    <div class=\"ekit_accordion_active_icon\">\n                                        <!-- Active Icon -->\n                                        <i aria-hidden=\"true\" class=\"icon-closed icon-right icon icon-up-arrow1\"><\/i>                                    <\/div>\n\n                                <\/div>\n\n                            \n                                                    <\/a>\n                    <\/div>\n\n                    <div id=\"Collapse-897e1af6a980b3a4e5a3\" class=\" collapse\" aria-labelledby=\"primaryHeading-0-162d1c24\" data-parent=\"#accordion-6a980b3a4e5a3\">\n\n                        <div class=\"elementskit-card-body ekit-accordion--content\">\n                            <div class=\"faq-answer-tablet\">\n\n<img decoding=\"async\" class=\"faqhr alignnone size-medium wp-image-21301\" src=\"https:\/\/emmapay.com\/costa-rica\/wp-content\/uploads\/sites\/8\/2023\/09\/Line-69.png\" alt=\"\" width=\"100%\" height=\"1\" \/>\n\nNo, nunca debes compartir tu PIN de seguridad o datos personales por seguridad.\n\n<\/div>                        <\/div>\n\n                    <\/div>\n\n                <\/div><!-- .elementskit-card END -->\n\n                \n                <div class=\"elementskit-card \">\n                    <div class=\"elementskit-card-header\" id=\"primaryHeading-1-162d1c24\">\n                        <a href=\"#collapse-4f961c16a980b3a4e5a3\" class=\"ekit-accordion--toggler elementskit-btn-link collapsed\" data-ekit-toggle=\"collapse\" data-target=\"#Collapse-4f961c16a980b3a4e5a3\" aria-expanded=\"false\" aria-controls=\"Collapse-4f961c16a980b3a4e5a3\">\n                            \n                            <span class=\"ekit-accordion-title\">\u00bfUna tercera persona puede comprar con mi aplicaci\u00f3n EMMA?<\/span>\n\n                            \n                                <div class=\"ekit_accordion_icon_group\">\n                                    <div class=\"ekit_accordion_normal_icon\">\n                                        <!-- Normal Icon -->\n                                        <i aria-hidden=\"true\" class=\"icon-open icon-right icon icon-down-arrow1\"><\/i>                                    <\/div>\n\n                                    <div class=\"ekit_accordion_active_icon\">\n                                        <!-- Active Icon -->\n                                        <i aria-hidden=\"true\" class=\"icon-closed icon-right icon icon-up-arrow1\"><\/i>                                    <\/div>\n\n                                <\/div>\n\n                            \n                                                    <\/a>\n                    <\/div>\n\n                    <div id=\"Collapse-4f961c16a980b3a4e5a3\" class=\" collapse\" aria-labelledby=\"primaryHeading-1-162d1c24\" data-parent=\"#accordion-6a980b3a4e5a3\">\n\n                        <div class=\"elementskit-card-body ekit-accordion--content\">\n                            <div class=\"faq-answer-tablet\">\n\n<img decoding=\"async\" class=\"faqhr alignnone size-medium wp-image-21301\" src=\"https:\/\/emmapay.com\/costa-rica\/wp-content\/uploads\/sites\/8\/2023\/09\/Line-69.png\" alt=\"\" width=\"100%\" height=\"1\" \/>\n\nNo, EMMA es de uso personal por lo que no debe permitir bajo ninguna circunstancia que terceras personas utilicen sus datos para ejecutar compras con EMMA.\n\n<\/div>                        <\/div>\n\n                    <\/div>\n\n                <\/div><!-- .elementskit-card END -->\n\n                        <\/div>\n    <\/div>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t                        <\/div>\n\n                    <\/div>\n\n                <\/div><!-- .elementskit-card END --> \n\n                        <\/div>\n    <\/div>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Ayuda \/ Preguntas frecuentes\/ Emma para personas Ayuda \/ Preguntas frecuentes \/ Emma para personas Preguntas frecuentes Cr\u00e9dito Emma Nueva APP Descarga y registro Mi aplicaci\u00f3n de cr\u00e9dito Compras con Emma Pago de mis cuotas Seguridad Edit Content \u00bfQu\u00e9 es Emma? Edit Content Emma es la app que te d\u00e1 cr\u00e9dito 100% digital desde tu [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":1203,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-2498","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v23.2 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Preguntas Frecuentes Personas - Emma Pay Costa Rica<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/emmapay.com\/costa-rica\/ayuda\/preguntas-frecuentes\/preguntas-frecuentes-personas\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Preguntas Frecuentes Personas - Emma Pay Costa Rica\" \/>\n<meta property=\"og:description\" content=\"Ayuda \/ Preguntas frecuentes\/ Emma para personas Ayuda \/ Preguntas frecuentes \/ Emma para personas Preguntas frecuentes Cr\u00e9dito Emma Nueva APP Descarga y registro Mi aplicaci\u00f3n de cr\u00e9dito Compras con Emma Pago de mis cuotas Seguridad Edit Content \u00bfQu\u00e9 es Emma? Edit Content Emma es la app que te d\u00e1 cr\u00e9dito 100% digital desde tu [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/emmapay.com\/costa-rica\/ayuda\/preguntas-frecuentes\/preguntas-frecuentes-personas\/\" \/>\n<meta property=\"og:site_name\" content=\"Emma Pay Costa Rica\" \/>\n<meta property=\"article:modified_time\" content=\"2023-09-24T22:29:28+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/emmapay.com\/costa-rica\/wp-content\/uploads\/sites\/8\/2023\/09\/GooglePlay-az.svg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"68 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/emmapay.com\/costa-rica\/ayuda\/preguntas-frecuentes\/preguntas-frecuentes-personas\/\",\"url\":\"https:\/\/emmapay.com\/costa-rica\/ayuda\/preguntas-frecuentes\/preguntas-frecuentes-personas\/\",\"name\":\"Preguntas Frecuentes Personas - Emma Pay Costa Rica\",\"isPartOf\":{\"@id\":\"https:\/\/emmapay.com\/costa-rica\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/emmapay.com\/costa-rica\/ayuda\/preguntas-frecuentes\/preguntas-frecuentes-personas\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/emmapay.com\/costa-rica\/ayuda\/preguntas-frecuentes\/preguntas-frecuentes-personas\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/emmapay.com\/costa-rica\/wp-content\/uploads\/sites\/8\/2023\/09\/GooglePlay-az.svg\",\"datePublished\":\"2023-09-19T22:55:45+00:00\",\"dateModified\":\"2023-09-24T22:29:28+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/emmapay.com\/costa-rica\/ayuda\/preguntas-frecuentes\/preguntas-frecuentes-personas\/#breadcrumb\"},\"inLanguage\":\"es-CR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/emmapay.com\/costa-rica\/ayuda\/preguntas-frecuentes\/preguntas-frecuentes-personas\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es-CR\",\"@id\":\"https:\/\/emmapay.com\/costa-rica\/ayuda\/preguntas-frecuentes\/preguntas-frecuentes-personas\/#primaryimage\",\"url\":\"https:\/\/emmapay.com\/costa-rica\/wp-content\/uploads\/sites\/8\/2023\/09\/GooglePlay-az.svg\",\"contentUrl\":\"https:\/\/emmapay.com\/costa-rica\/wp-content\/uploads\/sites\/8\/2023\/09\/GooglePlay-az.svg\",\"width\":198,\"height\":56,\"caption\":\"Descarg\u00e1 Emma en Google Play\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/emmapay.com\/costa-rica\/ayuda\/preguntas-frecuentes\/preguntas-frecuentes-personas\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/emmapay.com\/costa-rica\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Ayuda\",\"item\":\"https:\/\/emmapay.com\/costa-rica\/ayuda\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Preguntas frecuentes\",\"item\":\"https:\/\/emmapay.com\/costa-rica\/ayuda\/preguntas-frecuentes\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"Preguntas Frecuentes Personas\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/emmapay.com\/costa-rica\/#website\",\"url\":\"https:\/\/emmapay.com\/costa-rica\/\",\"name\":\"Emma Pay Costa Rica\",\"description\":\"Emma Pay Costa Rica\",\"publisher\":{\"@id\":\"https:\/\/emmapay.com\/costa-rica\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/emmapay.com\/costa-rica\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"es-CR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/emmapay.com\/costa-rica\/#organization\",\"name\":\"Emma Pay Costa Rica\",\"url\":\"https:\/\/emmapay.com\/costa-rica\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-CR\",\"@id\":\"https:\/\/emmapay.com\/costa-rica\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/emmapay.com\/costa-rica\/wp-content\/uploads\/sites\/8\/2023\/09\/Logo-Emma.svg\",\"contentUrl\":\"https:\/\/emmapay.com\/costa-rica\/wp-content\/uploads\/sites\/8\/2023\/09\/Logo-Emma.svg\",\"width\":171,\"height\":68,\"caption\":\"Emma Pay Costa Rica\"},\"image\":{\"@id\":\"https:\/\/emmapay.com\/costa-rica\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Preguntas Frecuentes Personas - Emma Pay Costa Rica","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/emmapay.com\/costa-rica\/ayuda\/preguntas-frecuentes\/preguntas-frecuentes-personas\/","og_locale":"es_ES","og_type":"article","og_title":"Preguntas Frecuentes Personas - Emma Pay Costa Rica","og_description":"Ayuda \/ Preguntas frecuentes\/ Emma para personas Ayuda \/ Preguntas frecuentes \/ Emma para personas Preguntas frecuentes Cr\u00e9dito Emma Nueva APP Descarga y registro Mi aplicaci\u00f3n de cr\u00e9dito Compras con Emma Pago de mis cuotas Seguridad Edit Content \u00bfQu\u00e9 es Emma? Edit Content Emma es la app que te d\u00e1 cr\u00e9dito 100% digital desde tu [&hellip;]","og_url":"https:\/\/emmapay.com\/costa-rica\/ayuda\/preguntas-frecuentes\/preguntas-frecuentes-personas\/","og_site_name":"Emma Pay Costa Rica","article_modified_time":"2023-09-24T22:29:28+00:00","og_image":[{"url":"https:\/\/emmapay.com\/costa-rica\/wp-content\/uploads\/sites\/8\/2023\/09\/GooglePlay-az.svg"}],"twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"68 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/emmapay.com\/costa-rica\/ayuda\/preguntas-frecuentes\/preguntas-frecuentes-personas\/","url":"https:\/\/emmapay.com\/costa-rica\/ayuda\/preguntas-frecuentes\/preguntas-frecuentes-personas\/","name":"Preguntas Frecuentes Personas - Emma Pay Costa Rica","isPartOf":{"@id":"https:\/\/emmapay.com\/costa-rica\/#website"},"primaryImageOfPage":{"@id":"https:\/\/emmapay.com\/costa-rica\/ayuda\/preguntas-frecuentes\/preguntas-frecuentes-personas\/#primaryimage"},"image":{"@id":"https:\/\/emmapay.com\/costa-rica\/ayuda\/preguntas-frecuentes\/preguntas-frecuentes-personas\/#primaryimage"},"thumbnailUrl":"https:\/\/emmapay.com\/costa-rica\/wp-content\/uploads\/sites\/8\/2023\/09\/GooglePlay-az.svg","datePublished":"2023-09-19T22:55:45+00:00","dateModified":"2023-09-24T22:29:28+00:00","breadcrumb":{"@id":"https:\/\/emmapay.com\/costa-rica\/ayuda\/preguntas-frecuentes\/preguntas-frecuentes-personas\/#breadcrumb"},"inLanguage":"es-CR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/emmapay.com\/costa-rica\/ayuda\/preguntas-frecuentes\/preguntas-frecuentes-personas\/"]}]},{"@type":"ImageObject","inLanguage":"es-CR","@id":"https:\/\/emmapay.com\/costa-rica\/ayuda\/preguntas-frecuentes\/preguntas-frecuentes-personas\/#primaryimage","url":"https:\/\/emmapay.com\/costa-rica\/wp-content\/uploads\/sites\/8\/2023\/09\/GooglePlay-az.svg","contentUrl":"https:\/\/emmapay.com\/costa-rica\/wp-content\/uploads\/sites\/8\/2023\/09\/GooglePlay-az.svg","width":198,"height":56,"caption":"Descarg\u00e1 Emma en Google Play"},{"@type":"BreadcrumbList","@id":"https:\/\/emmapay.com\/costa-rica\/ayuda\/preguntas-frecuentes\/preguntas-frecuentes-personas\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/emmapay.com\/costa-rica\/"},{"@type":"ListItem","position":2,"name":"Ayuda","item":"https:\/\/emmapay.com\/costa-rica\/ayuda\/"},{"@type":"ListItem","position":3,"name":"Preguntas frecuentes","item":"https:\/\/emmapay.com\/costa-rica\/ayuda\/preguntas-frecuentes\/"},{"@type":"ListItem","position":4,"name":"Preguntas Frecuentes Personas"}]},{"@type":"WebSite","@id":"https:\/\/emmapay.com\/costa-rica\/#website","url":"https:\/\/emmapay.com\/costa-rica\/","name":"Emma Pay Costa Rica","description":"Emma Pay Costa Rica","publisher":{"@id":"https:\/\/emmapay.com\/costa-rica\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/emmapay.com\/costa-rica\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"es-CR"},{"@type":"Organization","@id":"https:\/\/emmapay.com\/costa-rica\/#organization","name":"Emma Pay Costa Rica","url":"https:\/\/emmapay.com\/costa-rica\/","logo":{"@type":"ImageObject","inLanguage":"es-CR","@id":"https:\/\/emmapay.com\/costa-rica\/#\/schema\/logo\/image\/","url":"https:\/\/emmapay.com\/costa-rica\/wp-content\/uploads\/sites\/8\/2023\/09\/Logo-Emma.svg","contentUrl":"https:\/\/emmapay.com\/costa-rica\/wp-content\/uploads\/sites\/8\/2023\/09\/Logo-Emma.svg","width":171,"height":68,"caption":"Emma Pay Costa Rica"},"image":{"@id":"https:\/\/emmapay.com\/costa-rica\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/emmapay.com\/costa-rica\/wp-json\/wp\/v2\/pages\/2498"}],"collection":[{"href":"https:\/\/emmapay.com\/costa-rica\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/emmapay.com\/costa-rica\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/emmapay.com\/costa-rica\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/emmapay.com\/costa-rica\/wp-json\/wp\/v2\/comments?post=2498"}],"version-history":[{"count":0,"href":"https:\/\/emmapay.com\/costa-rica\/wp-json\/wp\/v2\/pages\/2498\/revisions"}],"up":[{"embeddable":true,"href":"https:\/\/emmapay.com\/costa-rica\/wp-json\/wp\/v2\/pages\/1203"}],"wp:attachment":[{"href":"https:\/\/emmapay.com\/costa-rica\/wp-json\/wp\/v2\/media?parent=2498"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}